{"id":13139,"date":"2013-03-21T07:52:04","date_gmt":"2013-03-21T07:52:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13139"},"modified":"2013-03-21T07:52:04","modified_gmt":"2013-03-21T07:52:04","slug":"templi-di-vita-e-arte-contemporanea-per-un-nuovo-rapporto-tra-citta-e-paesaggio-culturale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/templi-di-vita-e-arte-contemporanea-per-un-nuovo-rapporto-tra-citta-e-paesaggio-culturale\/","title":{"rendered":"\u201cTEMPLI DI VITA E ARTE CONTEMPORANEA  PER UN NUOVO RAPPORTO TRA CITT\u00c0 E PAESAGGIO CULTURALE\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><span style=\"text-decoration: underline\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/templi-di-vita-e-arte-contemporanea-per-un-nuovo-rapporto-tra-citta-e-paesaggio-culturale\/galatina\/\" rel=\"attachment wp-att-13140\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/galatina-756x1024.jpg\" alt=\"\" width=\"756\" height=\"1024\" class=\"alignleft size-large wp-image-13140\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/galatina-756x1024.jpg 756w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/galatina-221x300.jpg 221w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/galatina.jpg 872w\" sizes=\"(max-width: 756px) 100vw, 756px\" \/><\/a>Oggi 21 marzo, alle ore 11<\/span>, a Palazzo Adorno conferenza stampa di presentazione del progetto \u201c<strong>Templi di Vita e Arte Contemporanea per un nuovo rapporto tra Citt\u00e0 e Paesaggio Culturale<\/strong>\u201d, ciclo di eventi culturali promossi dall\u2019Associazione Poiesis e dal Comune di Galatina, in collaborazione con Provincia di Lecce, Regione Puglia, Ordine degli Architetti di Lecce, Confindustria Lecce, Associazione Filo di Aracne, con il coordinamento dei Laboratori Concept di Galatina.<br \/>\nAlla presentazione interverranno <strong>Antonio Gabellone<\/strong>, presidente della Provincia di Lecce, <strong>Andrea Coccioli<\/strong>, assessore ai Lavori Pubblici e Politiche giovanili del Comune di Galatina, <strong>Fabiana Cicirillo<\/strong>, vice presidente Ordine Architetti di Lecce e <strong>Luigi Mangia<\/strong>, dell\u2019Associazione Poiesis.<br \/>\nL\u2019evento culturale si svolger\u00e0 a Galatina <span style=\"text-decoration: underline\">dal 23 marzo al 25 aprile<\/span> prossimo.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/templi-di-vita-e-arte-contemporanea-per-un-nuovo-rapporto-tra-citta-e-paesaggio-culturale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/templi-di-vita-e-arte-contemporanea-per-un-nuovo-rapporto-tra-citta-e-paesaggio-culturale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Oggi 21 marzo, alle ore 11, a Palazzo Adorno conferenza stampa di presentazione del progetto \u201cTempli di Vita e Arte Contemporanea per un nuovo rapporto tra Citt\u00e0 e Paesaggio Culturale\u201d, ciclo di eventi culturali promossi dall\u2019Associazione Poiesis e dal Comune di Galatina, in collaborazione con Provincia di Lecce, Regione Puglia, Ordine degli Architetti di Lecce, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13140,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13139"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13139"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13139\/revisions"}],"predecessor-version":[{"id":13142,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13139\/revisions\/13142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13140"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}