{"id":13198,"date":"2013-03-21T14:43:30","date_gmt":"2013-03-21T14:43:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13198"},"modified":"2013-03-21T14:43:30","modified_gmt":"2013-03-21T14:43:30","slug":"rassegna-ci-la-ccappa-la-cunta-al-teatro-antoniano-di-lecce-sipario-su-vico-storto-carita-vecchia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/rassegna-ci-la-ccappa-la-cunta-al-teatro-antoniano-di-lecce-sipario-su-vico-storto-carita-vecchia\/","title":{"rendered":"RASSEGNA  \u201cCI LA CCAPPA \u2026 LA CUNTA\u201d:  AL TEATRO ANTONIANO DI LECCE SIPARIO SU   \u201cVICO STORTO CARITA\u2019 VECCHIA\u201d"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/rassegna-ci-la-ccappa-la-cunta-al-teatro-antoniano-di-lecce-sipario-su-vico-storto-carita-vecchia\/photo523_cuntipapa-calia_minm\/\" rel=\"attachment wp-att-13199\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Photo523_CuntiPapa-Calia_MinM.jpg\" alt=\"\" width=\"200\" height=\"268\" class=\"alignleft size-full wp-image-13199\" \/><\/a>Prosegue con un nuovo appuntamento \u201cCi la ccappa\u2026.la cunta!\u201d, Rassegna in vernacolo promossa ed organizzata dall\u2019Associazione culturale Antoniano di Lecce, con il patrocinio della Provincia di Lecce, giunta quest\u2019anno alla sua sesta edizione.<\/p>\n<p>\u00a0<span style=\"text-decoration: underline\">Domani, venerd\u00ec 22 marzo, nella Sala Comunit\u00e0 Cine Teatro Antoniano, alle ore 21<\/span>, la compagnia \u201cGruppo Sperimentale Teatrale\u201d di Monteroni, porter\u00e0 in scena \u201c<strong>Vico Storto Carit\u00e0 Vecchia<\/strong>\u201d di\u00a0 William Fiorentino, con la regia di Noemi Centonze e Antonella Rizzo.<\/p>\n<p>&nbsp;<\/p>\n<p>Il costo del biglietto per ogni rappresentazione \u00e8 di 7 euro ed il posto \u00e8 numerato; la prevendita dei biglietti \u00e8 da luned\u00ec al venerd\u00ec, dalle 16 alle 20. Per ulteriori informazioni:<a href=\"mailto:info@antonianolecce.it\">info@antonianolecce.it<\/a> oppure <a href=\"http:\/\/www.antonianolecce.it\/\">www.antonianolecce.it<\/a>; tel. 0832 392567.<\/p>\n<p>&nbsp;<\/p>\n<p>Il prossimo spettacolo della rassegna in vernacolo sar\u00e0 il <span style=\"text-decoration: underline\">5 aprile<\/span> con \u201cVilla Serena\u201d di William Fiorentino, con la regia dello stesso autore, interpretata da attori e attrici del gruppo teatrale \u201cLu Curtigghiu\u201d di Lecce.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/rassegna-ci-la-ccappa-la-cunta-al-teatro-antoniano-di-lecce-sipario-su-vico-storto-carita-vecchia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/21\/rassegna-ci-la-ccappa-la-cunta-al-teatro-antoniano-di-lecce-sipario-su-vico-storto-carita-vecchia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Prosegue con un nuovo appuntamento \u201cCi la ccappa\u2026.la cunta!\u201d, Rassegna in vernacolo promossa ed organizzata dall\u2019Associazione culturale Antoniano di Lecce, con il patrocinio della Provincia di Lecce, giunta quest\u2019anno alla sua sesta edizione. \u00a0Domani, venerd\u00ec 22 marzo, nella Sala Comunit\u00e0 Cine Teatro Antoniano, alle ore 21, la compagnia \u201cGruppo Sperimentale Teatrale\u201d di Monteroni, porter\u00e0 in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13198"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13198"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13198\/revisions"}],"predecessor-version":[{"id":13201,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13198\/revisions\/13201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13199"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}