{"id":13298,"date":"2013-03-22T15:34:44","date_gmt":"2013-03-22T15:34:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13298"},"modified":"2013-03-22T15:44:28","modified_gmt":"2013-03-22T15:44:28","slug":"no-tap","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/22\/no-tap\/","title":{"rendered":"NO TAP"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div dir=\"ltr\">\n<div>\n<div><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/30\/telerama-disinformazione-locale\/cinque-stelle\/\" rel=\"attachment wp-att-10163\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/cinque-stelle.jpg\" alt=\"\" width=\"325\" height=\"314\" class=\"alignleft size-full wp-image-10163\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/cinque-stelle.jpg 325w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/cinque-stelle-300x289.jpg 300w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/><\/a>Un ecomostro che minaccia di rovinare una delle pi\u00f9 belle coste del Salento e un territorio che da anni conquista la Bandiera Blu grazie ai suoi servizi ma soprattutto grazie al suo mare e al suo paesaggio costiero.<\/div>\n<div><\/div>\n<div>La Tap, in corso di realizzazione nel territorio compreso fra il mare di San Foca e il Comune di Vernole, sar\u00e0 l&#8217;argomento al centro del percorso di approfondimento del Movimento Cinque Stelle Lecce durante l&#8217;incontro di\u00a0<strong>sabato pomeriggio a partire dalle 16,30 presso la sede del Movimento in Corte dei Romiti 8<\/strong>.<\/div>\n<div><\/div>\n<div>La Tap \u00e8 un gasdotto che parte dall&#8217;Azerbaigian per approdare nel nostro territorio dove si sta realizzando una piattaforma al largo di San Foca (Comune di Melendugno) che sar\u00e0 collegata con una tubazione a forte impatto ambientale alla prevista centrale di depressurizzazione nel Comune di Vernole. Di tutto ci\u00f2 discuteremo sabato pomeriggio insieme agli amici della Cooperativa dei pescatori Il Delfino affiancata dal gruppo ecologista Biocontestiamo.<\/div>\n<div><\/div>\n<div>L&#8217;incontro di sabato pomeriggio si inserisce nella programmazione di iniziative del Movimento dedicate all&#8217;efficientamento energetico e al perseguimento di strade alternative per l&#8217;indipendenza energetica e per lo stop al consumo del territorio.<\/div>\n<div>Una nuova ottica di sviluppo incentrata sulle energie alternative (fotovoltaico, eolico, idrogeno ed altre fonti a basso impatto ambientale) con gli obiettivi della tutela e della valorizzazione del nostro paesaggio. Un incontro che si affianca ai precedenti dedicati all&#8217;uso inconsulto del carbone (leggi Cerano) e all&#8217;Ilva che tante tragedie sta procurando al territorio salentino. Un incontro aperto a tutte le voci ed ai contributi che vorranno essere apportati, sempre in uno spirito di collaborazione e partecipazione.Nella stessa giornata di sabato 23 marzo in Val di Susa si terr\u00e0 un&#8217;importante manifestazione contro la realizzazione della inutile e dannosa Tav, la linea ferroviaria ad alta velocit\u00e0 (15-20miliardi di euro spesi per un&#8217;opera utile per i soliti &#8220;pochi&#8221;). Un servizio del quale non se ne sente la mancanza, visto lo stato in cui versano i pi\u00f9 elementari servizi di trasporto in Italia e per i quali potrebbero essere investiti tutti quei fondi.<\/p>\n<\/div>\n<div>Alla manifestazione parteciper\u00e0 il cittadino leccese, deputato della Repubblica del Movimento Cinque Stelle Diego De Lorenzis. Il M5S di Lecce \u00e8 al suo fianco e sostiene questa grande battaglia contro la realizzazione di un&#8217;opera costosa, dannosa e da evitare a tutti i costi. L&#8217;appuntamento \u00e8 per sabato 23 marzo in Corte dei Romiti (nei pressi di piazza del Duomo) con inizio alle 16,30.<\/div>\n<div><\/div>\n<div>MoVimento 5 Stelle Lecce<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/22\/no-tap\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/22\/no-tap\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un ecomostro che minaccia di rovinare una delle pi\u00f9 belle coste del Salento e un territorio che da anni conquista la Bandiera Blu grazie ai suoi servizi ma soprattutto grazie al suo mare e al suo paesaggio costiero. La Tap, in corso di realizzazione nel territorio compreso fra il mare di San Foca e il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13298"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13298"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13298\/revisions"}],"predecessor-version":[{"id":13302,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13298\/revisions\/13302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/10163"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}