{"id":13439,"date":"2013-03-25T08:55:56","date_gmt":"2013-03-25T08:55:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13439"},"modified":"2013-03-25T08:55:56","modified_gmt":"2013-03-25T08:55:56","slug":"inquinamento-su-strade-come-fumo-passivo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/25\/inquinamento-su-strade-come-fumo-passivo\/","title":{"rendered":"Inquinamento su strade come fumo passivo"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/25\/inquinamento-su-strade-come-fumo-passivo\/6771_200x\/\" rel=\"attachment wp-att-13440\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/6771_200x.jpeg\" alt=\"\" width=\"200\" height=\"145\" class=\"alignleft size-full wp-image-13440\" \/><\/a>Il 14 % dei casi di asma cronica dei bambini potrebbe essere evitata se non si esponessero al traffico.<br \/>\n<\/strong>L\u2019inquinamento urbano \u00e8 una piaga per la salute, specie dei pi\u00f9 piccoli che dev\u2019essere combattuto in tutti i modi possibili per i costi sociali che comporta.<\/p>\n<p>A preoccupare ulteriormente Giovanni D&#8217;Agata, \u00e8 anche una recentissima ricerca dell&#8217;Istituto svizzero di salute tropicale e pubblica (Swiss TPH) di Basilea pubblicata sull&#8217;European Respiratory Journal ha rivelato che fino al 14% dei casi di asma cronica tra i bambini potrebbero essere evitati se i piccoli non fossero esposti all&#8217;inquinamento di strade a forte traffico.<\/p>\n<p>Un fenomeno, quello del traffico motorizzato che pu\u00f2 essere paragonato al fumo passivo che secondo i dati dll&#8217;Organizzazione mondiale della sanit\u00e0 (OMS), \u00e8 causa, infatti, di una percentuale compresa tra il 4% e il 18% dei casi di asma tra i bambini.<\/p>\n<p>L\u2019indagine scientifica in questione \u00e8 la prima che ha quantificato il numero di casi di asma cronica che potrebbero essere evitati se i bambini potessero respirare aria non inquinata anche perch\u00e9 sino ad oggi le conseguenze dell\u2019inalazione prolungata di gas di scarico erano associate solo ai casi di asma acuta.<\/p>\n<p>L\u2019equipe scientifica ha analizzato i dati provenienti da dieci grosse citt\u00e0 europee (Barcellona, Bilbao, Bruxelles, Granada, Lubiana, Roma, Siviglia, Stoccolma, Valencia e Vienna). Una strada \u00e8 considerata a forte traffico se vi circolano pi\u00f9 di 10&#8217;000 vetture al giorno.<\/p>\n<p>Questo studio che \u00e8 evidentemente estendibile nel resto del pianeta e quindi all\u2019Italia, \u00e8 un ulteriore monito nei confronti delle istituzioni e quindi dei Nostri amministratori dai Comuni sino alle massime autorit\u00e0 europee affinch\u00e9 si adoperino per adottare con urgenza e senza alcun differimento tutte le misure necessarie per ridurre l\u2019inquinamento nelle proprie citt\u00e0, come la chiusura al traffico dei centri urbani e l\u2019incentivazione di mezzi di locomozione pubblici o alternativi, anche perch\u00e9 \u00e8 sufficientemente provato che lo smog dovuto al traffico urbano \u00e8 causa diretta o indiretta di centinaia di migliaia di morti all\u2019anno e di costi sociali incalcolabili per il nostro sistema di Welfare.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/25\/inquinamento-su-strade-come-fumo-passivo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/25\/inquinamento-su-strade-come-fumo-passivo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il 14 % dei casi di asma cronica dei bambini potrebbe essere evitata se non si esponessero al traffico. L\u2019inquinamento urbano \u00e8 una piaga per la salute, specie dei pi\u00f9 piccoli che dev\u2019essere combattuto in tutti i modi possibili per i costi sociali che comporta. A preoccupare ulteriormente Giovanni D&#8217;Agata, \u00e8 anche una recentissima ricerca [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13439"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13439"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13439\/revisions"}],"predecessor-version":[{"id":13442,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13439\/revisions\/13442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13440"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}