{"id":13496,"date":"2013-03-27T11:16:04","date_gmt":"2013-03-27T11:16:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13496"},"modified":"2013-03-27T11:16:04","modified_gmt":"2013-03-27T11:16:04","slug":"ladri-di-cantiere-ci-riprovano-arrestati-dalle-volanti-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/ladri-di-cantiere-ci-riprovano-arrestati-dalle-volanti-2\/","title":{"rendered":"LADRI DI CANTIERE CI RIPROVANO. ARRESTATI DALLE VOLANTI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/ladri-di-cantiere-ci-riprovano-arrestati-dalle-volanti-2\/rollo-francesco\/\" rel=\"attachment wp-att-13497\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/ROLLO-FRANCESCO.jpg\" alt=\"\" width=\"494\" height=\"569\" class=\"alignleft size-full wp-image-13497\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/ROLLO-FRANCESCO.jpg 494w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/ROLLO-FRANCESCO-260x300.jpg 260w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/><\/a>Durante la decorsa notte, personale dell\u2019Ufficio Volanti interveniva in via Sandalo dove era stato segnalato un furto in atto. Giunti sul posto, il richiedente dichiarava agli agenti di aver sentito dei rumori provenire dal piano di sopra della propria abitazione dove sono in corso alcuni lavori per la costruzione di un appartamento e, dopo essersi affacciato aveva visto un\u2019autovettura che si era appena allontanata.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli agenti si ponevano immediatamente all\u2019inseguimento dell\u2019auto nella direzione indicata. L\u2019auto veniva intercettata e fermata dopo pochi minuti e venivano controllati i due uomini a bordo: <strong>MORETTI Marco, <\/strong>nato a San Paolo (Brasile) il 16.10.1988 e <strong>MARTUCCI Claudio <\/strong>\u00a0nato a Glarus (CHZ) il 04.01.1976, gi\u00e0 noti alle forze dell\u2019ordine, perch\u00e9 dediti alla commissione di furti nei cantieri e gi\u00e0 tratti in arresto da personale sezione Volanti in data 19.11.2012, per analogo reato.<\/p>\n<p>&nbsp;<\/p>\n<p>Da un immediato controllo all\u2019interno del veicolo di propriet\u00e0 del MARTUCCI\u00a0 Claudio, una mini car di colore grigio chiaro, marca AIXAM\u00a0 mod. MEGA C34 , nel bagagliaio, si rinvenivano dei cavi elettrici e dei tubi in rame, mentre sul sedile anteriore destro, si rinveniva una tenaglia, usata sicuramente per tranciare i cavi elettrici. In totale il materiale recuperato risulta essere: 3 cavi elettrici (prolunghe), di mt. 30 , 3 cavi elettrici di mt. 35, 2 cavi elettrici (prolunghe) di mt. 25, 2 cavi elettrici (prolunghe) di mt. 20, 2 tubi in rame rivestiti del diametro di 8 e 10 mm della lunghezza di mt. 1.<\/p>\n<p>&nbsp;<\/p>\n<p>Il materiale ritrovato veniva riconsegnato alla Ditta che aveva in appalto i lavori di costruzione ed i due venivano tratti in arresto per furto in flagranza di reato e condotti presso la locale casa circondariale<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/ladri-di-cantiere-ci-riprovano-arrestati-dalle-volanti-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/ladri-di-cantiere-ci-riprovano-arrestati-dalle-volanti-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Durante la decorsa notte, personale dell\u2019Ufficio Volanti interveniva in via Sandalo dove era stato segnalato un furto in atto. Giunti sul posto, il richiedente dichiarava agli agenti di aver sentito dei rumori provenire dal piano di sopra della propria abitazione dove sono in corso alcuni lavori per la costruzione di un appartamento e, dopo essersi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13496"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13496"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13496\/revisions"}],"predecessor-version":[{"id":13499,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13496\/revisions\/13499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13497"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}