{"id":135041,"date":"2018-04-09T15:14:02","date_gmt":"2018-04-09T13:14:02","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=135041"},"modified":"2018-04-09T15:14:02","modified_gmt":"2018-04-09T13:14:02","slug":"massacrati-di-multe-gli-automobilisti-leccesi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/09\/massacrati-di-multe-gli-automobilisti-leccesi\/","title":{"rendered":"MASSACRATI DI MULTE GLI AUTOMOBILISTI LECCESI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-135042\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani.jpg\" alt=\"\" width=\"1500\" height=\"1125\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/vigili-urbani-400x300.jpg 400w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>(g.p.)______Su centodieci citt\u00e0 capoluogo di provincia in Italia, Lecce \u00e8 al nono posto, ed \u00e8 la prima fra quelle del Sud. Classifica della qualit\u00e0 della vita? Del rispetto dell&#8217; ambiente? Dell&#8217; educazione civica? Macch\u00e8, dati sulle multe pagate dai cittadini automobilisti: 1 miliardo e settecento milioni di euro in Italia nel 2017, 7 milioni centosettanta mila euro a Lecce citt\u00e0.<\/p>\n<p>Ogni scusa, molte volte pretestuosa, per sanziare e stangare, e fare cassa, per i costi della politica, anche quella amminstrativa______<\/p>\n<p>L&#8217; APPROFONDIMENTO nel nostro articolo del 22 gennaio scorso<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ajTwYzZe77\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/01\/22\/meno-multe-a-lecce-citta-ma-fateci-il-piacere-la-nuova-amministrazione-peggio-della-prima-automobilisti-tartassati-quotidianamente-senza-pieta-ma-con-accanimento-persa-un-ottima-occasio\/\">MENO MULTE A LECCE CITTA&#8217;?!? MA MI FACCIA IL PIACERE&#8230;LA NUOVA AMMINISTRAZIONE PEGGIO DI QUELLA PRIMA, AUTOMOBILISTI TARTASSATI QUOTIDIANAMENTE SENZA PIETA&#8217; , MA CON ACCANIMENTO. PERSA UN&#8217; OTTIMA OCCASIONE PER FARE &#8216;QUALCOSA DI SINISTRA&#8217;, E UN&#8217; ALTRA OCCASIONE PER STARE ZITTI, CHE ERA MEGLIO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/01\/22\/meno-multe-a-lecce-citta-ma-fateci-il-piacere-la-nuova-amministrazione-peggio-della-prima-automobilisti-tartassati-quotidianamente-senza-pieta-ma-con-accanimento-persa-un-ottima-occasio\/embed\/#?secret=ajTwYzZe77\" data-secret=\"ajTwYzZe77\" width=\"500\" height=\"282\" title=\"&#8220;MENO MULTE A LECCE CITTA&#8217;?!? MA MI FACCIA IL PIACERE&#8230;LA NUOVA AMMINISTRAZIONE PEGGIO DI QUELLA PRIMA, AUTOMOBILISTI TARTASSATI QUOTIDIANAMENTE SENZA PIETA&#8217; , MA CON ACCANIMENTO. PERSA UN&#8217; OTTIMA OCCASIONE PER FARE &#8216;QUALCOSA DI SINISTRA&#8217;, E UN&#8217; ALTRA OCCASIONE PER STARE ZITTI, CHE ERA MEGLIO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/09\/massacrati-di-multe-gli-automobilisti-leccesi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/09\/massacrati-di-multe-gli-automobilisti-leccesi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.p.)______Su centodieci citt\u00e0 capoluogo di provincia in Italia, Lecce \u00e8 al nono posto, ed \u00e8 la prima fra quelle del Sud. Classifica della qualit\u00e0 della vita? Del rispetto dell&#8217; ambiente? Dell&#8217; educazione civica? Macch\u00e8, dati sulle multe pagate dai cittadini automobilisti: 1 miliardo e settecento milioni di euro in Italia nel 2017, 7 milioni centosettanta [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135041"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=135041"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135041\/revisions"}],"predecessor-version":[{"id":135043,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135041\/revisions\/135043"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=135041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=135041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=135041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}