{"id":135179,"date":"2018-04-11T18:31:01","date_gmt":"2018-04-11T16:31:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=135179"},"modified":"2018-04-11T19:08:20","modified_gmt":"2018-04-11T17:08:20","slug":"il-mondo-di-nuovo-col-fiato-sospeso-per-le-minacce-americane-possibile-intervento-militare-in-siria-per-ora-la-guerra-si-combatte-per-fortuna-solo-sui-social-e-intanto-in-italia-lunico-a-dire-qu","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/11\/il-mondo-di-nuovo-col-fiato-sospeso-per-le-minacce-americane-possibile-intervento-militare-in-siria-per-ora-la-guerra-si-combatte-per-fortuna-solo-sui-social-e-intanto-in-italia-lunico-a-dire-qu\/","title":{"rendered":"IL MONDO DI NUOVO COL FIATO SOSPESO, PER LE MINACCE AMERICANE. POSSIBILE INTERVENTO MILITARE IN SIRIA. FORTUNATAMENTE PER ORA SI COMBATTE SOLO SUI SOCIAL. E INTANTO IN ITALIA L&#8217; UNICO A DIRE QUALCOSA, PURE DI SENSATO, E&#8217; MATTEO SALVINI: &#8220;Basta guerre!&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-135180\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/assad-trump.jpg\" alt=\"\" width=\"594\" height=\"396\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/assad-trump.jpg 594w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/04\/assad-trump-300x200.jpg 300w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/>di <strong>Giuseppe Puppo______<\/strong><\/p>\n<p><em>&#8220;Notizie false per sganciare altre bombe? Basta guerre, grazie!<\/em>&#8220;. Lo scrive su Twitter il leader della Lega Matteo Salvini, intervenendo sulla crisi in Siria e linkando un articolo del sito Analisidifesa intitolato<em> &#8216;Siria: le &#8216;fake news sulle armi chimiche per creare il casus belli?&#8217;,<\/em> firmato da Gianandrea Gaiani. Tutto ineccepibile, sia il post di Salvini, sia il lungo, lucido, inppuntabile articolo dell&#8217; analista militare indipendente italiano.<\/p>\n<p>L&#8217; altra dichiarazione nostrana \u00e8 di Danilo Toninelli, capogruppo al Senato del M5S:\u00a0&#8220;<em>I ton<\/em>i&#8221; di queste ultime ore in Siria &#8220;<em>suscitano enormi preoccupazioni<\/em>&#8220;, lo &#8220;<em>scenario sembra che stia cambiando continuament<\/em>e&#8221;, pertanto il capogruppo del M5S Danilo Toninelli chiede che Gentiloni informi in Parlamento &#8220;<em>tutte le forze politiche sugli sviluppi in corso&#8221;.<\/em><\/p>\n<p>Gentiloni? Ma s\u00ec, non abbiamo un governo, solo fantasmi, noi.<\/p>\n<p>Mentre le navi si dispiegano nel mare nostrum e le compagnie aeree civili sono in allerta, per i propri voli nella regione mediorientale.<\/p>\n<p>Illuminanti, per\u00f2, le parole del leader leghista, un lampo di verit\u00e0, inedito, inusuale, per lui, che fa ben sperare, nel prossimo (aggettivo qualificativo, sottinteso governo).<\/p>\n<p>Donald Trump per ora, speriamo solo quelle, spara cazzate su Twitter:<em> &#8220;Russia vows to shoot down any and all missiles fired at Syria. Get ready Russia, because they will be coming, nice and new and \u201csmart!\u201d You shouldn\u2019t be partners with a Gas Killing Animal who kills his people and enjoys it!&#8221;.<\/em><\/p>\n<p>Appena appena mitigata dal tweet successivo:<em> &#8220;Our relationship with Russia is worse now than it has ever been, and that includes the Cold War. There is no reason for this. Russia needs us to help with their economy, something that would be very easy to do, and we need all nations to work together. Stop the arms race?&#8221;.<\/em><\/p>\n<p>La Russia risponde che cominci distruggere le sue, di armi chimiche, e se proprio vuole combattere, combatta i terroristi.<\/p>\n<p>Certo, preoccupa l&#8217; atteggiamento del presidente americano, che gi\u00e0 scaten\u00f2 un attacco missilistico contro i Siriani, contro ogni legge internazionale, un anno fa, per confermare la propria teoria di voler fare l&#8217; America di nuovo grande. Criminale. Preoccupa, ora che ha finito con i Nord Coreani, dimostratisi pi\u00f9 affidabili di lui, che se la pigli con i Siriani, da sceriffo da stapazzo del mondo.<\/p>\n<p>Preoccupa che oggi ne vuole sferrare un altro, senza motivo, dopo tutti i guai combinati dagli Occidentali in Siria, e le consegunze terribili per milioni di persone: l&#8217; unico motivo plausibile, far dimenticre all&#8217; opinione pubblica interna le proprie velleit\u00e0 politiche e gli scandali in cui \u00e8 coinvolto.<\/p>\n<p>La Nato, almeno Inghilterra e Francia si dicono pronte a seguire gli alleati americani.<\/p>\n<p>L&#8217; Italia \u00e8 dentro la Nato, purtroppo.<\/p>\n<p>In Italia, il ministro degli esteri \u00e8\/era Angelino Alfano. Scomparso. Come la politica estera italiana.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/11\/il-mondo-di-nuovo-col-fiato-sospeso-per-le-minacce-americane-possibile-intervento-militare-in-siria-per-ora-la-guerra-si-combatte-per-fortuna-solo-sui-social-e-intanto-in-italia-lunico-a-dire-qu\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/11\/il-mondo-di-nuovo-col-fiato-sospeso-per-le-minacce-americane-possibile-intervento-militare-in-siria-per-ora-la-guerra-si-combatte-per-fortuna-solo-sui-social-e-intanto-in-italia-lunico-a-dire-qu\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo______ &#8220;Notizie false per sganciare altre bombe? Basta guerre, grazie!&#8220;. Lo scrive su Twitter il leader della Lega Matteo Salvini, intervenendo sulla crisi in Siria e linkando un articolo del sito Analisidifesa intitolato &#8216;Siria: le &#8216;fake news sulle armi chimiche per creare il casus belli?&#8217;, firmato da Gianandrea Gaiani. Tutto ineccepibile, sia il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":135180,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135179"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=135179"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135179\/revisions"}],"predecessor-version":[{"id":135187,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/135179\/revisions\/135187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/135180"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=135179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=135179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=135179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}