{"id":13522,"date":"2013-03-27T11:35:52","date_gmt":"2013-03-27T11:35:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13522"},"modified":"2013-03-27T11:35:52","modified_gmt":"2013-03-27T11:35:52","slug":"nardo-pistola-in-pugno-rapina-un-supermercato-arrestato-da-carabinieri-e-polizia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/nardo-pistola-in-pugno-rapina-un-supermercato-arrestato-da-carabinieri-e-polizia\/","title":{"rendered":"Nard\u00f2. Pistola in pugno rapina un supermercato, arrestato da Carabinieri e Polizia"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/nardo-pistola-in-pugno-rapina-un-supermercato-arrestato-da-carabinieri-e-polizia\/schermata-2013-03-27-a-12-32-59\/\" rel=\"attachment wp-att-13524\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Schermata-2013-03-27-a-12.32.59.png\" alt=\"\" width=\"410\" height=\"163\" class=\"alignleft size-full wp-image-13524\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Schermata-2013-03-27-a-12.32.59.png 410w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/Schermata-2013-03-27-a-12.32.59-300x119.png 300w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/a>Nard\u00f2. Erano le prime ore dell\u2019alba di oggi, quando una pattuglia della Stazione Carabinieri di Nard\u00f2 ed una del locale Commissariato di P.S., hanno arrestato, dando esecuzione ad un\u2019 ordinanza di custodia cautelare richiesta dal P.M. Dott. Giovanni Gagliottta ed emessa ieri dall\u2019 Ufficio G.I.P. del Tribunale di Lecce D.ssa Antonia Martalo\u2019, Russo Riccardo, neretino 32enne, gi\u00e0 noto alle forze dell\u2019ordine per detenzione ai fini di spaccio di sostanze stupefacenti, furto ed altri reati contro il patrimonio. L\u2019uomo in data 15 marzo 2013 alle ore 19, aveva fatto irruzione nel supermercato \u201cEurospin\u201d di Nard\u00f2, a volto coperto da calzamaglia e casco ed armato di pistola, aveva minacciato la cassiera impossessandosi di 2000 \u20ac in contanti, dandosi alla fuga a bordo della propria autovettura. Il rapinatore \u00e8 stato individuato nei giorni successivi a seguito di complesse ed articolate indagini condotte in piena sinergia dai Carabinieri della locale Stazione insieme agli Agenti del Commissariato di P.S. di Nard\u00f2 che hanno permesso, anche grazie agli elementi forniti dal proprietario del suddetto supermercato nonch\u00e9 dalla stessa cassiera malcapitata, di addivenire con tempestivit\u00e0 e schiacciante efficacia probatoria alla risoluzione del \u201ccaso\u201d. L\u2019uomo, riconosciuto successivamente anche grazie alla fondamentale testimonianza dei dipendenti del supermercato quale autore della rapina, dopo le formalit\u00e0 di rito \u00e8 stato dichiarato in arresto e quindi condotto alla Casa Circondariale di Lecce, a disposizione dell\u2019 Autorit\u00e0 Giudiziaria.<\/p>\n<p align=\"center\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/nardo-pistola-in-pugno-rapina-un-supermercato-arrestato-da-carabinieri-e-polizia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/27\/nardo-pistola-in-pugno-rapina-un-supermercato-arrestato-da-carabinieri-e-polizia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nard\u00f2. Erano le prime ore dell\u2019alba di oggi, quando una pattuglia della Stazione Carabinieri di Nard\u00f2 ed una del locale Commissariato di P.S., hanno arrestato, dando esecuzione ad un\u2019 ordinanza di custodia cautelare richiesta dal P.M. Dott. Giovanni Gagliottta ed emessa ieri dall\u2019 Ufficio G.I.P. del Tribunale di Lecce D.ssa Antonia Martalo\u2019, Russo Riccardo, neretino [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13524,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13522"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13522"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13522\/revisions"}],"predecessor-version":[{"id":13526,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13522\/revisions\/13526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13524"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}