{"id":13623,"date":"2013-03-30T12:28:37","date_gmt":"2013-03-30T12:28:37","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13623"},"modified":"2013-03-30T12:29:33","modified_gmt":"2013-03-30T12:29:33","slug":"concorso-vigili-urbani-il-6-giugno-la-prova-scritta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/30\/concorso-vigili-urbani-il-6-giugno-la-prova-scritta\/","title":{"rendered":"CONCORSO VIGILI URBANI, IL 6 GIUGNO LA PROVA SCRITTA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/30\/concorso-vigili-urbani-il-6-giugno-la-prova-scritta\/imagepath-ashx\/\" rel=\"attachment wp-att-13624\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/03\/ImagePath.ashx_.jpeg\" alt=\"\" width=\"285\" height=\"245\" class=\"alignleft size-full wp-image-13624\" \/><\/a>I candidati dovranno presentarsi alle 13.30, al plesso Y di Ingegneria del complesso Ecotekne.<em><br \/>\n<\/em>E\u2019 stata fissata per il giorno <strong>6 giugno 2013, alle ore 15.30,<\/strong> la prova scritta per i candidati ammessi, ai sensi dell\u2019articolo 10 del Bando di Concorso per i Vigili Urbani. La prova si svolger\u00e0 presso l\u2019Universit\u00e0 del Salento (complesso Ecotekne), via per Monteroni snc, plesso Y Ingegneria.<\/p>\n<p>I candidati dovranno presentarsi alle ore 13.30, presso il plesso Y di Ingegneria, per le operazioni di identificazione; dovranno essere muniti di un valido documento di riconoscimento; non potranno portare carta da scrivere, appunti, manoscritti, libri o pubblicazioni di qualunque specie. I candidati potranno introdurre in aula e consultare soltanto i testi di legge non commentati, non annotati e non illustrati ed autorizzati dalla Commissione. E\u2019 fatto altres\u00ec divieto ai candidati di portare e utilizzare telefoni cellulari o altre attrezzature elettroniche. ranno essere muniti di un valido documento di riconoscimento; non potranno portare carta da scrivere, appunti, manoscritti, libri o pubblicazioni di qualunque specie.<br \/>\nI candidati potranno introdurre in aula e consultare soltanto i testi di legge non commentati, non annotati e non illustrati ed autorizzati dalla Commissione.<br \/>\nE\u2019 fatto altres\u00ec divieto ai candidati di portare e utilizzare telefoni cellulari o altre attrezzature elettroniche.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/30\/concorso-vigili-urbani-il-6-giugno-la-prova-scritta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/03\/30\/concorso-vigili-urbani-il-6-giugno-la-prova-scritta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I candidati dovranno presentarsi alle 13.30, al plesso Y di Ingegneria del complesso Ecotekne. E\u2019 stata fissata per il giorno 6 giugno 2013, alle ore 15.30, la prova scritta per i candidati ammessi, ai sensi dell\u2019articolo 10 del Bando di Concorso per i Vigili Urbani. La prova si svolger\u00e0 presso l\u2019Universit\u00e0 del Salento (complesso Ecotekne), [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13624,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13623"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13623"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13623\/revisions"}],"predecessor-version":[{"id":13628,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13623\/revisions\/13628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13624"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}