{"id":136901,"date":"2018-05-14T11:34:42","date_gmt":"2018-05-14T09:34:42","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=136901"},"modified":"2018-05-14T11:41:08","modified_gmt":"2018-05-14T09:41:08","slug":"mister-x-sotto-i-raggi-di-sergio-mattarella","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/14\/mister-x-sotto-i-raggi-di-sergio-mattarella\/","title":{"rendered":"MISTER X SOTTO I RAGGI DI SERGIO MATTARELLA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-136902\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/quirinale.jpg\" alt=\"\" width=\"720\" height=\"484\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/quirinale.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/quirinale-300x202.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>vm______Il nome c&#8217;\u00e8, almeno a stare alle dichiarazioni pi\u00f9 attendibili, uno solo, ed \u00e8 un politico, sempre ammesso che non siano depistaggi, buoni in caso di cambiamenti di scenari,\u00a0 e che su questo punto fondamentale l&#8217; intesa sia stata effettivamente raggiunta. Sul programma, anzi, &#8216;il contratto&#8217;, per adoperare il lessico degli protagonisti del nuovo esecutivo, invece, si hanno certezze in pi\u00f9 sull&#8217; effettiva stesura pi\u00f9 o meno concorde.<\/p>\n<p>L&#8217; impressione comunque \u00e8 che sul punto fondamentale di chi guider\u00e0 il governo la situazione sia ancora fluida. Circolano in queste ore decine di nomi, nessuno dei quali trova conferme, oltretutto perch\u00e8 \u00e8 ancora da vedere se sar\u00e0 gradito al presidente della Repubblica, che dovr\u00e0 dargli l&#8217; incarico.<\/p>\n<p>Sergio Mattarella ricever\u00e0 al Quirinale la delegazione del Movimento 5 Stelle alle 16.30, quella della Lega alle 18.00. E poi si vedr\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/14\/mister-x-sotto-i-raggi-di-sergio-mattarella\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/14\/mister-x-sotto-i-raggi-di-sergio-mattarella\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>vm______Il nome c&#8217;\u00e8, almeno a stare alle dichiarazioni pi\u00f9 attendibili, uno solo, ed \u00e8 un politico, sempre ammesso che non siano depistaggi, buoni in caso di cambiamenti di scenari,\u00a0 e che su questo punto fondamentale l&#8217; intesa sia stata effettivamente raggiunta. Sul programma, anzi, &#8216;il contratto&#8217;, per adoperare il lessico degli protagonisti del nuovo esecutivo, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":136902,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/136901"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=136901"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/136901\/revisions"}],"predecessor-version":[{"id":136907,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/136901\/revisions\/136907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/136902"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=136901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=136901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=136901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}