{"id":137081,"date":"2018-05-19T00:03:15","date_gmt":"2018-05-18T22:03:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=137081"},"modified":"2018-05-19T11:39:35","modified_gmt":"2018-05-19T09:39:35","slug":"mario-pugliese-e-nicola-vacca-presentano-il-loro-libro-meraviglia-dal-tratto-alle-parole-a-lecce-domenica-20","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/19\/mario-pugliese-e-nicola-vacca-presentano-il-loro-libro-meraviglia-dal-tratto-alle-parole-a-lecce-domenica-20\/","title":{"rendered":"MARIO PUGLIESE E NICOLA VACCA PRESENTANO IL LORO LIBRO-MERAVIGLIA A LECCE DOMENICA 20"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-137082\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/30118736_1905422226168593_1559722631_n.jpg\" alt=\"\" width=\"900\" height=\"1238\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/30118736_1905422226168593_1559722631_n.jpg 349w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/30118736_1905422226168593_1559722631_n-218x300.jpg 218w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>(e.b.)______<em>&#8220;Dal tratto alle parole&#8221;<\/em> di <strong>Mario Pugliese<\/strong> e <strong>Nicola Vacca,\u00a0<\/strong>I quaderni del Bardo Edizioni,\u00a0<strong>domenica 20 maggio 2018<\/strong> sar\u00e0 presentato ufficialmente per la prima volta in Puglia al Fondo Verri di <strong>Lecce,<\/strong> in via Santa Maria del Paradiso 8 da Alessandro Vergari e Giuseppe Scaglione, critici letterari, e dall\u2019editore Stefano Donno che dialogheranno con gli autori. Si comincia <strong>alle 19.00<\/strong>. L\u2019evento \u00e8 organizzato da I Quaderni del Bardo Edizioni, I Libri di Icaro, Fondo Verri e Associazione Thorah.______<\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Mario Pugliese ha preso in mano la matita e ha reso omaggio ad alcuni grandi della letteratura.&#8221; \u00c8 un viaggio rapido e incisivo tra i ritratti di scrittori e poeti che si sono opposti all&#8217;imperativo massificante del quieto vivere e si sono donati al demone della scrittura,spillando inchiostro dalle proprie vene&#8221;. (Dalla prefazione di Alessandro Vergari)<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">&#8221; Per entrambi a tenere le fila concettuali di questo progetto, al contempo limpido e complesso, si pone il sentiment stesso del Novecento. Lavorando a questo libro sia Vacca che Pugliese hanno scandagliato non solo quanto di iconico ha espresso il secolo breve, ma ne hanno ricercato le verit\u00e0 pi\u00f9 profonde, a volte le pi\u00f9 nascoste&#8221;. (Dalla postfazione di Giuseppe Scaglione)<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><b>Nicola Vacca<\/b><\/span><\/span><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"> \u00e8 nato a Gioia del Colle, nel 1963, laureato in giurisprudenza. \u00c8 scrittore, opinionista, critico letterario, collabora alle pagine culturali di quotidiani e riviste. Svolge, inoltre, un\u2019intensa attivit\u00e0 di operatore culturale, organizzando presentazioni ed eventi legati al mondo della poesia contemporanea. Ha pubblicato: Nel bene e nel male (Schena,1994); Frutto della passione (Manni 2000); La grazia di un pensiero (prefazione di Paolo Ruffilli, Pellicani, 2002); Serena musica segreta (Manni, 2003); Civilt\u00e0 delle anime (Book editore, 2004); Incursioni nell\u2019apparenza (prefazione di Sergio Zavoli Manni 2006); Ti ho dato tutte le stagioni (prefazione di Antonio Debenedetti, Manni 2007); Frecce e pugnali (prefazione di Giordano Bruno Guerri, Edizioni Il Foglio 2008); Esperienza degli affanni (Edizioni il Foglio 2009); con Carlo Gambescia il pamphlet A destra per caso (Edizioni Il Foglio 2010); Serena felicit\u00e0 nell\u2019istante (prefazione di Paolo Ruffilli, Edizioni Il Foglio 2010); Almeno un grammo di salvezza (Edizioni Il Foglio, 2011); Mattanza dell\u2019incanto (prefazione di Gian Ruggero Manzoni Marco Saya edizioni 2013); Sguardi dal Novecento (Galaad edizioni 2014); Luce nera (Marco Saya edizioni 2015, Premio Camaiore 2016); Vite colme di versi (Galaad edizioni 2016); Commedia Ubriaca (Marco Saya 2017); Lettere a Cioran (Galaad edizioni 2017). <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><b>Mario Pugliese<\/b><\/span><\/span><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">, classe 1964, figlio d\u2019arte diplomato al liceo artistico di Bari,successivamente si specializza a Udine in grafica pubblicitaria. Partecipa a numerose mostre e fiere in Italia e all\u2019estero. Collabora con diversi artisti e musicisti alla divulgazione dell\u2019arte e della musica come strumento di comunicazione. Le sue opere sono presenti in edifici pubblici e privati. Attualmente \u00e8 presidente dell\u2019associazione artistico culturale \u201cArtensione\u201d e direttore artistico di \u201cSpaziounotre\u201d a Gioia del Colle dove risiede e lavora. Contatti; <\/span><\/span><a href=\"http:\/\/www.rentartdesign.com\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><u>http:\/\/www.rentartdesign.com\/<\/u><\/span><\/span><\/span><\/a> <a href=\"mailto:artpugliese@tiscali.it\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><u>artpugliese@tiscali.it<\/u><\/span><\/span><\/span><\/a><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"> \u00a0Studio: via Giunone 26 Gioia del Colle (Ba) <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Segreteria Organizzativa: Dott.ssa Emanuela Boccassini,<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Impaginazione e grafica editoriale: Mauro Marino<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Progetti di sviluppo editoriale: Mario Contino, Mauro Camassa, Perla Longo, Paride Pino, Eliana Masulli<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\">Info link &#8211; <\/span><\/span><\/span><a href=\"http:\/\/www.iquadernidelbardoedizioni.it\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\"><u>http:\/\/www.iquadernidelbardoedizioni.it\/<\/u><\/span><\/span><\/span><\/span><\/a><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">iQdB edizioni di Stefano Donno (i Quaderni del Bardo Edizioni di Stefano Donno)<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Sede Legale e Redazione: Via S. Simone 74 &#8211; 73107 Sannicola (LE)<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\">Mail\u00a0 <\/span><\/span><\/span><a href=\"mailto:iquadernidelbardoed@libero.it\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\"><u>iquadernidelbardoed@libero.it<\/u><\/span><\/span><\/span><\/span><\/a><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\">Info Link &#8211; <\/span><\/span><\/span><a href=\"http:\/\/www.iquadernidelbardoedizioni.it\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><span lang=\"en-US\"><u>http:\/\/www.iquadernidelbardoedizioni.it\/<\/u><\/span><\/span><\/span><\/span><\/a><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Mudec, Museo delle Culture<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">via Tortona 56, Milano<\/span><\/span><\/p>\n<p align=\"justify\"><a href=\"http:\/\/www.festivaletteraturamilano.it\/FIPM\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><u>http:\/\/www.festivaletteraturamilano.it\/FIPM\/<\/u><\/span><\/span><\/span><\/a><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">I libri di Icaro <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">I LIBRI DI ICARO Edizioni<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Viale Finlandia, 11 &#8211; Lecce<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">Tel. 371 1878199 &#8211; Tel. 327 6956111<\/span><\/span><\/p>\n<p align=\"justify\"><a href=\"http:\/\/www.icarolibri.com\/\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><u>www.icarolibri.com<\/u><\/span><\/span><\/span><\/a><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\">\u00a0 &#8211; <\/span><\/span><a href=\"mailto:info@icarolibri.com\"><span style=\"color: #0000ff;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: medium;\"><u>info@icarolibri.com<\/u><\/span><\/span><\/span><\/a><\/p>\n<p>______<\/p>\n<p>LA RICERCA nei nostri articoli del 10 aprile e 18 aprile<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"LMqNzfNoRI\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/10\/le-piccole-cose-di-wislawa\/\">&#8220;Le piccole cose di Wis\u0142awa&#8221;<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/10\/le-piccole-cose-di-wislawa\/embed\/#?secret=LMqNzfNoRI\" data-secret=\"LMqNzfNoRI\" width=\"500\" height=\"282\" title=\"&#8220;&#8220;Le piccole cose di Wis\u0142awa&#8221;&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"zmHx1o2qZd\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/18\/nicola-vacca-mario-pugliese-e-pietro-romano-per-le-edizioni-i-quaderni-del-bardo-di-stefano-donno\/\">NICOLA VACCA, MARIO PUGLIESE E PIETRO ROMANO PER LE EDIZIONI I QUADERNI DEL BARDO DI STEFANO DONNO<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/04\/18\/nicola-vacca-mario-pugliese-e-pietro-romano-per-le-edizioni-i-quaderni-del-bardo-di-stefano-donno\/embed\/#?secret=zmHx1o2qZd\" data-secret=\"zmHx1o2qZd\" width=\"500\" height=\"282\" title=\"&#8220;NICOLA VACCA, MARIO PUGLIESE E PIETRO ROMANO PER LE EDIZIONI I QUADERNI DEL BARDO DI STEFANO DONNO&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/19\/mario-pugliese-e-nicola-vacca-presentano-il-loro-libro-meraviglia-dal-tratto-alle-parole-a-lecce-domenica-20\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/19\/mario-pugliese-e-nicola-vacca-presentano-il-loro-libro-meraviglia-dal-tratto-alle-parole-a-lecce-domenica-20\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.b.)______&#8220;Dal tratto alle parole&#8221; di Mario Pugliese e Nicola Vacca,\u00a0I quaderni del Bardo Edizioni,\u00a0domenica 20 maggio 2018 sar\u00e0 presentato ufficialmente per la prima volta in Puglia al Fondo Verri di Lecce, in via Santa Maria del Paradiso 8 da Alessandro Vergari e Giuseppe Scaglione, critici letterari, e dall\u2019editore Stefano Donno che dialogheranno con gli autori. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":137082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,75,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137081"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=137081"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137081\/revisions"}],"predecessor-version":[{"id":137219,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137081\/revisions\/137219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/137082"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=137081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=137081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=137081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}