{"id":137092,"date":"2018-05-17T17:26:24","date_gmt":"2018-05-17T15:26:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=137092"},"modified":"2018-05-17T17:29:35","modified_gmt":"2018-05-17T15:29:35","slug":"137092","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/17\/137092\/","title":{"rendered":"TRE &#8216;TOPI&#8217; DI APPARTAMENTO, IN TRASFERTA DI &#8216;LAVORO&#8217; AD ALESSANO, SCOPERTI, ARRESTATI E PORTATI IN CARCERE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137093\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/LADRI-ACROBATI-ALESSANO.jpg\" alt=\"\" width=\"724\" height=\"532\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/LADRI-ACROBATI-ALESSANO.jpg 724w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/LADRI-ACROBATI-ALESSANO-300x220.jpg 300w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>(e.l.)______I furti negli appartamenti, da parte dei cos\u00ec detti &#8216;topi di alloggio&#8217;, sono un fenomeno purtroppo diffuso che, per quanto considerato &#8216;microcriminalit\u00e0&#8217;, produce nelle numerose vittime quotidiane un grande sconforto, al di l\u00e0 del danno materiale, comunque a volte anche ingente, con serie ripercussioni psicologiche. Sensazione acuita dall&#8217; impunt\u00e0 sostanziale di cui i responsabili, che il pi\u00f9 delle volte rimangon impuniti, godono, o direttamente, o indirettamente. Quasi sempre.<\/p>\n<p>I Carabinieri di Alessano questa mattina hanno inseguito tre ladri &#8216;acrobati, ritenuti responsabili di tre furti in abitazione,&#8217; e li hanno arrestati in flagranza di reato dopo un rocambolesco inseguimento sui tetti, non solo, ma, su disposizione del magistrato di turno presso la Procura della Repubblica di Lecce, li hanno portati in carcere.<\/p>\n<p>Si tratta di (nelle foto, dall&#8217; alto in basso) Mica Jovanovic, 20 anni, nato a Roma e residente a Guidonia; Susanna Dzabiroski, 20 anni, nata e residente a Roma; e di Angelica Nikolic, 19 anni, nata a Palestrina e residente a Zagarolo.<\/p>\n<p>I militari sono intervenuti dopo la segnalazione della prima vittima, e hanno scovato i tre nascosti sul tetto dell&#8217; abitazione, riuscendo poi a immobilizzarli, dopo un rocambolesco, quanto pericoloso inseguimnto, fra i tetti della palazzine limitrofe.<\/p>\n<p>Recuperata tutta quanta la refertiva che avevano rubato in tre distinti furti, in case diverse. Un bottino ingente, stimato del valore di oltre 40 000 uro, restituito ai lgittimi proprietari, costituito da numerose collane, collanine, bracciali, braccialetti, orecchini, anelli, fedi, spille e orologi, oltre a 1450 euro in contanti.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137094\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/JOVANOVIC_MICA.jpg\" alt=\"\" width=\"290\" height=\"430\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/JOVANOVIC_MICA.jpg 290w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/JOVANOVIC_MICA-202x300.jpg 202w\" sizes=\"(max-width: 290px) 100vw, 290px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137095\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/DZABIROSKI_SUSANNA.jpg\" alt=\"\" width=\"277\" height=\"374\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/DZABIROSKI_SUSANNA.jpg 277w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/DZABIROSKI_SUSANNA-222x300.jpg 222w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137096\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/NIKOLIC_ANGELICA.jpg\" alt=\"\" width=\"286\" height=\"426\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/NIKOLIC_ANGELICA.jpg 286w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/NIKOLIC_ANGELICA-201x300.jpg 201w\" sizes=\"(max-width: 286px) 100vw, 286px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/17\/137092\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/17\/137092\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______I furti negli appartamenti, da parte dei cos\u00ec detti &#8216;topi di alloggio&#8217;, sono un fenomeno purtroppo diffuso che, per quanto considerato &#8216;microcriminalit\u00e0&#8217;, produce nelle numerose vittime quotidiane un grande sconforto, al di l\u00e0 del danno materiale, comunque a volte anche ingente, con serie ripercussioni psicologiche. Sensazione acuita dall&#8217; impunt\u00e0 sostanziale di cui i responsabili, che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137092"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=137092"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137092\/revisions"}],"predecessor-version":[{"id":137100,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137092\/revisions\/137100"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=137092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=137092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=137092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}