{"id":137803,"date":"2018-05-28T13:25:01","date_gmt":"2018-05-28T11:25:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=137803"},"modified":"2018-05-28T13:50:17","modified_gmt":"2018-05-28T11:50:17","slug":"l-arrotino-venite-gente-e-arrivato-l-arrotino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/l-arrotino-venite-gente-e-arrivato-l-arrotino\/","title":{"rendered":"L&#8217; ARROTINO! VENITE GENTE, E&#8217; ARRIVATO L&#8217; ARROTINO!"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-137804\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b.jpg\" alt=\"\" width=\"900\" height=\"416\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b.jpg 799w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b-300x139.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b-768x355.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b-630x290.jpg 630w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/cc-b-315x145.jpg 315w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>di <strong>Giuseppe Puppo______<\/strong><\/p>\n<p>La guerra \u00e8 finita da tre quarti di secolo, ma siamo ancora un Paese a sovranit\u00e0 limitata. Per cinquant&#8217; anni lo siamo stati solamente degli Usa, che sono pesantemente e ripetutamente intervenuti nel condizionare i nostri destini. Negli ultimi lustri lo siamo diventati anche dell&#8217; Unione Europea, cio\u00e8 l&#8217; Europa dei burocrati dei lobbysti dei banchieri dell&#8217; alta finanza internazionale al servizio degli interessi dei privilegiati contro quelli dei popoli.<\/p>\n<p>Non esite pi\u00f9 destra, n\u00e8 sinistra, ce ne dobbiamo fare tutti quanti una ragione. Semplicemente: c&#8217;\u00e8 chi sta da una parte, e invece chi sta dall&#8217; altra.<\/p>\n<p>Da una parte, che \u00e8 poi quella degli affaire, dei gasdotti, delle trivelle, delle devastazioni ambientali, in primis ci sta Sergio Mattarella, che ieri sera ha candidamente rivelato a tutti, qualora non fosse ancora chiaro, la nostra condizione politica di servi, se non di schiavi.<\/p>\n<p>Il suo golpe \u00e8 perfettamente riuscito.<\/p>\n<p>Questa mattina \u00e8 arrivato l&#8217; arrotino.<\/p>\n<p>Carlo Cottarelli, 64 anni, gi\u00e0 funzionario del Fondo Monetario Internazionale, nel\u00a02013 Commissario straordinario per la\u00a0Revisione della spesa pubblica del governo di Enrico Letta, e nel 2014, su nomina del governo di Matteo Renzi, direttore esecutivo nel Board del Fondo Monetario Internazionale.<\/p>\n<p>Poco dopo era gi\u00e0 tutto fatto.<\/p>\n<p><em>&#8220;Ho accettato l&#8217;incarico di formare un governo come mi ha chiesto il presidente della Repubblica. Sono molto onorato come italiano di questo incarico e naturalmente ce la metter\u00f2 tutta. In assenza di fiducia il governo si dimetterebbe immediatamente ed il suo compito \u00e8 quello dell&#8217;ordinaria amministrazione per le elezioni dopo il mese di agosto. Negli ultimi giorni sono aumentate le tensioni sui mercati finanziari, lo spread \u00e8 aumentato, tuttavia l&#8217;economia italiana \u00e8 in crescita e i conti pubblici rimangono sotto controllo. Un governo da me guidato assicurerebbe una gestione prudente dei nostri conti pubblici. Il dialogo con la Ue in difesa dei nostri interessi \u00e8 essenziale, deve essere un dialogo costruttivo, nel pieno riconoscimento del ruolo essenziale dell&#8217; Itaalia. Confermo la continua partecipazione all&#8217;area dell&#8217;euro&#8221;.<\/em><\/p>\n<p>Queste le sue prime parole.<\/p>\n<p>Andr\u00e0 in Parlamento a cercare voti. Presumibilmente non avr\u00e0 la fiducia, ma non \u00e8 detto, &#8216;menti raffinatissime&#8217; sono gi\u00e0 al lavoro per lui e per loro.<\/p>\n<p>Nella peggiore, per loro, delle ipotesi, rester\u00e0 comunque in carica. Per mesi. Poi diranno che non si pu\u00f2 andare a votare con il Rosatellum, e che quindi bisogna fare prima una nuova legge elettorale, un&#8217; altra volta. Poi succeder\u00e0 qualcosa, di eccezionale, e andremo al 2019. E rimetteranno fuori le cazzate dello spread, del debito pubblico, dei vincoli di bilancio.<\/p>\n<p>Ma tanto, che diamine ci andiamo a fare a votare, se siamo stati condannati da banchieri, speculatori e lobbysti dell&#8217; alta finanza internazionale, e dai politici italiani loro camerieri, a restare nell&#8217; euro, a non avere una nostra sovranit\u00e0 nazionale, una nostra moneta, una nostra dignit\u00e0? e a non poterci nemmeno provare, a liberarci, da questi lacci che ci stanno impoverendo sempre di pi\u00f9, ci stanno soffocando, ci stanno rovinando, ci stanno ammazzando.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/l-arrotino-venite-gente-e-arrivato-l-arrotino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/l-arrotino-venite-gente-e-arrivato-l-arrotino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo______ La guerra \u00e8 finita da tre quarti di secolo, ma siamo ancora un Paese a sovranit\u00e0 limitata. Per cinquant&#8217; anni lo siamo stati solamente degli Usa, che sono pesantemente e ripetutamente intervenuti nel condizionare i nostri destini. Negli ultimi lustri lo siamo diventati anche dell&#8217; Unione Europea, cio\u00e8 l&#8217; Europa dei burocrati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":137804,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137803"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=137803"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137803\/revisions"}],"predecessor-version":[{"id":137809,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137803\/revisions\/137809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/137804"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=137803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=137803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=137803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}