{"id":137822,"date":"2018-05-28T12:40:58","date_gmt":"2018-05-28T10:40:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=137822"},"modified":"2018-05-28T18:46:03","modified_gmt":"2018-05-28T16:46:03","slug":"grave-giovane-invtito-da-un-auto-pirata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/grave-giovane-invtito-da-un-auto-pirata\/","title":{"rendered":"GRAVE GIOVANE INVESTITO DA UN&#8217; AUTO PIRATA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137823\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata.jpg\" alt=\"\" width=\"2304\" height=\"1296\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata.jpg 2304w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata-1536x864.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/ospedale-ss_-annunziata-2048x1152.jpg 2048w\" sizes=\"(max-width: 2304px) 100vw, 2304px\" \/>(e.l.)______All&#8217; alba di ieri c&#8217;\u00e8 stato nei pressi di Taranto un drammatico episodio di cronaca nera. Un pedone, un giovane di 28 anni, \u00e8 stato investito da un&#8217; auto pirata. Si trova ora ricoverato all&#8217; ospedale Santissima Annunziata in prognosi riservata, per i diversi traumi riportati nell&#8217; impatto subito.<\/p>\n<p>E&#8217; accaduto\u00a0 in viale Jonio, a San Vito, nei pressi di una discoteca, sotto gli occhi di alcuni testimoni. Una Peugeot \u00e8 arrivata a velocit\u00e0 sostenuta, ha centrato il passante e ha proseguito la corsa senza fermrsi.<\/p>\n<p>Il conducente, un giovane di 24 anni, raggiunto e bloccato poco dopo a fatica nella zona di Leporano dagli agenti dellla Polizia di Stato, come si \u00e8 apprso oggi, \u00e8 stato arrestato, con numerose accuse: fra l&#8217; altro guidava senza aver mai conseguito la patente.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/grave-giovane-invtito-da-un-auto-pirata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/28\/grave-giovane-invtito-da-un-auto-pirata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______All&#8217; alba di ieri c&#8217;\u00e8 stato nei pressi di Taranto un drammatico episodio di cronaca nera. Un pedone, un giovane di 28 anni, \u00e8 stato investito da un&#8217; auto pirata. Si trova ora ricoverato all&#8217; ospedale Santissima Annunziata in prognosi riservata, per i diversi traumi riportati nell&#8217; impatto subito. E&#8217; accaduto\u00a0 in viale Jonio, a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":137823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137822"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=137822"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137822\/revisions"}],"predecessor-version":[{"id":137825,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137822\/revisions\/137825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/137823"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=137822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=137822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=137822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}