{"id":137966,"date":"2018-05-30T18:08:24","date_gmt":"2018-05-30T16:08:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=137966"},"modified":"2018-05-30T18:10:58","modified_gmt":"2018-05-30T16:10:58","slug":"storie-di-ordinaria-follia-a-manduria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/30\/storie-di-ordinaria-follia-a-manduria\/","title":{"rendered":"STORIE DI ORDINARIA FOLLIA A MANDURIA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-137967\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/manduria.jpg\" alt=\"\" width=\"650\" height=\"487\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/manduria.jpg 650w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/manduria-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/05\/manduria-400x300.jpg 400w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>(e.l.)_____<\/p>\n<p>Era affidato in prova ai servizi sociali. Beh, evidentemnte la prova \u00e8 andata proprio male.<\/p>\n<p>Scene da film dell&#8217; orrore ieri sera a Manduria, dove in una palazzina del centro, dal primo piano, un uomo di 57 anni, pregiudicato,\u00a0 ha preso a buttare su auto e passanti quello che gli capitava di avere in casa: oggetti, liquidi, suppellettili.<\/p>\n<p>&nbsp;<\/p>\n<p>Aveva prima tentato di ggredire un vicino con una motosega.<\/p>\n<p>Poi si era barricato in casa, e non apriva.<\/p>\n<p>E&#8217; durata un&#8217; ora. Sono arrivati agenti della Polizia di Stato, militari dell&#8217; Arma, Vigili del Fuoco, sanitari del 118. Allora il folle, ch\u00e9 evidentemente si trovava in uno stato di profonda alterazione psichica, \u00e8 scappato sul tetto.<\/p>\n<p>E da l\u00e0 ha ricominciato. Un&#8217; altra ora di pazzie, di nuovo con lanci, questa volta pi\u00f9 pericolosi, perch\u00e9 da altezza maggiore. Fino a quando, passando da una palazzina vicina, le Forze dell&#8217; Ordine non sono riuscite a bloccarlo, non senza difficolt\u00e0: infatti, l&#8217; uomo ha puntato contro di loro un fucile subacqueo.<\/p>\n<p>Si trova ora ricoverato all&#8217; ospedale Santissima Annunziata di Taranto, dopo essere stato sedato.<\/p>\n<p>E&#8217; stato denunciato oggi a piede libero per danneggiamento, minacce e resistenza a pubblico ufficiale, ubriachezza, e violazione degli obblighi cui era sottoposto.<\/p>\n<p>Non ci sono feriti. Solamente un&#8217; auto dei carabinieri \u00e8 stata danneggiata, centrata da una pietra.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/30\/storie-di-ordinaria-follia-a-manduria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/05\/30\/storie-di-ordinaria-follia-a-manduria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)_____ Era affidato in prova ai servizi sociali. Beh, evidentemnte la prova \u00e8 andata proprio male. Scene da film dell&#8217; orrore ieri sera a Manduria, dove in una palazzina del centro, dal primo piano, un uomo di 57 anni, pregiudicato,\u00a0 ha preso a buttare su auto e passanti quello che gli capitava di avere in [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":137967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137966"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=137966"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137966\/revisions"}],"predecessor-version":[{"id":137971,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/137966\/revisions\/137971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/137967"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=137966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=137966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=137966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}