{"id":13850,"date":"2013-04-05T16:05:00","date_gmt":"2013-04-05T16:05:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=13850"},"modified":"2013-04-05T16:05:00","modified_gmt":"2013-04-05T16:05:00","slug":"armi-e-munizioni-sotterrate-in-giardino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/05\/armi-e-munizioni-sotterrate-in-giardino\/","title":{"rendered":"Armi e munizioni sotterrate in giardino"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/05\/armi-e-munizioni-sotterrate-in-giardino\/carabinieri-salice-s-3-apr-2013\/\" rel=\"attachment wp-att-13851\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-salice-s-3-apr-2013.jpg\" alt=\"\" width=\"645\" height=\"860\" class=\"alignleft size-full wp-image-13851\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-salice-s-3-apr-2013.jpg 645w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/carabinieri-salice-s-3-apr-2013-225x300.jpg 225w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/a>Salice Salentino. I Carabinieri del Nucleo Radiomobile della Compagnia di Campi Salentina, coadiuvati dai colleghi della Stazione di Salice Salentino e del Nucleo Carabinieri Cinofili di Bari, \u00a0hanno eseguito una perquisizione domiciliare nel centro abitato presso l\u2019immobile della famiglia di Antonio Mogavero ventinovenne del luogo gi\u00e0 noto e nella circostanza agli arresti domiciliari per reati in materia di stupefacenti. Una laboriosa attivit\u00e0 info-investigativa ha portato a sospettare che nel giardino di pertinenza dell\u2019immobile perquisito potessero trovarsi delle armi. Infatti, l\u2019unit\u00e0 cinofila\u00a0<em>antiesplosivo\u00a0<\/em>dopo aver ispezionato la zona ha iniziato a scavare in un determinato in un posto preciso del giardino, con l\u2019aiuto dei carabinieri presenti. Cos\u00ec, sotto quasi cinquanta centimetri di terra \u00e8 stata scoperta una valigetta. Al suo interno la sorpresa: due pistole, una Zastava 6.35 (fabbricazione Serba), matricola mai censita, quindi clandestina; una Beretta 7.65, matricola non abrasa, su cui sono in corso degli accertamenti. Insieme alle pistole sono state trovate 250 cartucce: 110 relative alla pistola serba e 140 all\u2019altra. Antonio Mogavero \u00e8 stato quindi dichiarato in arresto e, su disposizione del magistrato di turno, sottoposto ai domiciliari. Armi e munizioni sono state sequestrate e saranno sottoposta ad accertamenti tecnici presso il Reparto Investigazioni Scientifiche di Roma.<\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\">\u00a0<\/span><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/05\/armi-e-munizioni-sotterrate-in-giardino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/05\/armi-e-munizioni-sotterrate-in-giardino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Salice Salentino. I Carabinieri del Nucleo Radiomobile della Compagnia di Campi Salentina, coadiuvati dai colleghi della Stazione di Salice Salentino e del Nucleo Carabinieri Cinofili di Bari, \u00a0hanno eseguito una perquisizione domiciliare nel centro abitato presso l\u2019immobile della famiglia di Antonio Mogavero ventinovenne del luogo gi\u00e0 noto e nella circostanza agli arresti domiciliari per reati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13850"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=13850"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13850\/revisions"}],"predecessor-version":[{"id":13854,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/13850\/revisions\/13854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/13851"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=13850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=13850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=13850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}