{"id":139371,"date":"2018-06-19T04:21:04","date_gmt":"2018-06-19T02:21:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=139371"},"modified":"2018-06-19T11:48:53","modified_gmt":"2018-06-19T09:48:53","slug":"10-anni-fa-pietro-fanigliulo-ci-lasciava","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/19\/10-anni-fa-pietro-fanigliulo-ci-lasciava\/","title":{"rendered":"A DIECI ANNI DALLA MORTE \/ PIETRO FANIGLIULO, UN GRANDE ARTISTA SALENTINO, UN GRANDE UOMO"},"content":{"rendered":"<div id=\"attachment_139372\" style=\"width: 692px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-139372\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-139372\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/fanigliulo.jpg\" alt=\"\" width=\"682\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/fanigliulo.jpg 682w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/fanigliulo-205x300.jpg 205w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/><p id=\"caption-attachment-139372\" class=\"wp-caption-text\">dav<\/p><\/div>\n<p>mv______<\/p>\n<p>Dieci anni fa <strong>Pietro Fanigliulo<\/strong> ci lasciava.<strong><br \/>\n<\/strong>Pietro \u00e8 stato senza ombra di dubbio <strong>il pi\u00f9 grande incisore che ha operato nel Salento negli ultimi decenni.<\/strong><br \/>\nUna produzione artistica ricchissima, che \u00e8 sta realizzata in \u00a0oltre un quarantennio di ininterrotto lavoro.<br \/>\nNato a Grottaglie si trasfer\u00ec giovanissimo a Lecce, dove ha insegnato arti figurative sia alla Scuola d&#8217;Arte che al Liceo Artistico.<br \/>\nMa il suo insegnamento non finiva a scuola, molti di noi sono stai iniziati alla tecnica dell&#8217;acquaforte e dell&#8217;acquatinta, della litografia, nello studio di Pietro, ricordo quando nel 1975 \u00a0gli fui presentato dall&#8217;amico comune Antonio Nisi, aveva lo studio in via Vignes a due passi da piazza Sant&#8217;Oronzo.<br \/>\nMi ricordo che quando gli fui presentato mi disse:&#8221; vagli\u00f2 io ti conosco tu sei un pochino irrequieto, dovresti darti nna calmata&#8221;, una lunga e polemica discussione, da cui poi nacque una bellissima amicizia.<br \/>\nTempo dopo si trasfer\u00ec in via Cerrate Casale, una traversa di viale Taranto, dove tutti i pomeriggi lo si poteva trovare, e dove abbiamo passato ore e ore a discutere, o a sfotterci, soprattutto in quelle lunghe serate d&#8217;inverno.<br \/>\nPer noi pi\u00f9 giovani, lo studio, o se preferite il laboratorio di Pietro era un punto di riferimento, non solo perch\u00e9 in quel posto ci si confrontava su temi legati all&#8217;arte, e non solo, ma perch\u00e9 \u00a0era una persona amabile, che non ti faceva mai sentire a disagio, ti accoglieva sempre con un sorriso, anche quando nell&#8217;ultimo periodo della sua vita, pure era consapevole che stava combattendo una battaglia che difficilmente avrebbe vinto.<br \/>\nPer cui oltre che maestro d&#8217;arte Pietro in tante occasioni \u00e8 stato pure maestro di vita.<br \/>\nPietro \u00e8 vissuto, in un&#8217;epoca in cui internet, i social non c&#8217;erano ancora, e mi \u00e8 profondamente dispiaciuto, scoprire che in rete non ci sia nulla che parli di lui, che lo ricordi, per cui ci riproponiamo di poter in futuro \u00a0pubblicare qualcuno dei suoi lavori.<br \/>\nChi non \u00a0ha conosciuto Pietro Fanigliulo di persona, magari lo ricorda attraverso le sue opere, i suoi quadri, le sue incisioni, notevoli erano i sui \u00a0girasoli, \u00a0gli ulivi, i ritratti.<br \/>\nChi invece ha avuto la fortuna di frequentarlo non pu\u00f2 che ricordarlo per quel suo sorriso aperto, per la sua grande generosit\u00e0, che si manifestava anche nell&#8217;essere prodigo di consigli con chi si approcciava all&#8217;arte del &#8220;torchio&#8221;,\u00a0senza tenere per se i segreti di cui si era appropriato in anni di sperimentazione.<br \/>\nNoi oggi lo vogliamo ricordare con le parole con le quali i suoi figli lo salutarono dieci anni fa, perch\u00e9 a mio avviso danno un quadro preciso dell&#8217;uomo,<br \/>\n<em><strong>&#8220;Nostro padre ha dedicato la sua vita a studiare, ammirare, insegnare e dipingere capolavori, ma non era consapevole che, per noi, era e sar\u00e0 lui il pi\u00f9 bel capolavoro.&#8221;<\/strong><\/em><br \/>\nCredo che parole, non solo pi\u00f9 belle, ma pi\u00f9 appropriate i figli di Pietro non avrebbero potuto trovare per ricordarlo e per ricordarcelo.<\/p>\n<p>(Il Cavaliere)<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/19\/10-anni-fa-pietro-fanigliulo-ci-lasciava\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/19\/10-anni-fa-pietro-fanigliulo-ci-lasciava\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>mv______ Dieci anni fa Pietro Fanigliulo ci lasciava. Pietro \u00e8 stato senza ombra di dubbio il pi\u00f9 grande incisore che ha operato nel Salento negli ultimi decenni. Una produzione artistica ricchissima, che \u00e8 sta realizzata in \u00a0oltre un quarantennio di ininterrotto lavoro. Nato a Grottaglie si trasfer\u00ec giovanissimo a Lecce, dove ha insegnato arti figurative [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139371"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=139371"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139371\/revisions"}],"predecessor-version":[{"id":139387,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139371\/revisions\/139387"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=139371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=139371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=139371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}