{"id":139733,"date":"2018-06-26T09:32:56","date_gmt":"2018-06-26T07:32:56","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=139733"},"modified":"2018-06-26T10:03:10","modified_gmt":"2018-06-26T08:03:10","slug":"stage-di-aikido-e-dintorni-tre-giorni-di-energia-e-di-allegria","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/stage-di-aikido-e-dintorni-tre-giorni-di-energia-e-di-allegria\/","title":{"rendered":"STAGE DI AIKIDO E DINTORNI. TRE GIORNI DI ENERGIA E DI ALLEGRIA &#8211; foto gallery"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139747\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/1-3.jpg\" alt=\"\" width=\"1500\" height=\"1005\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/1-3.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/1-3-300x201.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/1-3-1024x686.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/1-3-768x515.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139748\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5861.jpg\" alt=\"\" width=\"1500\" height=\"1140\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5861.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5861-300x228.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5861-1024x778.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5861-768x584.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139749\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5862.jpg\" alt=\"\" width=\"1500\" height=\"1031\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5862.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5862-300x206.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5862-1024x704.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5862-768x528.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139750\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5863.jpg\" alt=\"\" width=\"1157\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5863.jpg 1157w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5863-231x300.jpg 231w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5863-790x1024.jpg 790w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5863-768x996.jpg 768w\" sizes=\"(max-width: 1157px) 100vw, 1157px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139751\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5864.jpg\" alt=\"\" width=\"1000\" height=\"664\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5864.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5864-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5864-768x510.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139752\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5865.jpg\" alt=\"\" width=\"1500\" height=\"875\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5865.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5865-300x175.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5865-1024x597.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5865-768x448.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139753\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5866.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5866.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5866-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5866-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5866-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139754\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5867.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5867.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5867-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5867-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5867-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139755\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5869.jpg\" alt=\"\" width=\"1500\" height=\"841\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5869.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5869-300x168.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5869-1024x574.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5869-768x431.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139756\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5870.jpg\" alt=\"\" width=\"1500\" height=\"853\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5870.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5870-300x171.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5870-1024x582.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5870-768x437.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139757\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5873.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5873.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5873-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5873-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5873-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139758\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5875.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5875.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5875-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5875-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5875-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139759\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5878.jpg\" alt=\"\" width=\"1500\" height=\"944\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5878.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5878-300x189.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5878-1024x644.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5878-768x483.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139760\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5880.jpg\" alt=\"\" width=\"1429\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5880.jpg 1429w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5880-286x300.jpg 286w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5880-976x1024.jpg 976w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5880-768x806.jpg 768w\" sizes=\"(max-width: 1429px) 100vw, 1429px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139761\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5889.jpg\" alt=\"\" width=\"1500\" height=\"1065\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5889.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5889-300x213.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5889-1024x727.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5889-768x545.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139762\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5894.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5894.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5894-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5894-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5894-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139763\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5895a.jpg\" alt=\"\" width=\"1500\" height=\"1005\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5895a.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5895a-300x201.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5895a-1024x686.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5895a-768x515.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139764\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5896.jpg\" alt=\"\" width=\"1500\" height=\"1112\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5896.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5896-300x222.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5896-1024x759.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5896-768x569.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139765\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5897.jpg\" alt=\"\" width=\"1500\" height=\"945\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5897.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5897-300x189.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5897-1024x645.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5897-768x484.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139766\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5898.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5898.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5898-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5898-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5898-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139767\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5899.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5899.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5899-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5899-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5899-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139768\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5905.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5905.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5905-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5905-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5905-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139769\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5906.jpg\" alt=\"\" width=\"1500\" height=\"955\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5906.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5906-300x191.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5906-1024x652.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5906-768x489.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139770\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5907.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5907.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5907-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5907-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5907-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139771\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5908.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5908.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5908-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5908-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5908-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139772\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5909.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5909.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5909-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5909-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5909-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139773\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5910.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5910.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5910-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5910-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5910-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139774\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5915.jpg\" alt=\"\" width=\"1028\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5915.jpg 1028w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5915-206x300.jpg 206w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5915-702x1024.jpg 702w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5915-768x1121.jpg 768w\" sizes=\"(max-width: 1028px) 100vw, 1028px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139775\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5918.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5918.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5918-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5918-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5918-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139776\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5919.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5919.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5919-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5919-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5919-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139777\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5922.jpg\" alt=\"\" width=\"1500\" height=\"960\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5922.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5922-300x192.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5922-1024x655.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5922-768x492.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139778\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5923.jpg\" alt=\"\" width=\"1059\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5923.jpg 1059w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5923-212x300.jpg 212w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5923-723x1024.jpg 723w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5923-768x1088.jpg 768w\" sizes=\"(max-width: 1059px) 100vw, 1059px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139779\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5924.jpg\" alt=\"\" width=\"1500\" height=\"984\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5924.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5924-300x197.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5924-1024x672.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5924-768x504.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139780\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5925.jpg\" alt=\"\" width=\"1124\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5925.jpg 1124w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5925-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5925-767x1024.jpg 767w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5925-768x1025.jpg 768w\" sizes=\"(max-width: 1124px) 100vw, 1124px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139781\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5926.jpg\" alt=\"\" width=\"1500\" height=\"1074\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5926.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5926-300x215.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5926-1024x733.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5926-768x550.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139782\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5927.jpg\" alt=\"\" width=\"1258\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5927.jpg 1258w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5927-252x300.jpg 252w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5927-859x1024.jpg 859w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5927-768x916.jpg 768w\" sizes=\"(max-width: 1258px) 100vw, 1258px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139783\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5928.jpg\" alt=\"\" width=\"1053\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5928.jpg 1053w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5928-211x300.jpg 211w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5928-719x1024.jpg 719w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5928-768x1094.jpg 768w\" sizes=\"(max-width: 1053px) 100vw, 1053px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139784\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5929.jpg\" alt=\"\" width=\"1000\" height=\"776\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5929.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5929-300x233.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5929-768x596.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139785\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5931.jpg\" alt=\"\" width=\"997\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5931.jpg 997w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5931-199x300.jpg 199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5931-681x1024.jpg 681w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5931-768x1155.jpg 768w\" sizes=\"(max-width: 997px) 100vw, 997px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139786\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5932.jpg\" alt=\"\" width=\"1006\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5932.jpg 1006w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5932-201x300.jpg 201w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5932-687x1024.jpg 687w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5932-768x1145.jpg 768w\" sizes=\"(max-width: 1006px) 100vw, 1006px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139787\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5933.jpg\" alt=\"\" width=\"1500\" height=\"822\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5933.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5933-300x164.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5933-1024x561.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5933-768x421.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139788\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5935.jpg\" alt=\"\" width=\"853\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5935.jpg 853w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5935-256x300.jpg 256w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5935-768x900.jpg 768w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139789\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5936.jpg\" alt=\"\" width=\"1162\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5936.jpg 1162w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5936-232x300.jpg 232w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5936-793x1024.jpg 793w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5936-768x991.jpg 768w\" sizes=\"(max-width: 1162px) 100vw, 1162px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139790\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5937.jpg\" alt=\"\" width=\"1500\" height=\"1135\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5937.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5937-300x227.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5937-1024x775.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5937-768x581.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139791\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5939.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5939.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5939-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5939-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5939-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139792\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5941.jpg\" alt=\"\" width=\"1500\" height=\"940\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5941.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5941-300x188.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5941-1024x642.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5941-768x481.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139793\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5944.jpg\" alt=\"\" width=\"1500\" height=\"1022\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5944.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5944-300x204.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5944-1024x698.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5944-768x523.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139794\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5945.jpg\" alt=\"\" width=\"1220\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5945.jpg 1220w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5945-244x300.jpg 244w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5945-833x1024.jpg 833w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5945-768x944.jpg 768w\" sizes=\"(max-width: 1220px) 100vw, 1220px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139795\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5947.jpg\" alt=\"\" width=\"1248\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5947.jpg 1248w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5947-250x300.jpg 250w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5947-852x1024.jpg 852w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5947-768x923.jpg 768w\" sizes=\"(max-width: 1248px) 100vw, 1248px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139796\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5951.jpg\" alt=\"\" width=\"1500\" height=\"881\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5951.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5951-300x176.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5951-1024x601.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5951-768x451.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139797\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5952.jpg\" alt=\"\" width=\"1500\" height=\"1307\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5952.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5952-300x261.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5952-1024x892.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5952-768x669.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139798\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5953.jpg\" alt=\"\" width=\"1104\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5953.jpg 1104w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5953-221x300.jpg 221w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5953-754x1024.jpg 754w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5953-768x1043.jpg 768w\" sizes=\"(max-width: 1104px) 100vw, 1104px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139799\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5954.jpg\" alt=\"\" width=\"1500\" height=\"1005\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5954.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5954-300x201.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5954-1024x686.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5954-768x515.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139800\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5955.jpg\" alt=\"\" width=\"1165\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5955.jpg 1165w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5955-233x300.jpg 233w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5955-795x1024.jpg 795w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5955-768x989.jpg 768w\" sizes=\"(max-width: 1165px) 100vw, 1165px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139801\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5957.jpg\" alt=\"\" width=\"1099\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5957.jpg 1099w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5957-220x300.jpg 220w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5957-750x1024.jpg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5957-768x1048.jpg 768w\" sizes=\"(max-width: 1099px) 100vw, 1099px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139802\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5959.jpg\" alt=\"\" width=\"1500\" height=\"1022\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5959.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5959-300x204.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5959-1024x698.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5959-768x523.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139803\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5960.jpg\" alt=\"\" width=\"1091\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5960.jpg 1091w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5960-218x300.jpg 218w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5960-745x1024.jpg 745w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5960-768x1056.jpg 768w\" sizes=\"(max-width: 1091px) 100vw, 1091px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139804\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5962.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5962.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5962-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5962-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139805\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5964.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5964.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5964-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5964-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5964-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139806\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5966.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5966.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5966-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5966-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5966-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139807\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5968.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5968.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5968-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5968-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5968-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139808\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5969.jpg\" alt=\"\" width=\"1500\" height=\"945\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5969.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5969-300x189.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5969-1024x645.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5969-768x484.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139809\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5970.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5970.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5970-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5970-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5970-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139810\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139811\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971a.jpg\" alt=\"\" width=\"1453\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971a.jpg 1453w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971a-291x300.jpg 291w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971a-992x1024.jpg 992w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5971a-768x793.jpg 768w\" sizes=\"(max-width: 1453px) 100vw, 1453px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139812\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5972.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5972.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5972-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5972-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5972-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139813\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5974.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5974.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5974-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5974-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5974-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139814\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5975.jpg\" alt=\"\" width=\"1500\" height=\"938\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5975.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5975-300x188.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5975-1024x640.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5975-768x480.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139815\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5976.jpg\" alt=\"\" width=\"1500\" height=\"914\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5976.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5976-300x183.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5976-1024x624.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5976-768x468.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139816\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5977.jpg\" alt=\"\" width=\"1000\" height=\"768\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5977.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5977-300x230.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5977-768x590.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139817\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5978.jpg\" alt=\"\" width=\"955\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5978.jpg 955w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5978-287x300.jpg 287w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5978-768x804.jpg 768w\" sizes=\"(max-width: 955px) 100vw, 955px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139818\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979.jpg\" alt=\"\" width=\"1500\" height=\"948\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979-300x190.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979-1024x647.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979-768x485.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139819\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979web.jpg\" alt=\"\" width=\"1500\" height=\"1079\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979web.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979web-300x216.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979web-1024x737.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5979web-768x552.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139820\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5980.jpg\" alt=\"\" width=\"1300\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5980.jpg 1300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5980-260x300.jpg 260w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5980-887x1024.jpg 887w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5980-768x886.jpg 768w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139821\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5981.jpg\" alt=\"\" width=\"1500\" height=\"1064\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5981.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5981-300x213.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5981-1024x726.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5981-768x545.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139822\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5982.jpg\" alt=\"\" width=\"1304\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5982.jpg 1304w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5982-261x300.jpg 261w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5982-890x1024.jpg 890w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5982-768x883.jpg 768w\" sizes=\"(max-width: 1304px) 100vw, 1304px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139823\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5984.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5984.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5984-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5984-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5984-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139824\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5987.jpg\" alt=\"\" width=\"1500\" height=\"1263\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5987.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5987-300x253.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5987-1024x862.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5987-768x647.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139825\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5990.jpg\" alt=\"\" width=\"1500\" height=\"1006\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5990.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5990-300x201.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5990-1024x687.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5990-768x515.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139826\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5992.jpg\" alt=\"\" width=\"1051\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5992.jpg 1051w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5992-210x300.jpg 210w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5992-717x1024.jpg 717w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5992-768x1096.jpg 768w\" sizes=\"(max-width: 1051px) 100vw, 1051px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139827\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5993.jpg\" alt=\"\" width=\"1156\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5993.jpg 1156w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5993-231x300.jpg 231w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5993-789x1024.jpg 789w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5993-768x997.jpg 768w\" sizes=\"(max-width: 1156px) 100vw, 1156px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139828\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5995.jpg\" alt=\"\" width=\"1209\" height=\"1500\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5995.jpg 1209w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5995-242x300.jpg 242w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5995-825x1024.jpg 825w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5995-768x953.jpg 768w\" sizes=\"(max-width: 1209px) 100vw, 1209px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139829\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5996.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5996.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5996-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5996-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5996-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139830\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5997.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5997.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5997-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5997-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5997-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139831\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5998.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5998.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5998-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5998-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5998-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139832\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6004.jpg\" alt=\"\" width=\"1500\" height=\"829\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6004.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6004-300x166.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6004-1024x566.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6004-768x424.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139833\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6008.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6008.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6008-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6008-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6008-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139834\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6010.jpg\" alt=\"\" width=\"1500\" height=\"768\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6010.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6010-300x154.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6010-1024x524.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6010-768x393.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139835\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6013.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6013.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6013-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6013-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139836\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6017.jpg\" alt=\"\" width=\"1000\" height=\"753\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6017.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6017-300x226.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6017-768x578.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6017-400x300.jpg 400w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139837\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6018.jpg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6018.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6018-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6018-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139838\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6019.jpg\" alt=\"\" width=\"1500\" height=\"983\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6019.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6019-300x197.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6019-1024x671.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6019-768x503.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139839\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6020.jpg\" alt=\"\" width=\"1500\" height=\"812\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6020.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6020-300x162.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6020-1024x554.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/6020-768x416.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>a cura di Valerio Melcore_____Uno stage di aikido, di tre giorni \u00a0per \u00a0avere la possibilit\u00e0 di approfondire alcuni aspetti, che in palestra durante l&#8217;anno \u00e8 difficile trattare con la dovuta attenzione, mi riferisco sopratutto \u00a0alla meditazione e all&#8217;utilizzo \u00a0di quella energia sottile che i giapponesi chiamano Ki, i cinesi Chi, gli indiani Prana, e che per chi pratica nell&#8217;Aikikai d&#8217;Italia sotto la direzione del Maestro Hiroshi Tada, sono definiti esercizi di Kinorenma.<br \/>\nQuesto era il programma che \u00a0contavo di sviluppare quando il Maestro Antonio Giacoia, \u00a0ci aveva invitati, e che come dojo Il Cavaliere avevamo di buon grado accettato.<br \/>\nSi trattava di tenere uno stage di Aikido all&#8217;interno di una manifestazione nazionale di Arti Marziali, che il Maestro Cosimo Cavallo decano delle Scuole joniche di Karate, ogni anno organizza.<br \/>\nQuest&#8217;anno lo stage si sarebbe tenuto a Torre Ovo a pochi chilometri da Porto Cesareo, proseguendo sulla strada per la marina di San Pietro in Bevagna. Insomma al confine tra la provincia di Lecce e di Taranto.<br \/>\nAd onor del vero, negli anni scorsi pi\u00f9 volte il responsabile della Scuola di Kendo, il Maestro Dino Schiavone, ci aveva invitato a partecipare all&#8217;evento, tanto che i nostri ripetuti no, potevano apparire come \u00a0una mancanza di riguardo nei confronti di un amico tanto garbato e gentile.<br \/>\nPertanto quest&#8217;anno libero da impegni contavo non solo di organizzare lo stage all&#8217;interno della cornice del Villaggio Eden a Torre Ovo, ma anche di poter incontrare e praticare col Maestro Schiavone, il quale invece era assente a \u00a0causa di un altro raduno organizzato dalla federazione di Kendo.<br \/>\nConvinto quindi che lo stage di Aikido lo avremmo tenuto io ed il Maestro Giacoia avevo preannunciato ai miei allievi, le lezioni ed i temi che avrei trattato, non solo, ma come sono solito fare in occasione degli stage che si tengono in zona, \u00a0ho fatto tappezzare Lecce e dintorni di mega manifesti.<br \/>\nLe cose invece sono andate diversamente, ed abbiamo avuto la fortuna di conoscere una serie di bravissimi insegnanti, venuti da diverse parti d&#8217;Italia, con i quali ci siamo potuti confrontare. Scuole di Aikido differenti, diversi i maestri, i programmi e persino i rituali ed il saluto.<br \/>\nUn&#8217;esperienza insolita ed esaltante al tempo stesso.<br \/>\nOgnuno con il suo stile, col suo bagaglio culturale, con la sua esperienza ultratrentennale di pratica e di studio, questo incontro e confronto ci ha arricchito, tutti noi abbiamo portato a casa qualcosa.<br \/>\nDomani ognuno di noi torner\u00e0 nella propria scuola, nel proprio dojo, ad allenarsi come ha sempre fatto seguendo gli insegnamenti del maestro che ha deciso di seguire, ma con la consapevolezza che nessuno \u00e8 depositario della verit\u00e0, del vero Aikido, \u00a0ma certamente quel confronto ci aiuter\u00e0 a fare meglio, con l&#8217;umilt\u00e0 che dovrebbe sempre contraddistinguere chi pratica quest&#8217;arte, sapendo che l&#8217;Aikido \u00e8 l&#8217;arte della perfezione, e per quanti anni e per quante vite dovessimo vivere, non potremmo mai raggiungerla.<br \/>\nVoglio ringraziare oltre al Maestro Antonio Giacoia responsabile del dojo Aikido ASD di Taranto, il Maestro Antonio Morgano responsabile della scuola di Aikido e Ju Jutsu di Enna, che oltre alla sua bravura ci ha portato una ventata di sicilianit\u00e0, alla Maestra Lucia responsabile del dojo di Castellana, a Ciro Valvo , al Maestro di Iaido e a tutti gli altri insegnanti che erano presenti.<\/p>\n<p>Un ringraziamento particolare agli amici del dojo il Cavaliere, a cominciare dal Maestro Antonio Cannone, Mario De Blasi, alla neo cintura nera Giuseppe Miglietta, a Massimo D&#8217;Amico, a Tania che ci ha raggiunto con al seguito marito e figlio, e poi l&#8217;amico di sempre del nostro dojo, Marco Rollo e naturalmente non possiamo dimenticare il nostro uke preferito, \u00a0Giuliano Melcore.<img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139840\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796.jpg\" alt=\"\" width=\"1500\" height=\"694\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796-300x139.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796-1024x474.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796-768x355.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796-630x290.jpg 630w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5796-315x145.jpg 315w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139841\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5797.jpg\" alt=\"\" width=\"1500\" height=\"942\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5797.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5797-300x188.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5797-1024x643.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5797-768x482.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139842\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5798.jpg\" alt=\"\" width=\"1500\" height=\"1391\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5798.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5798-300x278.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5798-1024x950.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5798-768x712.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139843\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5801.jpg\" alt=\"\" width=\"1500\" height=\"1055\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5801.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5801-300x211.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5801-1024x720.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5801-768x540.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139844\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5802.jpg\" alt=\"\" width=\"1500\" height=\"1268\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5802.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5802-300x254.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5802-1024x866.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5802-768x649.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139845\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5803.jpg\" alt=\"\" width=\"1500\" height=\"926\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5803.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5803-300x185.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5803-1024x632.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5803-768x474.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139846\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5805.jpg\" alt=\"\" width=\"1500\" height=\"1158\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5805.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5805-300x232.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5805-1024x791.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5805-768x593.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139847\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5816.jpg\" alt=\"\" width=\"1500\" height=\"668\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5816.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5816-300x134.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5816-1024x456.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5816-768x342.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139848\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5818.jpg\" alt=\"\" width=\"1500\" height=\"1277\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5818.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5818-300x255.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5818-1024x872.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5818-768x654.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139849\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5820.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5820.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5820-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5820-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5820-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139850\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5824.jpg\" alt=\"\" width=\"1500\" height=\"718\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5824.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5824-300x144.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5824-1024x490.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5824-768x368.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139851\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5827.jpg\" alt=\"\" width=\"1500\" height=\"731\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5827.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5827-300x146.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5827-1024x499.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5827-768x374.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139852\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5828.jpg\" alt=\"\" width=\"1500\" height=\"739\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5828.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5828-300x148.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5828-1024x504.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5828-768x378.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139853\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5832.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5832.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5832-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5832-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5832-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139854\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5833.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5833.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5833-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5833-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5833-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139855\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5834.jpg\" alt=\"\" width=\"1500\" height=\"679\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5834.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5834-300x136.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5834-1024x464.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5834-768x348.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139856\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5835.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5835.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5835-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5835-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5835-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139857\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5836.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5836.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5836-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5836-1024x683.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5836-768x512.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139858\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839.jpg\" alt=\"\" width=\"2000\" height=\"460\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839-300x69.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839-1024x236.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839-768x177.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5839-1536x353.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139859\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5840.jpg\" alt=\"\" width=\"1500\" height=\"768\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5840.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5840-300x154.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5840-1024x524.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5840-768x393.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139860\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843.jpg\" alt=\"\" width=\"2000\" height=\"738\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843-300x111.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843-1024x378.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843-768x283.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5843-1536x567.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139861\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5844.jpg\" alt=\"\" width=\"1500\" height=\"522\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5844.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5844-300x104.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5844-1024x356.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5844-768x267.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139862\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845.jpg\" alt=\"\" width=\"2000\" height=\"713\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845-300x107.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845-1024x365.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845-768x274.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5845-1536x548.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139863\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846.jpg\" alt=\"\" width=\"2000\" height=\"454\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846-300x68.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846-1024x232.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846-768x174.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5846-1536x349.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139864\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847.jpg\" alt=\"\" width=\"2000\" height=\"654\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847-300x98.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847-1024x335.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847-768x251.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5847-1536x502.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139865\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849.jpg\" alt=\"\" width=\"2000\" height=\"736\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849-300x110.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849-1024x377.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849-768x283.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5849-1536x565.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139866\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5850.jpg\" alt=\"\" width=\"1500\" height=\"639\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5850.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5850-300x128.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5850-1024x436.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5850-768x327.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139867\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5851.jpg\" alt=\"\" width=\"1500\" height=\"664\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5851.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5851-300x133.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5851-1024x453.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5851-768x340.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139868\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5855.jpg\" alt=\"\" width=\"1500\" height=\"996\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5855.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5855-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5855-1024x680.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5855-768x510.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139869\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856.jpg\" alt=\"\" width=\"2000\" height=\"1064\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856.jpg 2000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856-300x160.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856-1024x545.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856-768x409.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5856-1536x817.jpg 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139870\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5858.jpg\" alt=\"\" width=\"1500\" height=\"837\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5858.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5858-300x167.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5858-1024x571.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5858-768x429.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139871\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5859.jpg\" alt=\"\" width=\"1500\" height=\"891\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5859.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5859-300x178.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5859-1024x608.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5859-768x456.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/> <img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139872\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5860.jpg\" alt=\"\" width=\"1500\" height=\"817\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5860.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5860-300x163.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5860-1024x558.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/5860-768x418.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139880\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/aikido-dojo-il-cavaliere-lecce-melcore.jpg\" alt=\"\" width=\"1500\" height=\"1097\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/aikido-dojo-il-cavaliere-lecce-melcore.jpg 1500w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/aikido-dojo-il-cavaliere-lecce-melcore-300x219.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/aikido-dojo-il-cavaliere-lecce-melcore-1024x749.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/aikido-dojo-il-cavaliere-lecce-melcore-768x562.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>Un ringraziamento a tutti gli allievi delle altre scuole con i quali in questi tre giorni ci siamo &#8221; scambiati&#8221; energia positiva.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/stage-di-aikido-e-dintorni-tre-giorni-di-energia-e-di-allegria\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/stage-di-aikido-e-dintorni-tre-giorni-di-energia-e-di-allegria\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>a cura di Valerio Melcore_____Uno stage di aikido, di tre giorni \u00a0per \u00a0avere la possibilit\u00e0 di approfondire alcuni aspetti, che in palestra durante l&#8217;anno \u00e8 difficile trattare con la dovuta attenzione, mi riferisco sopratutto \u00a0alla meditazione e all&#8217;utilizzo \u00a0di quella energia sottile che i giapponesi chiamano Ki, i cinesi Chi, gli indiani Prana, e che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139733"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=139733"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139733\/revisions"}],"predecessor-version":[{"id":139881,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139733\/revisions\/139881"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=139733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=139733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=139733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}