{"id":139904,"date":"2018-06-26T16:56:53","date_gmt":"2018-06-26T14:56:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=139904"},"modified":"2018-06-26T17:46:38","modified_gmt":"2018-06-26T15:46:38","slug":"il-professor-ippazio-luceri-in-lotta-contro-la-tap-in-grecia-detenuto-dalla-polizia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/il-professor-ippazio-luceri-in-lotta-contro-la-tap-in-grecia-detenuto-dalla-polizia\/","title":{"rendered":"IL PROFESSOR IPPAZIO LUCERI IN LOTTA CONTRO LA TAP IN GRECIA DETENUTO DALLA POLIZIA DA VENTIQUATTRO ORE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-139905\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati.jpg\" alt=\"\" width=\"960\" height=\"960\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati-768x768.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/pati-60x60.jpg 60w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(e.l.)______Il professor Ippazio Luceri, detto Pati (nella foto), 66 anni, di Martano, \u00e8 stato fermato ieri in Grecia, a Kavala, mentre prendeva parte ad una protesta contro la costruzione del gasdotto Tap, nella piana di Filippi, area ad alta valenza storica, archeologica, agricola e naturalistica, insieme ad attivsti greci. Portato in caserma anche\u00a0il presidente della Camera agricola di Kavala, Themis Kalpaskides. Sono in sciopero della fame, in attesa di essere sentiti da un magistrato.<\/p>\n<p>L&#8217; ultimo messaggio sui social di Ippazio Luceri \u00e8 di ieri mattin presto:<em> &#8220;Dal Presidio NO TAP di KAVALLA a quello di San FOCA (Lecce)\u00a0La LOTTA E&#8217; UNA SOLA !\u00a0NE&#8217; a San Foca NE&#8217; a KAVALLA: UNITI SI VINCE !&#8221;.<\/em><\/p>\n<p><em>&#8220;Questa \u00e8 la democratica Grecia asservita al volere delle multinazionali criminali.<\/em><br \/>\n<em> Questo \u00e8 il sistema estrattivista che calpesta la volont\u00e0 e la dignit\u00e0 delle popolazioni per garantirsi lo sfruttamento di risorse e arricchire le tasche di pochi a discapito delle comunit\u00e0<\/em>&#8220;, ha commentato su Facebook il leader dei No Tap salentini Gianluca Maggiore.<\/p>\n<p><em>&#8220;Il prof. PATI Luceri \u00e8 un esempio di dignit\u00e0, di democrazia, di forza e generosit\u00e0. Protestare PACIFICAMENTE, a mani nude e braccia alzate, non \u00e8 mai pericoloso n\u00e8 sovversivo. Solidariet\u00e0 e vicinanza a Pati, attivista No Tap da sempre.<\/em><br \/>\n<em>Chiedo a nome di tutta la mia comunit\u00e0, Melendugno e di tutti i Sindaci NoTap del Salento (Puglia, Italia, Europa), la liberazione immediata di Pati e degli altri attivisti, fermati perch\u00e9 manifestavano contro un\u2019opera inutile, dannosa e pericolosa come il gasdotto TAP, simbolo di speculazione finanziaria di pochi ai danni di molti! Le Istituzioni repubblicane Italiane, il Governo e l\u2019Ambasciatore italiano in Grecia si attivino presto per restituire Pati e gli altri alla libert\u00e0 ed alla democrazia&#8221;,<\/em> ha dichiarato il sindaco di Melendugno Marco Pot\u00ec.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/il-professor-ippazio-luceri-in-lotta-contro-la-tap-in-grecia-detenuto-dalla-polizia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/26\/il-professor-ippazio-luceri-in-lotta-contro-la-tap-in-grecia-detenuto-dalla-polizia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Il professor Ippazio Luceri, detto Pati (nella foto), 66 anni, di Martano, \u00e8 stato fermato ieri in Grecia, a Kavala, mentre prendeva parte ad una protesta contro la costruzione del gasdotto Tap, nella piana di Filippi, area ad alta valenza storica, archeologica, agricola e naturalistica, insieme ad attivsti greci. Portato in caserma anche\u00a0il presidente della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":139905,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139904"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=139904"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139904\/revisions"}],"predecessor-version":[{"id":139910,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/139904\/revisions\/139910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/139905"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=139904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=139904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=139904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}