{"id":14007,"date":"2013-04-09T07:20:14","date_gmt":"2013-04-09T07:20:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14007"},"modified":"2013-04-09T07:20:14","modified_gmt":"2013-04-09T07:20:14","slug":"paesaggi-e-archeologie-un-week-end-con-10-proposte-imperdibili-con-gli-esperti-di-aiapp-puglia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/paesaggi-e-archeologie-un-week-end-con-10-proposte-imperdibili-con-gli-esperti-di-aiapp-puglia\/","title":{"rendered":"\u201cPAESAGGI E ARCHEOLOGIE\u201d:  UN WEEK-END CON 10 PROPOSTE IMPERDIBILI  CON GLI ESPERTI DI AIAPP PUGLIA"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><span style=\"text-decoration: underline\">Domani, marted\u00ec 9 aprile, alle ore 12, a Palazzo Adorno, a Lecce<\/span>, si terr\u00e0 la conferenza stampa di presentazione di <strong>\u201cGiardini e Paesaggi Aperti- Paesaggi e Archeologie\u201d,<\/strong> la manifestazione nazionale che nel week-end del 13 e 14 aprile approda in cento siti di interesse architettonico e paesaggistico e che coinvolger\u00e0 anche la Puglia, e il Salento in particolare, proponendo ai visitatori una lettura inconsueta di spazi e luoghi con l\u2019aiuto di archeologi, storici, botanici.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019iniziativa sul territorio regionale \u00e8 promossa dall\u2019Aiapp- Associazione italiana di architettura del paesaggio-Sezione Puglia che, inserendosi nell\u2019evento nazionale, realizza <strong>10 percorsi<\/strong> sul tema che vanno dall\u2019archeologia industriale della produzione ai ritrovamento archeologici e botanici, passando per l\u2019archeologia delle infrastrutture ferroviarie. La manifestazione pugliese viene realizzata grazie alla collaborazione di numerose associazioni ed enti, tra i quali la Provincia di Lecce.<\/p>\n<p>&nbsp;<\/p>\n<p>I soci Aiapp, insieme ad architetti, agronomi e archeologi, offriranno ai visitatori un ricco programma di eventi che spazieranno nel Salento, in provincia di Brindisi e di Taranto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ad illustrarli interverranno il presidente della Provincia di Lecce <strong>Antonio Gabellone<\/strong>, il direttore generale della Provincia <strong>Giovanni Refolo<\/strong>, insieme alla presidente Aiapp Puglia <strong>Tiziana Lettere<\/strong> e al segretario <strong>Francesco Tarantino<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/paesaggi-e-archeologie-un-week-end-con-10-proposte-imperdibili-con-gli-esperti-di-aiapp-puglia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/09\/paesaggi-e-archeologie-un-week-end-con-10-proposte-imperdibili-con-gli-esperti-di-aiapp-puglia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Domani, marted\u00ec 9 aprile, alle ore 12, a Palazzo Adorno, a Lecce, si terr\u00e0 la conferenza stampa di presentazione di \u201cGiardini e Paesaggi Aperti- Paesaggi e Archeologie\u201d, la manifestazione nazionale che nel week-end del 13 e 14 aprile approda in cento siti di interesse architettonico e paesaggistico e che coinvolger\u00e0 anche la Puglia, e il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14007"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14007"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14007\/revisions"}],"predecessor-version":[{"id":14008,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14007\/revisions\/14008"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}