{"id":140080,"date":"2018-06-29T14:52:57","date_gmt":"2018-06-29T12:52:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=140080"},"modified":"2018-06-29T14:54:07","modified_gmt":"2018-06-29T12:54:07","slug":"la-spietata-mala-foggiana-torna-a-uccidere-muore-giovane-di-casarano-che-si-trovava-in-compagnia-di-un-pregiudicato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/29\/la-spietata-mala-foggiana-torna-a-uccidere-muore-giovane-di-casarano-che-si-trovava-in-compagnia-di-un-pregiudicato\/","title":{"rendered":"LA SPIETATA MALA FOGGIANA TORNA A UCCIDERE, MUORE GIOVANE DI CASARANO CHE SI TROVAVA IN AUTO IN COMPAGNIA DI UN PREGIUDICATO DEL POSTO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-140081\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/FORSE.jpg\" alt=\"\" width=\"1000\" height=\"484\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/FORSE.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/FORSE-300x145.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/06\/FORSE-768x372.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>(e.l.)______La criminalit\u00e0 organizzata foggiana torna a uccidere senza piet\u00e0. C&#8217;\u00e8 stato un agguato questa notte in via Forcella, anonima e isolata periferia della citt\u00e0 (nella foto). E&#8217; morto un giovane di 32 anni, Antonio Luigi De Rocco, di Casarano.<\/p>\n<p>Era in auto in compagnia di altre due persone, rimaste illese. I sicari, giunti all&#8217; improvviso nel buio, hanno sparato diversi colpi di fucile a canne mozze, prima di fuggire, senza lasciare tracce.<\/p>\n<p>Per il salentino, colpito alla schiena, non c&#8217;\u00e8 stato nulla da fare: quando sono arrivati i sanitari del 118 lo hanno trovato gi\u00e0 senza vita.<\/p>\n<p>I Carabinieri hanno avviato subito le indagini partendo proprio dall&#8217; interrogatorio dei due scampati miracolosamente all&#8217; agguato.<\/p>\n<p>Questa mattina gli inquirenti hanno avanzato l&#8217; ipotesi\u00a0 per cui la vittima sia stata uccisa per errore: il vero obiettivo sarebbe stato invece uno degli altri due, Bruno Carella, pregiudicato, che si trovava con il figlio ventenne sulla Peugeot 307 crivellata di colpi. Nove mesi fa era scampato ad un altro agguato, tesogli sotto casa, mentre si allontanava in auto, sempre in compagnia del figlio.<\/p>\n<p>Le indagini comunque sono in pieno svolgimento e, fra le altre cose, dovranno stabilire come mai il giovane di Casarano si trovasse in compagnia della coppia foggiana padre-figlio.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/29\/la-spietata-mala-foggiana-torna-a-uccidere-muore-giovane-di-casarano-che-si-trovava-in-compagnia-di-un-pregiudicato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/06\/29\/la-spietata-mala-foggiana-torna-a-uccidere-muore-giovane-di-casarano-che-si-trovava-in-compagnia-di-un-pregiudicato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______La criminalit\u00e0 organizzata foggiana torna a uccidere senza piet\u00e0. C&#8217;\u00e8 stato un agguato questa notte in via Forcella, anonima e isolata periferia della citt\u00e0 (nella foto). E&#8217; morto un giovane di 32 anni, Antonio Luigi De Rocco, di Casarano. Era in auto in compagnia di altre due persone, rimaste illese. I sicari, giunti all&#8217; improvviso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":140081,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140080"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=140080"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140080\/revisions"}],"predecessor-version":[{"id":140084,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140080\/revisions\/140084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/140081"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=140080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=140080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=140080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}