{"id":140502,"date":"2018-07-08T00:27:17","date_gmt":"2018-07-07T22:27:17","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=140502"},"modified":"2018-07-08T15:06:11","modified_gmt":"2018-07-08T13:06:11","slug":"emozione-continua-aspettando-le-semifinali","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/07\/08\/emozione-continua-aspettando-le-semifinali\/","title":{"rendered":"EMOZIONE CONTINUA \/ ASPETTANDO LE SEMIFINALI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-140503\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/07\/croazia.esultanza.rigori.russia.2018.750x450.jpg\" alt=\"\" width=\"750\" height=\"450\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/07\/croazia.esultanza.rigori.russia.2018.750x450.jpg 750w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/07\/croazia.esultanza.rigori.russia.2018.750x450-300x180.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>(Rdl)______A Soci scende la notte anche sulla Russia intera, che non va pi\u00f9 in l\u00e0 dei quarti, dopo una partita d&#8217;una intensit\u00e0 straordinaria, e la lotteria dei calci di rigore, che questa volta premia gli avversari, una Serbia quadrata, quanto talentuosa.<\/p>\n<p>In precedenza, nel pomeriggio, a Samara, l&#8217; Inghilterra &#8216;regola&#8217; &#8211; &#8216;stavolta come da pronostico e senza patemi d&#8217; animo &#8211; con il punteggio di 2 a 0 tanto British, una Svezia che di pi\u00f9 non poteva fare.<\/p>\n<p>Si ricominia marted\u00ec 10, alle 20, a San Pietroburgo, con Francia &#8211; Belgio.<\/p>\n<p>Si continua mercoled\u00ec 11, alle 20, a Mosca, con Croazia &#8211; Inghilterra.<\/p>\n<p>Questi Mondiali di Russia 2018 non smettono di emozionare<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/07\/08\/emozione-continua-aspettando-le-semifinali\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/07\/08\/emozione-continua-aspettando-le-semifinali\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______A Soci scende la notte anche sulla Russia intera, che non va pi\u00f9 in l\u00e0 dei quarti, dopo una partita d&#8217;una intensit\u00e0 straordinaria, e la lotteria dei calci di rigore, che questa volta premia gli avversari, una Serbia quadrata, quanto talentuosa. In precedenza, nel pomeriggio, a Samara, l&#8217; Inghilterra &#8216;regola&#8217; &#8211; &#8216;stavolta come da pronostico [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":140503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140502"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=140502"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140502\/revisions"}],"predecessor-version":[{"id":140504,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/140502\/revisions\/140504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/140503"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=140502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=140502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=140502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}