{"id":14411,"date":"2013-04-16T07:14:27","date_gmt":"2013-04-16T07:14:27","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14411"},"modified":"2013-04-16T07:14:27","modified_gmt":"2013-04-16T07:14:27","slug":"tributo-ai-radiohead-con-the-bends-al-black-betty-di-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/tributo-ai-radiohead-con-the-bends-al-black-betty-di-lecce\/","title":{"rendered":"TRIBUTO AI RADIOHEAD CON THE BENDS AL BLACK BETTY DI LECCE"},"content":{"rendered":"<p><span style=\"color: #222222;font-family: arial, sans-serif\">Mercoled\u00ec 17 aprile tornano in scena &#8220;I Mercoled\u00ec Live&#8221;, la rassegna che vede protagonista la musica dal vivo al &#8220;Black Betty&#8221; di Lecce.\u00a0<a href=\"http:\/\/webmaildomini.aruba.it\/\/ext_aruba\/classic\/html\/mainframe.html?_v_=v4r1b17m6.20120629_1045?lang=it&amp;flavour=orange&amp;theme=ext_aruba\/classic&amp;useSprite=0\">Questa settimana<\/a>\u00a0gli ospiti saranno i The Bends per un tributo dedicato ai Radiohead e alle loro storiche hits.<\/span><\/p>\n<p>&#8220;The Bends&#8221; \u00e8 un progetto che nasce nel 2012 per rendere omaggio ad una delle band che pi\u00f9 ha influenzato e segnato il panorama musicale negli ultimi 20 anni: i Radiohead. Pochi come loro sono stati in grado di rappresentare in musica il disagio esistenziale di fine millennio, l&#8217;alienazione della &#8220;X Generation&#8221;, l&#8217;umore dei &#8220;kids&#8221; del nuovo secolo. Le loro canzoni, affollate di &#8220;loser&#8221; e di &#8220;creep&#8221;, di androidi e di rottami spaziali, sono la sintesi ideale di un percorso che parte dalla desolazione post-punk di Smiths e Joy Division per approdare nelle fredde lande dell&#8217;elettronica europea.<\/p>\n<div><\/div>\n<div>\u2018Radiohead\u2019 \u00e8 il punto di incontro di cinque musicisti per la formazione di una tribute band che prende il nome da uno dei loro dischi pi\u00f9 rappresentativi, un progetto nato per vivere un\u2019esperienza sonora attraverso brani come &#8216;No Surprises&#8217;, &#8216;2+2=5&#8217;, &#8216;Paranoid Android&#8217;, &#8216;Bodysnatchers&#8217;, &#8216;Just&#8217;, cercando di ricreare quel sound arcano, disperato,\u00a0sublime ed ultraterreno che ha segnato lo stile dei ragazzi di Oxford.<\/div>\n<div>\n<span style=\"color: #222222;font-family: arial, sans-serif\">La line up del gruppo \u00e8 composta da:\u00a0<\/span>\u00a0Alessandro Serio (voce\/chitarra),\u00a0Johnny Davide Sergi (chitarra\/tastiere),\u00a0Antonio Tunno (chitarra\/voce),\u00a0Dario Ancona (basso) e\u00a0Vittorio Gaudenti (batteria).<\/p>\n<p>L&#8217;appuntamento si preannuncia imperdibile per farsi trascinare e\u00a0coinvolgere dalle note dei The Bends, sul palco\u00a0del &#8220;Black Betty&#8221; di Lecce, ormai locale cult per i concerti rock nel\u00a0leccese, per rendere omaggio ai grandi Radiohead.<\/p>\n<p>L&#8217;ingresso \u00e8 totalmente gratuito e l&#8217;inizio del concerto \u00e8 previsto per le 22.<\/p>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/tributo-ai-radiohead-con-the-bends-al-black-betty-di-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/tributo-ai-radiohead-con-the-bends-al-black-betty-di-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 17 aprile tornano in scena &#8220;I Mercoled\u00ec Live&#8221;, la rassegna che vede protagonista la musica dal vivo al &#8220;Black Betty&#8221; di Lecce.\u00a0Questa settimana\u00a0gli ospiti saranno i The Bends per un tributo dedicato ai Radiohead e alle loro storiche hits. &#8220;The Bends&#8221; \u00e8 un progetto che nasce nel 2012 per rendere omaggio ad una delle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14411"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14411"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14411\/revisions"}],"predecessor-version":[{"id":14413,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14411\/revisions\/14413"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}