{"id":14414,"date":"2013-04-16T09:21:57","date_gmt":"2013-04-16T09:21:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14414"},"modified":"2013-04-16T09:21:57","modified_gmt":"2013-04-16T09:21:57","slug":"i-corti-di-jonathan-imperiale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/i-corti-di-jonathan-imperiale\/","title":{"rendered":"I corti di Jonathan Imperiale"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/i-corti-di-jonathan-imperiale\/sum-km97-locandina-corti-di-jonathan\/\" rel=\"attachment wp-att-14415\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/sum-km97-locandina-corti-di-jonathan.jpg\" alt=\"\" width=\"1005\" height=\"565\" class=\"alignleft size-full wp-image-14415\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/sum-km97-locandina-corti-di-jonathan.jpg 1005w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/sum-km97-locandina-corti-di-jonathan-300x168.jpg 300w\" sizes=\"(max-width: 1005px) 100vw, 1005px\" \/><\/a>La rivoluzione \/ Piovono caschi \/<\/strong> <strong>Il frutto dell&#8217;amore.<br \/>\n<\/strong><strong>Sabato 20 aprile, a partire dalle 22.00<\/strong>, il <strong>Km97<\/strong> si trasformer\u00e0 in una sala cinematografica in occasione della proiezione di tre <strong>cortometraggi<\/strong> firmati <strong>Jonathan Imperiale <\/strong>(al secolo Giacinto Gionat Imperiale).<\/p>\n<p>Giacinto Gionat Imperiale \u00e8 nato a Casarano (Le) nel 1975 e si \u00e8 laureato in filosofia con una tesi sui meccanismi del comico nel cinema. Dall\u2019ampliamento di questo lavoro pubblica con la collaborazione del professor Antonio Godino, ordinario di Psicologia generale presso l\u2019Universit\u00e0 del Salento, il testo <em>Far ridere non \u00e8 uno scherzo. I meccanismi del comico e delle comiche in cento film<\/em>.<br \/>\nHa conseguito presso L\u2019Universit\u00e0 degli Studi di Foggia il dottorato in scienze dell\u2019antichit\u00e0 con una tesi dal titolo <em>Moloch, Golem e Faust<\/em>. <em>Sacrificio, creazione e tentazione tra Cinema e Bibbia<\/em>.<br \/>\nDa sempre studioso delle tecniche e dei linguaggi cinematografici, \u00e8 autore di diverse pubblicazioni nel campo per la rivista <em>Psychofenia. Ricerca ed analisi psicologic<\/em>a, tra cui i saggi \u2018<em>Tra universale e particolare: Chaplin e Tot\u00f2\u2019<\/em> (n.14\/2006) e \u2018<em>Aspetti psicologici nel cinema: L\u2019espressionismo tedesco\u2019<\/em> (n.24\/2011). Per <em>Cabiria. Studi di cinema,<\/em> pubblica inoltre il saggio \u2018<em>Cabiria. Il romanzo delle fiamme\u2019<\/em> (n.169\/2012). In via di stampa \u00e8 infine il saggio \u2018<em>La via Crucis del Comico. Da Aristofane a La Passione di Carlo Mazzacurati\u2019<\/em> per la rivista di studi cristianistici <em>Auctores Nostri<\/em> (n.10\/2011).<br \/>\nLa grande passione per il cinema e la comicit\u00e0 lo spingono a cimentarsi sia nel cabaret sia nella realizzazione di numerosi cortometraggi, utilizzando, per firmare il suoi lavori, il nome d\u2019arte di Jonathan Imperiale.<br \/>\nNel febbraio del 2009 entra a far parte dei comici del laboratorio <strong>Zelig<\/strong> di Bari, ed un anno dopo \u00e8 scelto dalla <strong>RAI<\/strong> nell\u2019iniziativa <strong>Nuovi Talenti<\/strong>.<br \/>\nNel 2010, con <strong>Piovono caschi<\/strong>, si \u00e8 distinto al concorso <strong>Save the talent,<\/strong> indetto da <strong>RAI<\/strong> e <strong>INAIL<\/strong> per la sicurezza sul lavoro. Nel 2011 ha partecipato al <strong>13\u00b0 Festival del<\/strong> <strong>Cinema Europeo di Lecce<\/strong> nella sezione <strong>Puglia Show<\/strong> con il mediometraggio <strong>La Rivoluzione.<\/p>\n<p><\/strong><\/p>\n<p><strong><em>I CORTOMETRAGGI IN PROIEZIONE<\/em><\/strong><\/p>\n<p><strong>La rivoluzione<\/strong><strong>.<br \/>\n<\/strong>Surreale tentativo di ascesa al potere di uno sparuto ed improbabile gruppo rivoluzionario. Diviso in tre parti (<em>i tempi della rivoluzione \u2013 la presa del ministero \u2013 i modi della rivoluzione<\/em>) il corto propone lo scontro paradossale tra le incerte appartenenze ideologiche dei singoli rivoluzionari ed il grottesco formalismo dell\u2019apparato burocratico.<br \/>\n<strong>Piovono caschi<\/strong><strong>.<br \/>\n<\/strong>Tra i primi classificati al concorso Save the talent indetto da Rai e Inail per la sicurezza sul lavoro (2010), racconta il viaggio <em>magrittiano<\/em> di un operaio \u2018<em>Mario\u2019<\/em> sotto una pioggia di caschi. Nel finale, tra i titoli di coda, viene svelata la meta del tragitto, nel momento in cui un altro operaio intraprende lo stesso percorso.<br \/>\n<strong>Il frutto dell&#8217;amore<\/strong><strong>.<br \/>\n<\/strong>Un omaggio al grande Buster Keaton.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sabato 20 aprile<br \/>\nKm97<br \/>\nVia della Ferrandina, 5 (prov. Lecce-Novoli)<br \/>\nore 22.00<br \/>\ningresso libero riservato ai soci<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/i-corti-di-jonathan-imperiale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/16\/i-corti-di-jonathan-imperiale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La rivoluzione \/ Piovono caschi \/ Il frutto dell&#8217;amore. Sabato 20 aprile, a partire dalle 22.00, il Km97 si trasformer\u00e0 in una sala cinematografica in occasione della proiezione di tre cortometraggi firmati Jonathan Imperiale (al secolo Giacinto Gionat Imperiale). Giacinto Gionat Imperiale \u00e8 nato a Casarano (Le) nel 1975 e si \u00e8 laureato in filosofia [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14415,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14414"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14414"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14414\/revisions"}],"predecessor-version":[{"id":14417,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14414\/revisions\/14417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14415"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}