{"id":144541,"date":"2018-09-28T14:31:06","date_gmt":"2018-09-28T12:31:06","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=144541"},"modified":"2018-09-28T14:31:06","modified_gmt":"2018-09-28T12:31:06","slug":"nuovi-pullman-per-le-ferrovie-del-sud-est","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/09\/28\/nuovi-pullman-per-le-ferrovie-del-sud-est\/","title":{"rendered":"NUOVI PULLMAN PER LE FERROVIE DEL SUD EST"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-144542\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/09\/ND3_2501.jpg\" alt=\"\" width=\"3500\" height=\"2329\" \/><\/p>\n<p>(a.p.)_____Le ferrovie del Sud Est hanno\u00a0presentato questa mattina a Lecce, alla presenza\u00a0 dell\u2019Assessore regionale ai Trasporti e alle Infrastrutture, Giovanni Giannini, e dell\u2019Amministratore Delegato e dal Direttore Generale di FSE, Luigi Lenci e Giorgio Botti, la nuova flotta di bus.<\/p><\/div>\n<p>I nuovi mezzi, che rispondono a migliori condizioni di\u00a0\u00a0confort di viaggio e standard di sicurezza, hanno una capienza di 51 posti a sedere e 26 in piedi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/09\/28\/nuovi-pullman-per-le-ferrovie-del-sud-est\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/09\/28\/nuovi-pullman-per-le-ferrovie-del-sud-est\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(a.p.)_____Le ferrovie del Sud Est hanno\u00a0presentato questa mattina a Lecce, alla presenza\u00a0 dell\u2019Assessore regionale ai Trasporti e alle Infrastrutture, Giovanni Giannini, e dell\u2019Amministratore Delegato e dal Direttore Generale di FSE, Luigi Lenci e Giorgio Botti, la nuova flotta di bus. I nuovi mezzi, che rispondono a migliori condizioni di\u00a0\u00a0confort di viaggio e standard di sicurezza, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/144541"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=144541"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/144541\/revisions"}],"predecessor-version":[{"id":144543,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/144541\/revisions\/144543"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=144541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=144541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=144541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}