{"id":14534,"date":"2013-04-18T10:03:52","date_gmt":"2013-04-18T10:03:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14534"},"modified":"2013-04-18T10:03:52","modified_gmt":"2013-04-18T10:03:52","slug":"m-o-oggi-il-prisoners-day-236-bimbi-palestinesi-detenuti-in-israele","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/18\/m-o-oggi-il-prisoners-day-236-bimbi-palestinesi-detenuti-in-israele\/","title":{"rendered":"M.O.: OGGI IL &#8220;PRISONERS DAY&#8221;, 236 BIMBI PALESTINESI DETENUTI IN ISRAELE"},"content":{"rendered":"<div>\n<div><em><strong>Riceviamo e pubblichiamo<\/strong><\/em><\/div>\n<\/div>\n<div>\n<div><a title=\"Clicca per vedere l'anteprima dell'immagine\" href=\"http:\/\/italian.irib.ir\/media\/k2\/items\/cache\/3724c30569d70a6232f94d090c3c9400_XL.jpg\" rel=\"{handler: 'image'}\"><img decoding=\"async\" src=\"http:\/\/italian.irib.ir\/media\/k2\/items\/cache\/3724c30569d70a6232f94d090c3c9400_L.jpg\" alt=\"M.O.: oggi il &#039;Prisoners Day&#039;, 236 bimbi palestinesi detenuti in Israele\" \/><\/a><\/p>\n<div><\/div>\n<\/div>\n<div>RAMALLAH &#8211; Tra i quasi 5 mila palestinesi detenuti nelle carceri israeliane almeno 236 sono bambini fino ai 12 anni: lo ha reso noto oggi l&#8217;Autorita&#8217; nazionale palestinese in occasione del &#8216;Prisoners Day&#8217;, secondo quanto scrive l&#8217;agenzia Maan.<\/div>\n<div>\n<p>Israele &#8211; si legge &#8211; e&#8217; oggi l&#8217;unico paese al mondo ad aver istituito tribunali militari per i bambini e dal 2000 ne ha arrestti circa 8 mila. Quasi sette mila, invece, secondo l&#8217;organizzazione non governativa Defence for Children International. Seguendo l&#8217;ordinamento giuridico militare dello Stato ebraico, un bambino palestinese puo&#8217; infatti essere detenuto per un massimo di 188 giorni prima di essere accusato di un reato. Gran parte di loro &#8211; prosegue la Maan &#8211; sono in arresto per aver lanciato pietre, un atto che secondo la legge militare prevede una pena massima di 20 anni di prigione. Stando a un recente rapporto dell&#8217;Unicef, i minorenni detenuti nelle carceri israeliane sono soggetti a una diffusa, sistematica e istituzionalizzata catena di maltrattamenti che viola il diritto internazionale. Subiscono, recita il dossier, &#8221;punizioni crudeli, inumani o degradanti in base alla Convenzione sui diritti del fanciullo e la Convenzione contro la tortura&#8221;. I maltrattementi includono &#8221;il bendaggio degli occhi e le mani legate con fascette di plastica, abusi fisici e verbali durante il trasferimento per un interrogatorio, durante il quale molti minori hanno subito violenze fisica e minacce&#8221;.<\/p>\n<\/div>\n<div><\/div>\n<div>\u00a0<a title=\"Share\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele&amp;t=M.O.:%20oggi%20il%20'Prisoners%20Day',%20236%20bimbi%20palestinesi%20detenuti%20in%20Israele\">Facebook<\/a><\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>Commenti\u00a0<a title=\"RSS feed dei commenti di questo post.\" href=\"http:\/\/italian.irib.ir\/component\/jcomments\/feed\/com_k2\/124320\" target=\"_blank\">\u00a0<\/a><a title=\"Aggiorna elenco commenti\" href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#\">\u00a0<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<div>0<a id=\"comment-12462\" href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#comment-12462\">#3<\/a>\u00a0Antisionista\u00a02013-04-18 03:12<\/p>\n<div>I mass media occidentali sono impegnati a nascondere la verit\u00e0.<\/div>\n<p><a href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#\">Citazione<\/a><\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>\n<div>\u00a0+3<a id=\"comment-12454\" href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#comment-12454\">#2<\/a>\u00a0zardoz\u00a02013-04-17 19:47<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>E dove stanno i &#8220;difensori dei diritti civili&#8221;???? dove cazzo stanno Amnisty International e l&#8217;UNICEF e tutte le organizzazioni fantoccio pagate per campagne farlocche &#8230;?<\/div>\n<p><a href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#\">Citazione<\/a><\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>\n<div>\u00a0+3<a id=\"comment-12447\" href=\"http:\/\/italian.irib.ir\/notizie\/palestina-news\/item\/124320-m-o-oggi-il-prisoners-day-,-236-bimbi-palestinesi-detenuti-in-israele#comment-12447\">#1<\/a>\u00a0Vincenzo Mannello\u00a02013-04-17 18:21<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>Gi\u00e0,questo \u00e8 il civile e democratico trattamento che israele riserva ai bambini ! Uno schifo,che abbiano lanciato una pietra o meno. Una pietra contro blindati e carri armati ! Personalmente,a\u00a0ssieme a tanti altri,faccio di tutto e di pi\u00fa per segnalare questo obbrobrio. Non basta,in Italia ed Europa non basta. Occorre smuovere i grandi media che proprio non vedono,non sentono e,tantomeno,par\u00a0lano o scrivono. Eppure il sistema si potrebbe trovare&#8230;&#8230;.<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/18\/m-o-oggi-il-prisoners-day-236-bimbi-palestinesi-detenuti-in-israele\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/18\/m-o-oggi-il-prisoners-day-236-bimbi-palestinesi-detenuti-in-israele\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo RAMALLAH &#8211; Tra i quasi 5 mila palestinesi detenuti nelle carceri israeliane almeno 236 sono bambini fino ai 12 anni: lo ha reso noto oggi l&#8217;Autorita&#8217; nazionale palestinese in occasione del &#8216;Prisoners Day&#8217;, secondo quanto scrive l&#8217;agenzia Maan. Israele &#8211; si legge &#8211; e&#8217; oggi l&#8217;unico paese al mondo ad aver istituito [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14534"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14534"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14534\/revisions"}],"predecessor-version":[{"id":14535,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14534\/revisions\/14535"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}