{"id":14728,"date":"2013-04-21T12:06:44","date_gmt":"2013-04-21T12:06:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14728"},"modified":"2013-04-21T12:07:23","modified_gmt":"2013-04-21T12:07:23","slug":"ruba-il-portafoglio-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/21\/ruba-il-portafoglio-arrestato\/","title":{"rendered":"RUBA IL PORTAFOGLIO: ARRESTATO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/21\/ruba-il-portafoglio-arrestato\/corciulo-davide-stampa\/\" rel=\"attachment wp-att-14732\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/CORCIULO-Davide-stampa.jpg\" alt=\"\" width=\"312\" height=\"413\" class=\"alignleft size-full wp-image-14732\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/CORCIULO-Davide-stampa.jpg 312w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/CORCIULO-Davide-stampa-226x300.jpg 226w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/a>I Carabinieri della Stazione di Gagliano del Capo hanno arrestato, per furto in abitazione, Davide CORCIULO, ventenne di Gallipoli, gi\u00e0 gravato da precedenti di polizia, e denunciato in stato di libert\u00e0 il suo complice minorenne. Ieri una signora di Gagliano del Capo era nel giardino della propria abitazione intenta ad accudire alcune pianticelle quando, nel fare rientro nella casa si \u00e8 accorta che le era sparito il portafoglio poco prima appoggiato su un mobile della cucina. Dopo i primi minuti di affannose ricerche, avuta la certezza di non averlo riposto in un altro luogo, ha chiesto, tramite il Numero Unico Europeo di Emergenza 112, alla Centrale Operativa della Compagnia Carabinieri di Tricase, l\u2019intervento di una pattuglia di Carabinieri. All\u2019indirizzo richiesto \u00e8 quindi prontamente intervenuta una pattuglia della Stazione Carabinieri di Gagliano del Capo i cui componenti, ricostruito quanto accaduto, si sono immediatamente messi a svolgere le prime indagini. Grazie alla preziosissima collaborazione di alcuni cittadini, i quali hanno riferito univocamente di aver visto due giovani, di cui uno facilmente distinguibile perch\u00e9 indossava un giubbotto di colore blu elettrico, che si aggiravano con fare circospetto nei pressi della casa derubata, \u00e8 stato subito possibile indirizzare le ricerche su un minore del paese notato poco prima dagli stessi Carabinieri mentre andava a spasso assieme ad un altro ragazzo sconosciuto. Aspetto fisico ed abbigliamento dei due giovani corrispondevano in modo incredibile con i due presunti autori del furto visti dai diversi testimoni. Rintracciati i giovani, e successivamente identificato per Davide CORCIULO quello non noto, sono stati accompagnati in caserma dove \u00e8 stato convocato anche il padre del sedicenne. In un primo momento i due hanno negato qualsiasi tipo di responsabilit\u00e0 ma poi, messi di fronte alle numerose contraddizioni e falle nelle loro ricostruzioni delle ore trascorse insieme e, soprattutto, inchiodati dalle numerose testimonianze che li collocavano in modo inequivocabile ed inconfutabile sul luogo e nell\u2019ora del furto, hanno iniziato a vacillare fino a quando non hanno confessato. Nel frattempo i Carabinieri erano riusciti a recuperare il portafogli della vittima, gettato in un campo non lontano da dove i due erano stati fermati. Davide CORCIULO, con il concorde parere del PM di turno della Procura della Repubblica presso il Tribunale di Lecce, dr.ssa Paola Guglielmi, \u00e8 stato dichiarato in arresto e trasferito presso la Casa Circondariale \u201cBorgo San Nicola\u201d di Lecce.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/21\/ruba-il-portafoglio-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/21\/ruba-il-portafoglio-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Gagliano del Capo hanno arrestato, per furto in abitazione, Davide CORCIULO, ventenne di Gallipoli, gi\u00e0 gravato da precedenti di polizia, e denunciato in stato di libert\u00e0 il suo complice minorenne. Ieri una signora di Gagliano del Capo era nel giardino della propria abitazione intenta ad accudire alcune pianticelle quando, nel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14732,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14728"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14728"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14728\/revisions"}],"predecessor-version":[{"id":14735,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14728\/revisions\/14735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14732"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}