{"id":147683,"date":"2018-12-06T13:45:29","date_gmt":"2018-12-06T12:45:29","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=147683"},"modified":"2018-12-06T17:43:57","modified_gmt":"2018-12-06T16:43:57","slug":"giro-di-favori-arresti-eccellenti-in-manette-un-pubblico-ministero-della-procura-della-repubblica-di-lecce-e-il-direttore-generale-dell-asl-di-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/giro-di-favori-arresti-eccellenti-in-manette-un-pubblico-ministero-della-procura-della-repubblica-di-lecce-e-il-direttore-generale-dell-asl-di-lecce\/","title":{"rendered":"GIRO DI FAVORI, ARRESTI ECCELLENTI, IN MANETTE UN PUBBLICO MINISTERO DELLA PROCURA DELLA REPUBBLICA DI LECCE E IL DIRETTORE GENERALE DELL&#8217; ASL DI LECCE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-147685 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/PO.jpg\" alt=\"\" width=\"1000\" height=\"478\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/PO.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/PO-300x143.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/PO-768x367.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>(e.l.)______Clamorosi esiti dell&#8217; indagine della Procura della Repubblica di Potenza (nella foto) che ha indagato su presunti vantaggi economici e prestazioni sessuali in cambio di favori giudiziari.<\/p>\n<p>Con l&#8217;accusa di corruzione \u00e8 stato arrestato un pubblico ministero della Procura della Repubblica di Lecce, Emilio Arnesano. E&#8217; stata disposto anche a suo carico il sequestro di un&#8217;imbarcazione e di 18.000 mila euro.<\/p>\n<p>Inoltre il gip di Potenza ha disposto gli arresti domiciliari per altre quattro persone: tre dirigenti dell&#8217;Asl di Lecce &#8211; Ottavio Naracci, direttore generale, e due dirigenti, Giorgio Trianni e Giuseppe Rollo, e dell&#8217;avvocato Benedetta Martina.<\/p>\n<p>A breve, metteremo on line tutti i particolari, resi noti dal Procuratore di Potenza Francesco Curcio.______<\/p>\n<p>LA RICERCA nel nostro articolo seguito a questo dopo un&#8217;ora<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"gw7KrYiCqS\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/prestazioni-sessuali-una-barca-soldi-e-altri-favori-cosi-il-pm-arrestato-secondo-le-accuse-svendeva-la-giustizia-ecco-tutti-gli-episodi-contestatigli\/\">PRESTAZIONI SESSUALI, UNA BARCA, SOLDI E ALTRI FAVORI, COSI&#8217; IL PM ARRESTATO, SECONDO LE ACCUSE, SVENDEVA LA GIUSTIZIA. ECCO TUTTI GLI EPISODI CONTESTATIGLI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/prestazioni-sessuali-una-barca-soldi-e-altri-favori-cosi-il-pm-arrestato-secondo-le-accuse-svendeva-la-giustizia-ecco-tutti-gli-episodi-contestatigli\/embed\/#?secret=gw7KrYiCqS\" data-secret=\"gw7KrYiCqS\" width=\"500\" height=\"282\" title=\"&#8220;PRESTAZIONI SESSUALI, UNA BARCA, SOLDI E ALTRI FAVORI, COSI&#8217; IL PM ARRESTATO, SECONDO LE ACCUSE, SVENDEVA LA GIUSTIZIA. ECCO TUTTI GLI EPISODI CONTESTATIGLI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/giro-di-favori-arresti-eccellenti-in-manette-un-pubblico-ministero-della-procura-della-repubblica-di-lecce-e-il-direttore-generale-dell-asl-di-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/giro-di-favori-arresti-eccellenti-in-manette-un-pubblico-ministero-della-procura-della-repubblica-di-lecce-e-il-direttore-generale-dell-asl-di-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Clamorosi esiti dell&#8217; indagine della Procura della Repubblica di Potenza (nella foto) che ha indagato su presunti vantaggi economici e prestazioni sessuali in cambio di favori giudiziari. Con l&#8217;accusa di corruzione \u00e8 stato arrestato un pubblico ministero della Procura della Repubblica di Lecce, Emilio Arnesano. E&#8217; stata disposto anche a suo carico il sequestro di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":147685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147683"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=147683"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147683\/revisions"}],"predecessor-version":[{"id":147712,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147683\/revisions\/147712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/147685"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=147683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=147683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=147683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}