{"id":147694,"date":"2018-12-06T00:02:15","date_gmt":"2018-12-05T23:02:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=147694"},"modified":"2018-12-06T19:59:51","modified_gmt":"2018-12-06T18:59:51","slug":"maria-grazia-palazzo-a-lecce-venerdi7","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/maria-grazia-palazzo-a-lecce-venerdi7\/","title":{"rendered":"MARIA GRAZIA PALAZZO A LECCE VENERDI&#8217; 7"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-147696 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/cover-palazzo.jpg\" alt=\"\" width=\"800\" height=\"353\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/cover-palazzo.jpg 800w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/cover-palazzo-300x132.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/cover-palazzo-768x339.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>(Rdl)______Venerd\u00ec 7 dicembre, alle 19.00, a Lecce, al Fondo Verri, in via S. Maria Del Paradiso 8, ci ar\u00e0 la presentazione della raccolta di poesie &#8220;Andromeda&#8221; di <strong>Maria Grazia Palazzo<\/strong> (nella foto), I Quaderni del Bardo Edizioni.<\/p>\n<p>Dialogano con l\u2019autrice l\u2019editore Stefano Donno e Mauro Marino del Fondo Verri.<\/p>\n<p>&nbsp;<\/p>\n<p>Maria Grazia Palazzo \u00e8 nata nel \u201968 in valle d\u2019Itria. Avvocato e insegnante precaria. Negli ultimi anni ha intrapreso lo studio della teologia e dei diritti delle differenze e dei saperi di genere.<\/p>\n<p>Info link &#8211; http:\/\/www.iquadernidelbardoedizioni.it\/<\/p>\n<p>Mail &#8211; iquadernidelbardoed@libero.it ______<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-147697 size-large\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/andromeda-960x1024.jpg\" alt=\"\" width=\"960\" height=\"1024\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/andromeda-960x1024.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/andromeda-281x300.jpg 281w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/andromeda-768x819.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2018\/12\/andromeda.jpg 1298w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217; APPROFONDIMENTO nella nostra recensione del 28 novembre scorso<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ufcm11Lz1u\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/11\/28\/la-raccolta-di-poesie-andromeda-viaggio-destinale-di-maria-grazia-palazzo-per-iqsb-ediioni\/\">ESCE LA RACCOLTA DI POESIE &#8220;ANDROMEDA&#8221;, VIAGGIO DESTINALE DI MARIA GRAZIA PALAZZO, PER iQdB EDIZIONI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/11\/28\/la-raccolta-di-poesie-andromeda-viaggio-destinale-di-maria-grazia-palazzo-per-iqsb-ediioni\/embed\/#?secret=Ufcm11Lz1u\" data-secret=\"Ufcm11Lz1u\" width=\"500\" height=\"282\" title=\"&#8220;ESCE LA RACCOLTA DI POESIE &#8220;ANDROMEDA&#8221;, VIAGGIO DESTINALE DI MARIA GRAZIA PALAZZO, PER iQdB EDIZIONI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/maria-grazia-palazzo-a-lecce-venerdi7\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2018\/12\/06\/maria-grazia-palazzo-a-lecce-venerdi7\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Venerd\u00ec 7 dicembre, alle 19.00, a Lecce, al Fondo Verri, in via S. Maria Del Paradiso 8, ci ar\u00e0 la presentazione della raccolta di poesie &#8220;Andromeda&#8221; di Maria Grazia Palazzo (nella foto), I Quaderni del Bardo Edizioni. Dialogano con l\u2019autrice l\u2019editore Stefano Donno e Mauro Marino del Fondo Verri. &nbsp; Maria Grazia Palazzo \u00e8 nata [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":147696,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,75,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147694"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=147694"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147694\/revisions"}],"predecessor-version":[{"id":147720,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/147694\/revisions\/147720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/147696"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=147694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=147694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=147694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}