{"id":14867,"date":"2013-04-23T07:54:55","date_gmt":"2013-04-23T07:54:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14867"},"modified":"2013-04-23T07:54:55","modified_gmt":"2013-04-23T07:54:55","slug":"tenta-di-rubare-attrezzature-da-pesca-denunciato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/tenta-di-rubare-attrezzature-da-pesca-denunciato\/","title":{"rendered":"TENTA DI RUBARE ATTREZZATURE DA PESCA: DENUNCIATO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/tenta-di-rubare-attrezzature-da-pesca-denunciato\/unknown-14\/\" rel=\"attachment wp-att-14868\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Unknown3.jpeg\" alt=\"\" width=\"276\" height=\"183\" class=\"alignleft size-full wp-image-14868\" \/><\/a>I militari dell\u2019Aliquota Radiomobile della Compagnia di Campi Salentina hanno proceduto questa notte alla denuncia in stato di libert\u00e0 di A.R., trentenne di Casalabate, per il reato di furto in abitazione. Alle ore 01.30 circa, una pattuglia dell\u2019istituto di vigilanza \u201cLa Folgore\u201d, transitando in via della Mormora, ha notato una Lancia Ypsilon con il cofano aperto e due ragazzi che caricavano alcune cose. Avvicinatosi maggiormente, uno dei due \u00e8 riuscito a scappare, mentre l\u2019altro \u00e8 stato prontamente bloccato. Accorsi subito dopo, i carabinieri chiamati in rinforzo, dopo accurato sopralluogo hanno appurato che il materiale caricato in macchina, attrezzatura varia da pesca (fucile, canna, pinne ecc.), era stato asportato da un\u2019abitazione per le vacanze non distante. Nessuna forzatura \u00e8 stata riscontrata: \u00e8 stata sollevata una tapparella nascondente una finestra lasciata aperta. Il materiale, nonch\u00e9 l\u2019autovettura, di propriet\u00e0 di A.R. risultata priva di assicurazione, sono stati sequestrati. Il giovane denunciato per furto in abitazione. Indagini in corso per individuare il complice.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><em><br \/>\n<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/tenta-di-rubare-attrezzature-da-pesca-denunciato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/tenta-di-rubare-attrezzature-da-pesca-denunciato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I militari dell\u2019Aliquota Radiomobile della Compagnia di Campi Salentina hanno proceduto questa notte alla denuncia in stato di libert\u00e0 di A.R., trentenne di Casalabate, per il reato di furto in abitazione. Alle ore 01.30 circa, una pattuglia dell\u2019istituto di vigilanza \u201cLa Folgore\u201d, transitando in via della Mormora, ha notato una Lancia Ypsilon con il cofano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14868,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14867"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14867"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14867\/revisions"}],"predecessor-version":[{"id":14870,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14867\/revisions\/14870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14868"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}