{"id":14871,"date":"2013-04-23T07:56:58","date_gmt":"2013-04-23T07:56:58","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=14871"},"modified":"2013-04-23T07:56:58","modified_gmt":"2013-04-23T07:56:58","slug":"a-rubare-con-il-furgone-sequestrato-arrestati","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/a-rubare-con-il-furgone-sequestrato-arrestati\/","title":{"rendered":"A RUBARE CON IL FURGONE SEQUESTRATO: ARRESTATI"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/a-rubare-con-il-furgone-sequestrato-arrestati\/furgone-iveco\/\" rel=\"attachment wp-att-14872\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/furgone-iveco.jpeg\" alt=\"\" width=\"260\" height=\"194\" class=\"alignleft size-full wp-image-14872\" \/><\/a>Nella mattinata odierna, ore 09,30 circa, una pattuglia de \u201cLa Velialpol\u201d ha intercettato un furgone \u201cIveco\u201d parcheggiato nei pressi dell\u2019ingresso del villaggio \u201cRiva degli Angeli\u201d, in Porto Cesareo, recentemente sottoposto a sequestro probatorio dalla dott. Ruggiero per il reato di abuso edilizio. All\u2019interno del cancello, ammassate, sette porte in alluminio asportate dagli alloggi estivi, nonch\u00e9 due uomini che, alla vista della pattuglia, hanno scavalcato e si sono messi alla guida del furgone. Ne \u00e8 nato un inseguimento, a cui nel frattempo si erano accodati i carabinieri della Stazione di Porto Cesareo, terminato ad Avetrana. Sono stati arrestati per tentato furto aggravato e violazione dei sigilli, Leo Bruno (coniugato) , nato il 23.03.1966, e suo nipote Leo Vincenzo, nato il 29.08.1982, entrambi nati e residenti a Francavilla Fontana, operai, pluripregiudicati per reati contro il patrimonio. La refurtiva \u00e8 stata restituita al legittimo proprietario, Pippi Durante, consigliere di maggioranza del Comune di Porto Cesareo. Il furgone \u00e8 stato sottoposto a sequestro. Gli arrestati, su disposizione della dott. Licci, sono stati accompagnati nella Casa Circondariale di Lecce.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/a-rubare-con-il-furgone-sequestrato-arrestati\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/23\/a-rubare-con-il-furgone-sequestrato-arrestati\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nella mattinata odierna, ore 09,30 circa, una pattuglia de \u201cLa Velialpol\u201d ha intercettato un furgone \u201cIveco\u201d parcheggiato nei pressi dell\u2019ingresso del villaggio \u201cRiva degli Angeli\u201d, in Porto Cesareo, recentemente sottoposto a sequestro probatorio dalla dott. Ruggiero per il reato di abuso edilizio. All\u2019interno del cancello, ammassate, sette porte in alluminio asportate dagli alloggi estivi, nonch\u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14871"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=14871"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14871\/revisions"}],"predecessor-version":[{"id":14874,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/14871\/revisions\/14874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/14872"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=14871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=14871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=14871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}