{"id":150120,"date":"2019-02-05T14:43:16","date_gmt":"2019-02-05T13:43:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=150120"},"modified":"2019-02-05T14:47:52","modified_gmt":"2019-02-05T13:47:52","slug":"dispersi-in-mare-due-pescatori","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/05\/dispersi-in-mare-due-pescatori\/","title":{"rendered":"PAURA PER DUE PESCATORI DISPERSI IN MARE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-150121\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/pescoluse-2.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/pescoluse-2.jpg 700w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/pescoluse-2-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>(e.l.)______C&#8217;\u00e8 moltissima apprensione per le sorti di due pescatori da ieri sera dispersi in mare al largo del Capo di Leuca. Si tratta di Damiano Tricarico, 43 anni, di Tuglie, e di Fabrizio Piro, 53 anni, di Gallipoli. La loro barca, un semicabinato, \u00e8 stata rovesciata dalle onde causate dal forte vento che batteva sulla zona. Un terzo uomo, il figlio di Fabrizio, Cosimo, 33 anni, \u00e8 invece riuscito a raggiungere a nuoto la riva e a dare l&#8217;allarme.<\/p>\n<p>Le ricerche vanno avanti dalle prime ore di oggi. L&#8217;imbarcazione \u00e8 stata recuperata, arenata sulla spiaggia di Pescoluse (nella foto). Dei due dispersi, invece, ancora nessuna traccia.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/05\/dispersi-in-mare-due-pescatori\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/05\/dispersi-in-mare-due-pescatori\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______C&#8217;\u00e8 moltissima apprensione per le sorti di due pescatori da ieri sera dispersi in mare al largo del Capo di Leuca. Si tratta di Damiano Tricarico, 43 anni, di Tuglie, e di Fabrizio Piro, 53 anni, di Gallipoli. La loro barca, un semicabinato, \u00e8 stata rovesciata dalle onde causate dal forte vento che batteva sulla [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":150121,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150120"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=150120"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150120\/revisions"}],"predecessor-version":[{"id":150125,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150120\/revisions\/150125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/150121"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=150120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=150120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=150120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}