{"id":150296,"date":"2019-02-09T18:26:54","date_gmt":"2019-02-09T17:26:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=150296"},"modified":"2019-02-09T20:19:45","modified_gmt":"2019-02-09T19:19:45","slug":"calcio-serie-b-aggiornamenti-34","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/09\/calcio-serie-b-aggiornamenti-34\/","title":{"rendered":"CALCIO, SERIE B, AGGIORNAMENTI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-150297\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/perugia-palermo-625x350.jpeg\" alt=\"\" width=\"625\" height=\"350\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/perugia-palermo-625x350.jpeg 625w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/02\/perugia-palermo-625x350-300x168.jpeg 300w\" sizes=\"(max-width: 625px) 100vw, 625px\" \/>(Rdl)______Risultati delle partite disputate nel pomeriggio.<\/p>\n<p>Lo Spezia va a vincere a Cittadella, gol partita di Galabinv a un quarto d&#8217;ora dalla fine, con i padroni di casa in dieci per espulsione per tutta la ripresa.<\/p>\n<p>Il Palermo si ritrova, e si rialza, sempre in testa, dopo le ultime prove negative, con la vittoria esterna a Perugia 1 a 2 (nella foto): doppietta di Puscas, che segna in avvio di gara, e poi in avvio di ripresa; troppo tardi, quasi alla fine, i padroni di casa accorciano le distanze con\u00a0 Melchiorri.<\/p>\n<p>Cremonese e Padova a reti bianche.<\/p>\n<p>Quando scriviamo questo pezzo, sono in campo da 20&#8242; Brescia e Carpi, e Donnarumma ha gi\u00e0 segnato un gol, un altro rigore a favore dei Lombardi.______<\/p>\n<p>AGGIORNAMENTO delle ore 20.15. Finita 3 a 1. Il Carpi aveva pareggiato poco dopo con Rolando, ma poi arriva presto con Ndoj il nuovo vantaggio dei padroni di casa, che arrotondano il successo di nuovo nei minuti del recupero finale e di nuovo con Donnarumma.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/09\/calcio-serie-b-aggiornamenti-34\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/02\/09\/calcio-serie-b-aggiornamenti-34\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Risultati delle partite disputate nel pomeriggio. Lo Spezia va a vincere a Cittadella, gol partita di Galabinv a un quarto d&#8217;ora dalla fine, con i padroni di casa in dieci per espulsione per tutta la ripresa. Il Palermo si ritrova, e si rialza, sempre in testa, dopo le ultime prove negative, con la vittoria esterna [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":150297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150296"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=150296"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150296\/revisions"}],"predecessor-version":[{"id":150305,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/150296\/revisions\/150305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/150297"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=150296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=150296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=150296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}