{"id":15098,"date":"2013-04-25T07:35:19","date_gmt":"2013-04-25T07:35:19","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15098"},"modified":"2013-04-25T07:37:52","modified_gmt":"2013-04-25T07:37:52","slug":"mostra-del-lecce-seconda-giornata","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/25\/mostra-del-lecce-seconda-giornata\/","title":{"rendered":"LA MOSTRA DEL LECCE"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/25\/mostra-del-lecce-seconda-giornata\/unknown-15\/\" rel=\"attachment wp-att-15099\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Unknown4.jpeg\" alt=\"\" width=\"190\" height=\"266\" class=\"alignleft size-full wp-image-15099\" \/><\/a><\/p>\n<p>Grande successo di pubblico e unanimi consensi per l\u2019<strong>inaugurazione<\/strong> ufficiale della mostra-evento \u201c<strong>Passione Lecce 105<\/strong>\u201d dedicata al Lecce calcio ed ai suoi tifosi. Le sale del <strong>Castello Carlo V<\/strong> di Lecce hanno accolto centinaia di visitatori letteralmente incantati per i tanti cimeli esposti, che hanno catturato l\u2019attenzione dei presenti, ciascuno dei quali alla ricerca del periodo storico pi\u00f9 vicino alla propria et\u00e0 anagrafica per poterlo ammirare e fotografare.<\/p>\n<p>La kermesse, organizzata da \u201c<strong>Lecce in Azione<\/strong>\u201d, grazie anche alla collaborazione offerta dalle associazioni \u201c<strong>Noi Lecce<\/strong>\u201d, \u201c<strong>Salento GialloRosso<\/strong>\u201d e l\u2019<strong>Archivio di Stato di Lecce<\/strong> \u00e8 stata inaugurata alla presenza del <strong>Presidente della Provincia di Lecce, Antonio Gabellone<\/strong>, che ha effettuato il rituale taglio del nastro rigorosamente giallorosso, dei consiglieri comunali <strong>Massimo Alfarano<\/strong> e <strong>Wojtek Pankiewicz<\/strong> e del consigliere regionale <strong>Saverio Congedo<\/strong>. Alla cerimonia sono intervenuti i dirigenti ed i tecnici dell\u2019U.S. Lecce <strong>Antonio Tesoro, Adolfo Starace, Donato Provenzano, Giuseppe Mercadante,<\/strong><strong> <\/strong><strong>Andrea Micati, Matteo Ievolella, <\/strong>mister<strong> Antonio Toma <\/strong>ed il suo vice<strong> Raffaele Di Fusco<\/strong>. Non hanno voluto mancare all\u2019inaugurazione anche mister <strong>Roberto Rizzo<\/strong>, l\u2019onorevole <strong>Ugo Lisi<\/strong> e l\u2019avvocato <strong>Pinuccio Milli<\/strong> che, insieme a <strong>Nicola Ricci<\/strong> ed altri indimenticabili amici, fondarono i \u201c<strong>Ragazzi della Nord<\/strong>\u201d ed il \u201c<strong>Commando Ultr\u00e0 Curva Nord<\/strong>\u201d (<strong>CUCN<\/strong>).<\/p>\n<p>La parte da leone l\u2019hanno fatto i <strong>trofei<\/strong> ufficiali del club di via Templari, concessi dalla societ\u00e0 salentina e sistemati nelle teche di vetro e sul palco appositamente predisposto in maniera da mostrare a tutti i partecipanti le coppe conquistate dall\u2019U.S. Lecce nella sua ultracentenaria storia.<\/p>\n<p>Un percorso-amarcord, arricchito dalla proiezione di <strong>immagini e filmati<\/strong> <strong>d\u2019epoca<\/strong>, colorato di giallo e di rosso anche con l\u2019ausilio della tante <strong>maglie da gioco originali<\/strong> messe a disposizione degli organizzatori da vecchie glorie e calciatori attualmente in forza alla formazione salentina.<\/p>\n<p>La seconda giornata della rassegna entra nel vivo degli incontri-dibattito con due distinti appuntamenti. Alle <strong>ore 11:00<\/strong>, si tratter\u00e0 il tema della storia del calcio a Lecce con gli interventi di <strong>Enzo Bianco, Antonio Corcella, Vittorio Renna, Stefano Adamo <\/strong>e di<strong> Elio Donno<\/strong>. Alle <strong>ore<\/strong> <strong>18:30<\/strong>, dopo la <strong>proiezione<\/strong> della gara degli <strong>spareggi <\/strong>del<strong> 1987<\/strong> per la promozione in A tra <strong>Lecce e Cremonese (4-1)<\/strong>, sar\u00e0 la volta dell\u2019<strong>era-Jurlano <\/strong>e del ricordo di <strong>Michele Lorusso <\/strong>e<strong> Ciro Pezzella<\/strong>. Vi parteciperanno <strong>Mimmo Renna, Aldo Sensibile, Ruggero Cannito Annarella Carlino <\/strong>(vedova di Ciro Pezzella)<strong> <\/strong>e<strong> Francesco Lorusso<\/strong>, uno dei figli di Michele. A moderare l\u2019incontro sar\u00e0 <strong>Umberto Verri<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>La seconda giornata della mostra dedicata ai 105 anni della storia del calcio a Lecce, la giornata di oggi,\u00a0<span style=\"color: #ff0000\">25 aprile,<\/span>\u00a0prevede due incontri dibattito. Gli ospiti \u00a0saranno: alle\u00a0<span>ore 11:00 Enzo Bianco, Antonio Corcella, Vittorio Renna, Stefano Adamo ed Elio Donno<\/span>\u00a0che parleranno della storia del Lecce calcio;\u00a0<span>alle ore 18:30 saranno invece presenti Mimino Renna, Aldo Sensibile, Ruggero Cannito, Annarella Pezzella (vedova di Ciro) e Francesco Lorusso (figlio di Michele) che affronteranno l\u2019era-Jurlano<\/span>.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/25\/mostra-del-lecce-seconda-giornata\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/25\/mostra-del-lecce-seconda-giornata\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Grande successo di pubblico e unanimi consensi per l\u2019inaugurazione ufficiale della mostra-evento \u201cPassione Lecce 105\u201d dedicata al Lecce calcio ed ai suoi tifosi. Le sale del Castello Carlo V di Lecce hanno accolto centinaia di visitatori letteralmente incantati per i tanti cimeli esposti, che hanno catturato l\u2019attenzione dei presenti, ciascuno dei quali alla ricerca del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15099,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15098"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15098"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15098\/revisions"}],"predecessor-version":[{"id":15102,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15098\/revisions\/15102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15099"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}