{"id":151277,"date":"2019-03-03T11:19:33","date_gmt":"2019-03-03T10:19:33","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=151277"},"modified":"2019-03-03T11:25:30","modified_gmt":"2019-03-03T10:25:30","slug":"il-lecce-il-postpartita-parlano-i-due-mister","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/03\/03\/il-lecce-il-postpartita-parlano-i-due-mister\/","title":{"rendered":"IL LECCE \/ IL POSTPARTITA \/ PARLANO I DUE MISTER"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-151278\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/03\/ste.png\" alt=\"\" width=\"711\" height=\"400\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/03\/ste.png 711w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/03\/ste-300x169.png 300w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/>(Rdl)______<\/p>\n<p>In evidenza, fra gli altri del postpartita, i commenti dei due allenatori, per la lucidit\u00e0 dell&#8217;analisi e l&#8217;onest\u00e0 intellettuale. Ecco una sintesi delle loro dichiarazioni, fatte a caldo nella serata di ieri.<\/p>\n<p><strong>Roberto Stellone <\/strong>(nella foto):\u00a0<em>&#8220;Abbiamo fatto un buon primo quarto d&#8217;ora, una bella gara, poi abbiamo sofferto, il Lecce &#8211; e faccio i complimenti &#8211; ci ha messo in difficolt\u00e0, non riuscivamo ad andarli\u00a0 prendere, \u00e8 stato bravo Brignoli in due-tre occasioni. Ecco, pr\u00f2 abbiamo saputo soffrire&#8230;Poi ci siamo sistemati meglio, siamo cresciuti, ma complimenti ancora al Lecce, che gioca un buon calcio.<\/em><\/p>\n<p><em>Per noi \u00e8 una vittoria importante, dopo la sconfitta di Crotone. Oggi siamo stati bravi a soffrire quando c&#8217;era da soffrire, e siamo stati cinici come non mai prima&#8221;.<\/em><\/p>\n<p><strong>Fabio Liverani<\/strong>: &#8220;<em>Rimpianti? Siamo partiti sapendo di doverli aggredire tra le linee, ma subito abbiamo concesso l&#8217;errore di concedere lo spazio di calciare a Trajkovski. Questo \u00e8 stato l\u2019unico nostro errore. Alla mia squadra posso rimproverare poco. La bravura di Brignoli e la nostra imprecisione non ci hanno permesso di far gol<\/em>.\u00a0<em>Sul 2-0 \u00e8 diventata molto pi\u00f9 difficile. Da l\u00ec in poi i rosanero hanno dettato il ritmo. Noi siamo stati coraggiosi e non abbiamo mai buttato la palla. Andiamo a casa con zero punti ma grandi certezze. Mancano ancora tante partite, se continueremo a giocare cos\u00ec potremo portare a casa tanti punti\u201d.<\/em><\/p>\n<p><em>Insomma&#8230;Credo che loro hanno sfruttato la prima occasione, poi la partita l&#8217;abbiamo fatta noi, abbiamo giocato sempre palla a terra, ma buttata in avanti alla cieca, bravura del portiere loro e un po&#8217; di imprecisione nostra se non li abbiamo ripresi subito&#8230; Poi un altro errore errore di valutazione e abbiamo preso il secondo gol&#8230;Comunque,\u00a0esco dalla partita di oggi con grandi certezze e con grande\u00a0 rispetto per la nostra squadra. Se il Palernmo \u00e8 costruito per vincere, noi possiamo giocarcela nelle restanti undici partite&#8221;.______<\/em><\/p>\n<p>LA RICERCA nel nostro articolo di ieri sera<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"65LTXVgV2l\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/03\/02\/il-lecce-la-partita-sconfitta-amara\/\">IL LECCE \/ LA PARTITA \/ SCONFITTA AMARA<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/03\/02\/il-lecce-la-partita-sconfitta-amara\/embed\/#?secret=65LTXVgV2l\" data-secret=\"65LTXVgV2l\" width=\"500\" height=\"282\" title=\"&#8220;IL LECCE \/ LA PARTITA \/ SCONFITTA AMARA&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<div id=\"rcsad_Bottom1\" class=\"\" data-google-query-id=\"CIa5pJzY5eACFcQX4AodyYYF4Q\"><em>\u00a0<\/em><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/03\/03\/il-lecce-il-postpartita-parlano-i-due-mister\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/03\/03\/il-lecce-il-postpartita-parlano-i-due-mister\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______ In evidenza, fra gli altri del postpartita, i commenti dei due allenatori, per la lucidit\u00e0 dell&#8217;analisi e l&#8217;onest\u00e0 intellettuale. Ecco una sintesi delle loro dichiarazioni, fatte a caldo nella serata di ieri. Roberto Stellone (nella foto):\u00a0&#8220;Abbiamo fatto un buon primo quarto d&#8217;ora, una bella gara, poi abbiamo sofferto, il Lecce &#8211; e faccio i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":151278,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/151277"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=151277"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/151277\/revisions"}],"predecessor-version":[{"id":151282,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/151277\/revisions\/151282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/151278"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=151277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=151277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=151277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}