{"id":15227,"date":"2013-04-28T09:04:09","date_gmt":"2013-04-28T09:04:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15227"},"modified":"2013-04-28T09:04:09","modified_gmt":"2013-04-28T09:04:09","slug":"ha-inizio-il-dance-art-fusion-festival","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/ha-inizio-il-dance-art-fusion-festival\/","title":{"rendered":"HA INIZIO IL DANCE ART FUSION FESTIVAL"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/ha-inizio-il-dance-art-fusion-festival\/600267_10201016853687937_1059632891_n\/\" rel=\"attachment wp-att-15228\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/600267_10201016853687937_1059632891_n.jpg\" alt=\"\" width=\"654\" height=\"406\" class=\"alignleft size-full wp-image-15228\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/600267_10201016853687937_1059632891_n.jpg 654w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/600267_10201016853687937_1059632891_n-300x186.jpg 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/><\/a>Inizia domenica 28 aprile il festival Daff organizzato da a.s.d. Alegria,a.s.d. New ever dance e Arci Officina mentis. il DAFF acronimo di Dance Art Fusion Festival, giunto alla seconda edizione spiegano gli organizzatori nasce con lo scopo di creare un punto di incontro tra le varie forme artistiche, tra la danza e l&#8217;arte, tra la musica e la moda, coinvolgendo attraverso le attivit\u00e0 previste, tutte le fasce generazionali. E&#8217; un movimento in crescita, come si pu\u00f2 notare dalla ricchezza e dalla variet\u00e0 del programma 2013, con l&#8217;auspicio di migliorare e potenziare il festival nelle edizioni avvenire, fermamente convinti che &#8220;L&#8217;arte \u00e8 un luogo dove si esprime la propria libert\u00e0!!!&#8221; cit. Andr\u00e9 Suar\u00e8s<\/p>\n<p>Domenica 28 aprile : LOCATION PIAZZA FALCONIERI ,<br \/>\nORE:15.00 \u201cGIORNATA DELL\u2019ARTE\u201d con Giochi per bambini, artisti di strada, animazione, esibizione dei ragazzi Parcour, sfilata cinofila , vari stand;<br \/>\nORE 16:30 : GIMKANA PER BAMBINI DAI 6 AI 10 ANNI ORGANIZZATA DAL\u2019ASS. MTB-MONTERONI;<br \/>\nORE 18:00 : SFILATA CINOFILA in collaborazione con l\u2019associazione animalista \u201cL\u2019impronta\u201d e SCOOBY \u2013 DOO di Piero Manca, Carmiano;<br \/>\nORE 19.30 :<br \/>\nconcorso di bellezza e moda MISSDAFF13 con STYLIST ROCCO GENCO,DANIELA MELCORE,PARTICOLARI DI VALENTINA SIMONETTI,OTTICA QUARTA, HAIR STYLIST ANTONELLA MAGLI e Spettacolo di TEATRO-DANZA dal titolo \u201c ITER : L\u2019ESSENZA DI UN VIAGGIO\u201d<br \/>\nin serata Premiazione dei vincitori scuole elementari e medie I\u00b0 e II\u00b0 polo al concorso\u201cLavoro e futuro disegna la tua strada\u201d<br \/>\ndiretta radio CDJ SHOW<br \/>\nLOCATION PALAZZO BARONALE : Allestimento mostra di pittura,moda, arte povera, fotografia, scultura, disegni scuole;<\/p>\n<p>Luned\u00ec 29 aprile : LOCATION PALAZZO BARONALE: ORE 20:00 :<br \/>\nTORNEO di Burraco, allestimento mostre e disegni scuole;<\/p>\n<p>Marted\u00ec 30 aprile : NELLA LOCATION SCUOLA \u201c A.S.D. NEW EVER DANCE\u201d :<br \/>\ndalle ore 14:00 : Workshop di Modern Jazz con Andr\u00e8 De La Roche (coreografo e ballerino internazionale di danza)<br \/>\nHIP HOP\/POPPIN\u2019\/LOCKIN\u2019 con KRIS<br \/>\nNELLA LOCATION DEL PALAZZO BARONALE:ore20.00 Festa degli adulti<\/p>\n<p>Gioved\u00ec 2 maggio : LOCATION SCUOLA A.S.D. NEW EVER DANCE:<br \/>\nlezioni aperte GRATUITE di danza classica, moderna,orientale,hip hop e fitness, tenute da maestri professionisti;<\/p>\n<p>Sabato 4 maggio : LOCATION SCUOLA A..S.D. NEW EVER DANCE<br \/>\nDALLE ORE 10:00 WORKSHOP di BREAK-DANCE con QUIC(ATLANTA-USA)<br \/>\nDALLE ORE 15:00 WORKSHOP DI NEW STYLE\/HOUSE \u2013RAGGAE\/DANCEHALL con DIEGO PENNETTA,<\/p>\n<p>Presso il CLUB EVENING in P.zza Falconieri :<br \/>\nOre 17.00 BREAK-DANCE CONTEST \u201cFIRE FLOOR BATTLE 2\u201d con in giuria ballerini professionisti internazionali di Break-Dance<\/p>\n<p>a seguire \u201cDANCEFIRE FLOOR\u201d SERATA CON MUSICA hip hop \u2013 raggae \u2013 dub step \u2013 electro \u2013 d\u2019nb\u2019.<\/p>\n<p>EVENTO APERTO A TUTTI, VI ASPETTIAMO<\/p>\n<p>PER INFO : GIUSI 328.0710422 \u2013 ANDREA : 388.1443943 \u2013 VALENTINA : 327.0514949<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/ha-inizio-il-dance-art-fusion-festival\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/ha-inizio-il-dance-art-fusion-festival\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Inizia domenica 28 aprile il festival Daff organizzato da a.s.d. Alegria,a.s.d. New ever dance e Arci Officina mentis. il DAFF acronimo di Dance Art Fusion Festival, giunto alla seconda edizione spiegano gli organizzatori nasce con lo scopo di creare un punto di incontro tra le varie forme artistiche, tra la danza e l&#8217;arte, tra la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15228,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15227"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15227"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15227\/revisions"}],"predecessor-version":[{"id":15231,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15227\/revisions\/15231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15228"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}