{"id":15232,"date":"2013-04-28T09:09:31","date_gmt":"2013-04-28T09:09:31","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15232"},"modified":"2013-04-28T09:10:58","modified_gmt":"2013-04-28T09:10:58","slug":"scoperto-evasore-per-circa-35-milioni-di-euro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/scoperto-evasore-per-circa-35-milioni-di-euro\/","title":{"rendered":"SCOPERTO EVASORE PER CIRCA 3,5 MILIONI DI EURO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/scoperto-evasore-per-circa-35-milioni-di-euro\/evasione-fiscale\/\" rel=\"attachment wp-att-15233\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/evasione-fiscale.gif\" alt=\"\" width=\"600\" height=\"405\" class=\"alignleft size-full wp-image-15233\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/evasione-fiscale.gif 600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/evasione-fiscale-300x202.gif 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a>I Finanzieri della Compagnia di Lecce hanno eseguito una verifica fiscale nei confronti di una societ\u00e0 della provincia operante nel settore delle costruzioni edili, la quale, omettendo di presentare la dichiarazione annuale dei redditi, IVA ed IRAP per le annualit\u00e0 2008 e 2010, ha sottratto a tassazione ricavi per oltre 3,5 milioni di euro ed evaso IVA per oltre 89mila euro.<\/p>\n<p>Le Fiamme Gialle, dopo aver esaminato con capillare attenzione tutta la documentazione contabile acquisita in sede di primo accesso ispettivo, con particolare riferimento a documentazione extra contabile rinvenuta presso il domicilio del rappresentante legale della societ\u00e0, sono riusciti a quantificare quanto nascosto al Fisco.<\/p>\n<p>Adesso sar\u00e0 l\u2019Agenzia delle Entrate, cui il verbale \u00e8 stato trasmesso, a completare l\u2019attivit\u00e0 intrapresa dalla Guardia di Finanza, attraverso l\u2019azione di accertamento e riscossione delle relative imposte evase.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/scoperto-evasore-per-circa-35-milioni-di-euro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/scoperto-evasore-per-circa-35-milioni-di-euro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I Finanzieri della Compagnia di Lecce hanno eseguito una verifica fiscale nei confronti di una societ\u00e0 della provincia operante nel settore delle costruzioni edili, la quale, omettendo di presentare la dichiarazione annuale dei redditi, IVA ed IRAP per le annualit\u00e0 2008 e 2010, ha sottratto a tassazione ricavi per oltre 3,5 milioni di euro ed [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15233,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15232"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15232"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15232\/revisions"}],"predecessor-version":[{"id":15238,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15232\/revisions\/15238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15233"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}