{"id":15246,"date":"2013-04-28T09:21:25","date_gmt":"2013-04-28T09:21:25","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15246"},"modified":"2013-04-28T09:21:25","modified_gmt":"2013-04-28T09:21:25","slug":"viola-gli-arresti-domiciliari-e-torna-in-carcere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/viola-gli-arresti-domiciliari-e-torna-in-carcere\/","title":{"rendered":"V\u00ecola gli arresti domiciliari e torna in carcere"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/viola-gli-arresti-domiciliari-e-torna-in-carcere\/resize-aspx\/\" rel=\"attachment wp-att-15247\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/resize.aspx_.jpeg\" alt=\"\" width=\"220\" height=\"170\" class=\"alignleft size-full wp-image-15247\" \/><\/a>Monteroni di Lecce. Ieri sera i Carabinieri della locale Stazione, in esecuzione del provvedimento di sostituzione degli arresti domiciliari con la custodia in carcere, emesso dalla Corte di Appello di Lecce, hanno arrestato\u00a0<strong>Rosanna Tornese<\/strong>,<strong>\u00a0<\/strong>trentanovenne del luogo, gi\u00e0 nota. Il provvedimento \u00e8 stato emesso in seguito alla violazione degli obblighi degli arresti domiciliari cui era sottoposta.<\/p>\n<p>La donna, che era stata sottoposta alla misura cautelare nel contesto dell\u2019operazione antidroga\u00a0<em>Valle della Cupa,<\/em>\u00a0 espletate formalit\u00e0 di rito, \u00e8 stata associata alla Casa Circondariale di Lecce.<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/viola-gli-arresti-domiciliari-e-torna-in-carcere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/28\/viola-gli-arresti-domiciliari-e-torna-in-carcere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Monteroni di Lecce. Ieri sera i Carabinieri della locale Stazione, in esecuzione del provvedimento di sostituzione degli arresti domiciliari con la custodia in carcere, emesso dalla Corte di Appello di Lecce, hanno arrestato\u00a0Rosanna Tornese,\u00a0trentanovenne del luogo, gi\u00e0 nota. Il provvedimento \u00e8 stato emesso in seguito alla violazione degli obblighi degli arresti domiciliari cui era sottoposta. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15247,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15246"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15246"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15246\/revisions"}],"predecessor-version":[{"id":15249,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15246\/revisions\/15249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15247"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}