{"id":152527,"date":"2019-04-05T16:22:57","date_gmt":"2019-04-05T14:22:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=152527"},"modified":"2019-04-05T16:47:30","modified_gmt":"2019-04-05T14:47:30","slug":"iniziato-oggi-e-subito-rinviato-il-processo-a-carico-di-venticinque-persone-che-il-13-novembre-2017-manifestarono-contro-la-zona-rossa-di-tap-a-melendugno-un-pezzo-di-svizzera-a-casa-nostra","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/04\/05\/iniziato-oggi-e-subito-rinviato-il-processo-a-carico-di-venticinque-persone-che-il-13-novembre-2017-manifestarono-contro-la-zona-rossa-di-tap-a-melendugno-un-pezzo-di-svizzera-a-casa-nostra\/","title":{"rendered":"INIZIATO OGGI E SUBITO RINVIATO IL PROCESSO A CARICO DI VENTICINQUE PERSONE CHE IL 13 NOVEMBRE 2017  MANIFESTARONO CONTRO LA &#8216;ZONA ROSSA&#8217; DI TAP A MELENDUGNO, &#8220;un pezzo di Svizzera a casa nostra&#8221;. MA SI PUO&#8217; PROCESSARE IL DISSENSO POLITICO? E COMUNQUE &#8220;l\u2019opposizione al gasdotto continua&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-152539 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-1.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-1.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-1-400x300.jpg 400w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-152528 size-full\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/04\/mani-400x300.jpg 400w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(Rdl)______In venticinque a giudizio con le accuse di manifestazione non autorizzata e, a vario titolo, di danneggiamento, violenza privata, oltraggio e resistenza a pubblico ufficiale, dopo la protesta dei No Tap del 13 novembre 2017 a Melendugno.<\/p>\n<p>Il processo era previsto per questa mattina davanti ai giudici della seconda sezione penale del Tribunale di Lecce, ma \u00e8 stato rinviato per vizi di notifiche a due imputati al prossimo 10 ottobre.<\/p>\n<p>Questa mattina, fuori dal Palazzo di Giustizia un gruppo di attivisti No Tap ha tenuto una manifestazione di protesta.<\/p>\n<p>&nbsp;<\/p>\n<p>In un comunicato diffuso ieri, il Comitato No Tap si era cos\u00ec espresso: <em>&#8220;Il numero di imputati e la particolare circostanza dei fatti ci permettono di definire questo processo come il primo atto formale della repressione contro l\u2019intero movimento.<\/em><br \/>\n<em>Sono passati quasi due anni da quel giorno ma la nostra memoria \u00e8 abbastanza viva da ricordare con lucidit\u00e0 contesti, motivazioni e stati d\u2019animo.<\/em><br \/>\n<em>Quel giorno, il 13 novembre del 2017, l\u2019allora Prefetto di Lecce, istituiva attorno al cantiere di San Basilio a San Foca l\u2019ormai celeberrima \u201cZona Rossa\u201d, un dispositivo di impostazione militare, attraverso il quale una vasta porzione di territorio veniva praticamente sottratta all\u2019uso pubblico per agevolare \u201csuperiori interessi\u201d privati. <\/em><\/p>\n<p><em>Un provvedimento inaspettato ma funzionale ad arginare un\u2019opposizione popolare tenace e partecipata che si esprimeva ogni giorno nei pressi del cantiere.<\/em><br \/>\n<em>L\u2019intensa militarizzazione sarebbe durata per un mese: giusto il tempo per costruire una vera e propria fortezza ad uso della multinazionale TAP.<\/em><\/p>\n<p><em>Quel 13 novembre anche il presidio No TAP era stato \u201cintrappolato\u201d nella Zona Rossa e qualcuno di noi ci sarebbe rimasto sequestrato all\u2019interno per ore, senza capirne i motivi. Insieme ad altre decine di persone, appresa la notizia, ci siamo recati a Melendugno manifestando, spontaneamente, per le vie del\u00a0paese.<\/em><br \/>\n<em>Se il prefetto tentava, con un colpo di mano, di eludere la protesta spianando la strada a TAP, noi eravamo l\u00ec per dimostrare che la resistenza contro la devastazione del territorio non si sarebbe messa a tacere con nessun mezzo, meno che mai con la militarizzazione.<\/em><br \/>\n<em>Ci sembrava naturale e giusto gridarlo di fronte agli uffici di TAP e dovunque risiedessero le<\/em><br \/>\n<em>responsabilit\u00e0 dello scempio sotto gli occhi di tutti. <\/em><\/p>\n<p><em>Durante i trenta giorni di Zona Rossa, la\u00a0<\/em><em>popolazione in pi\u00f9 occasioni ha protestato a gran voce, spingendosi a ridosso dei cancelli, scioperando, scendendo in strada in molte occasioni a Melendugno e a Lecce.\u00a0<\/em><em>Sebbene siano state giornate difficili da dimenticare, questo processo ci d\u00e0 l\u2019opportunit\u00e0 di ricordarle ancora. <\/em><\/p>\n<p><em>Oggi, che la zona di Melendugno \u00e8 squarciata da almeno tre cantieri, che l\u2019ecosistema \u00e8 stato irrimediabilmente stravolto, che molti di noi stanno pagando quella resistenza in termini di repressione giudiziaria e poliziesca, l\u2019opposizione al gasdotto continua.<\/em><\/p>\n<p><em>Oggi siamo nuovamente chiamati, come imputati, davanti ad un Tribunale dello Stato. Quello stesso Stato che si china agli interessi di una multinazionale, disponendo forze di polizia a protezione dei suoi cantieri, quello stesso Stato che, per bocca del capo del Governo, annuncia e promuove l\u2019offerta in\u00a0denaro di TAP per rabbonire la popolazione danneggiata.<\/em><br \/>\n<em>Volentieri cogliamo l\u2019occasione che questo Tribunale ci offre per ribadire la giustezza della nostra opposizione a TAP e la nostra incondizionata solidariet\u00e0 a chiunque si opponga a quest\u2019opera scellerata\u00a0e a tutte le grandi opere devastatrici&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Dal canto loro le Mamme No Tap hanno diffuso pocho minuti fa via social la seguente dichiarazione e la foto che abbiamo qui ripreso: &#8220;<em>Oggi prima udienza nel procedimento penale contro 25 tra uomini e donne che responsabilmente dissentono alla realizzazione del TAP.<\/em><br \/>\n<em>25 amici che hanno manifestato la propria contrariet\u00e0 ad un opera inutile e dannosa e ad un sistema marcio che sta stuprando il nostro territorio al solo scopo di ricavarne profitto.<\/em><br \/>\n<em>Noi mamme no tap eravamo l\u00ec, davanti al tribunale, per ribadire che difendere il proprio territorio da progetti scellerati non \u00e8 un crimine! Noi tutte ci sentiamo con loro a giudizio; con loro, anche oggi, dalla parte giusta della barricata&#8221;.______<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;APPROFONDIMENTO nell&#8217;ultimo dei nostri articoli di quel 13 novembre 2017, in cui il sindaco di Melendugno Marco Pot\u00ec parlava di sospensione delle libert\u00e0 fondamentali dei cittadini. Nei link sottostanti, tutti gli altri con i fatti ed i commenti di quanto accadde.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"FGtOp4L7FZ\"><p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/13\/che-facciamo-un-pezzo-di-svizzera-a-casa-nostra-il-sindaco-di-melendugno-marco-poti-spiega-a-leccecronaca-it-perche-sono-state-soppresse-le-liberta-dei-cittadini-per-favorire-gli-interess\/\">&#8220;Che facciamo? Un pezzo di Svizzera a casa nostra?&#8221;. MARCO POTI&#8217; SPIEGA A leccecronaca.it COME SIANO STATE SOPPRESSE LE LIBERTA&#8217; DEI CITTADINI<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2017\/11\/13\/che-facciamo-un-pezzo-di-svizzera-a-casa-nostra-il-sindaco-di-melendugno-marco-poti-spiega-a-leccecronaca-it-perche-sono-state-soppresse-le-liberta-dei-cittadini-per-favorire-gli-interess\/embed\/#?secret=FGtOp4L7FZ\" data-secret=\"FGtOp4L7FZ\" width=\"500\" height=\"282\" title=\"&#8220;&#8220;Che facciamo? Un pezzo di Svizzera a casa nostra?&#8221;. MARCO POTI&#8217; SPIEGA A leccecronaca.it COME SIANO STATE SOPPRESSE LE LIBERTA&#8217; DEI CITTADINI&#8221; &#8212; LecceCronaca.it\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/04\/05\/iniziato-oggi-e-subito-rinviato-il-processo-a-carico-di-venticinque-persone-che-il-13-novembre-2017-manifestarono-contro-la-zona-rossa-di-tap-a-melendugno-un-pezzo-di-svizzera-a-casa-nostra\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/04\/05\/iniziato-oggi-e-subito-rinviato-il-processo-a-carico-di-venticinque-persone-che-il-13-novembre-2017-manifestarono-contro-la-zona-rossa-di-tap-a-melendugno-un-pezzo-di-svizzera-a-casa-nostra\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______In venticinque a giudizio con le accuse di manifestazione non autorizzata e, a vario titolo, di danneggiamento, violenza privata, oltraggio e resistenza a pubblico ufficiale, dopo la protesta dei No Tap del 13 novembre 2017 a Melendugno. Il processo era previsto per questa mattina davanti ai giudici della seconda sezione penale del Tribunale di Lecce, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":152528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/152527"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=152527"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/152527\/revisions"}],"predecessor-version":[{"id":152541,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/152527\/revisions\/152541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/152528"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=152527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=152527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=152527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}