{"id":15392,"date":"2013-04-30T10:08:34","date_gmt":"2013-04-30T10:08:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15392"},"modified":"2013-04-30T10:27:04","modified_gmt":"2013-04-30T10:27:04","slug":"lamosa-chiusura-del-centro-alle-auto-coinvolgiamo-tutta-la-citta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/30\/lamosa-chiusura-del-centro-alle-auto-coinvolgiamo-tutta-la-citta\/","title":{"rendered":"LAMOSA: CHIUSURA DEL CENTRO ALLE AUTO? COINVOLGIAMO TUTTA LA CITTA\u2019"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/30\/lamosa-chiusura-del-centro-alle-auto-coinvolgiamo-tutta-la-citta\/unknown-1\/\" rel=\"attachment wp-att-15393\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/04\/Unknown-1.jpeg\" alt=\"\" width=\"153\" height=\"174\" class=\"alignleft size-full wp-image-15393\" \/><\/a>Il capogruppo di Lecce Citt\u00e0 del Mondo, Antonio Lamosa, auspica un percorso partecipato sull\u2019ipotesi di chiusura del traffico veicolare nelle zone centrali di Lecce.<br \/>\n\u201cQuanto apparso sul Nuovo Quotidiano di Puglia del 29 aprile sull\u2019ipotesi di chiudere tutto il centro alle auto chiarisce principalmente la situazione di disagio che vivono alcuni residenti del centro storico.<\/p>\n<p>La nostra citt\u00e0 ha visto un significativo incremento del turismo negli ultimi anni, a volte anche di un turismo selvaggio, non per definizione, ma per via di una domanda sempre pi\u00f9 caotica nel tentativo di rispondere all\u2019enorme appeal di questa terra.<\/p>\n<p>Due assessori del Comune di Lecce hanno voluto dichiarare la loro disponibilit\u00e0 e impegno ad un\u2019eventuale chiusura totale del traffico della microzona centro storico. Una presa di posizione, tuttavia, che ha creato un po\u2019 di allarme tra gli operatori commerciali. Ad ogni buon conto, per uscire da questa impasse e tranquillizzare gli addetti ai lavori \u00e8 possibile \u201criposizionare\u201d \u00a0l\u2019attenzione sull\u2019importanza della cosiddetta politica partecipata, un processo che questa Amministrazione, con a capo il sindaco Perrone, sta portando avanti oramai da diversi anni con ottimi risultati: gli esempi del costruendo Pug o della riqualificazione urbana del quartiere Leuca, ne rappresentano una limpida testimonianza nella quale la partecipazione \u00e8 diventata la parola chiave.<\/p>\n<p>Ecco perch\u00e9, quale capogruppo di Lecce Citt\u00e0 del Mondo, ho gi\u00e0 proposto ad uno degli assessori interpellati dai media su questo delicato tema di indire una conferenza pubblica, \u00a0al fine di coinvolgere la cittadinanza nella condivisione di un percorso unitario. I risultati del sondaggio apparsi sul Nuovo Quotidiano di Puglia sono confortanti, ma probabilmente non rappresentano ancora il sentire comune , le opinioni diffuse e generali di tuti i cittadini leccesi che invece si potrebbero desumere proprio attraverso l\u2019auspicato percorso di politica partecipata.<\/p>\n<p>La citt\u00e0 di Lecce \u00e8 cambiata e si \u00e8 dovuta adeguare frettolosamente a quella che oggi rappresenta la leva dell\u2019economia leccese, vale a dire il turismo. Tuttavia, c\u2019\u00e8 ancora tanto da fare. E\u2019 sulla questione-traffico che si gioca principalmente questa \u201cpartita\u201d; per questo sarebbe necessario incoraggiare i leccesi, o chi proviene da fuori citt\u00e0, a \u00a0condividere un percorso che prevede la realizzazione di un parcheggio alle porte di Lecce. E\u2019 chiaro che i parcheggi che stanno per essere ultimati (vedi quello dell\u2019ex Enel) porteranno benefici e soluzioni pi\u00f9 consone e pi\u00f9 facili da individuare. Il mio auspicio, dunque, \u00e8 che nel percorso tracciato si possa trovare la collaborazione da parte di tutti.\u00a0 Ritengo che nessuno prover\u00e0 a non ascoltare la voce dei cittadini e degli amministratori comunali, sempre impegnati nella ricerca dei problemi che stanno a cuore alla nostra bellissima citt\u00e0.\u00a0 Insomma, iniziamo a pensare positivo per il bene di Lecce e dei leccesi\u201d.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/30\/lamosa-chiusura-del-centro-alle-auto-coinvolgiamo-tutta-la-citta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/04\/30\/lamosa-chiusura-del-centro-alle-auto-coinvolgiamo-tutta-la-citta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Il capogruppo di Lecce Citt\u00e0 del Mondo, Antonio Lamosa, auspica un percorso partecipato sull\u2019ipotesi di chiusura del traffico veicolare nelle zone centrali di Lecce. \u201cQuanto apparso sul Nuovo Quotidiano di Puglia del 29 aprile sull\u2019ipotesi di chiudere tutto il centro alle auto chiarisce principalmente la situazione di disagio che vivono alcuni residenti del centro storico. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15392"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15392"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15392\/revisions"}],"predecessor-version":[{"id":15398,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15392\/revisions\/15398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15393"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}