{"id":1546,"date":"2012-06-04T07:45:44","date_gmt":"2012-06-04T07:45:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=1546"},"modified":"2012-06-04T07:45:46","modified_gmt":"2012-06-04T07:45:46","slug":"la-siria-sotto-attacco-degli-americani","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/04\/la-siria-sotto-attacco-degli-americani\/","title":{"rendered":"La Siria sotto attacco degli Americani"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/04\/la-siria-sotto-attacco-degli-americani\/siria\/\" rel=\"attachment wp-att-1547\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/siria.jpg\" alt=\"\" title=\"siria\" width=\"550\" height=\"327\" class=\"alignnone size-full wp-image-1547\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/siria.jpg 550w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/06\/siria-300x178.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p>La Siria sotto attacco degli Americani<\/p>\n<div>\n<p><strong>di Brandon Turbeville<\/strong><\/p>\n<\/div>\n<p><strong>____________<\/strong><\/p>\n<p><strong>da \u201cActivist Post<br \/>\n<\/strong><strong>____________<\/strong><\/p>\n<p>Col procedere\u00a0di evidenti atti di destabilizzazione, stanno diventando sempre pi\u00f9 ovvie le connessioni fra le forze terroriste dell\u2019\u00abopposizione\u00bb ed i governi anglo-americani pro-NATO, anche se la stampa ufficiale allineata si rifiuta di trattare l\u2019argomento se non per gettarvi sopra del fumo.<\/p>\n<p>Fortunatamente, una grossa parte della stampa alternativa \u2013 insieme ad alcune voci siriane quali quella della blogger\u00a0Syrian Girl\u00a0su Youtube \u2013 ha giocato un ruolo importante nello smascherare i \u00abribelli\u00bb per quello che veramente sono: terroristi stranieri ed elementi criminali siriani appoggiato dai governi anglo-americani e pro-NATO e dai servizi segreti.<\/p>\n<p>Molti di tali elementi si sa come facciano parte di al-Qaeda in modo molto simile a quei \u00abribelli libici\u00bb che \u2013 dopo aver preso il potere con l\u2019aiuto della NATO \u2013 hanno immediatamente iniziato a restringere le libert\u00e0 ed a massacrare i libici di pelle nera. Non c\u2019\u00e8 dubbio che una parte considerevole di questi terroristi abbia oggettivamente viaggiato dalla Libia alla Siria, con diverse operazioni attraverso le frontiere di Turchia, Giordania e Libano.<\/p>\n<p>Lo scrittore e storico Webster Griffin Tarpley ha sostenuto che al-Qaeda sia \u00a0una\u00a0<em>legione<\/em>\u00a0araba degli Stati Uniti.<\/p>\n<p>Inoltre, data la crescente impudenza con la quale l\u2019impero anglo-americano effettua le proprie operazioni, stanno diventando sempre pi\u00f9 visibili anche le parti realmente coinvolte.<\/p>\n<p>Una figura che sta ricevendo un\u2019attenzione insolitamente smisurata da parte della stampa ufficiale \u00e8 l\u2019ambasciatore USA in Siria Robert Stephen Ford.<\/p>\n<p>Naturalmente, tutta l\u2019azione di\u00a0<em>informazione <\/em>della stampa ufficiale allineata \u00e8 concorde ed a lui favorevole e volta a far sembrare Ford un eroe che in\u00a0<em>bona fide<\/em>\u00a0stia lottando per un popolo oppresso.<\/p>\n<p>Ma la realt\u00e0 \u00e8 ben diversa: non \u00e8 altro che un esperto globalizzatore nella destabilizzazione, che sta mettendo in pratica gli insegnamenti di John Negroponte, il suo mentore diventato quasi un raffinato istigatore di massacri di massa nell\u2019America Centrale ed in Iraq. \u00c8 in Iraq, sotto l\u2019organizzazione di Negroponte che Ford ha potuto affinare le proprie capacit\u00e0 nell\u2019armare e dare appoggio a spietati squadroni della morte che prendevano di mira innocenti con azioni di terrore e massacro di massa.<\/p>\n<p>A questo punto, comunque, sorgono delle domande sulle possibili connessioni fra agenti destabilizzatori e sul potenziale ruolo del Generale Robert Mood \u2013 il generale norvegese recentemente salito alla carica di capo dell\u2019UNSMIS (United Nations Supervision Mission in Syria) \u2013 e dell\u2019onnipresente \u2013 anche se sullo sfondo \u2013 generale David Petraeus.<\/p>\n<p>Per quelli che non hanno famigliarit\u00e0 con le connessioni fra eminenti \u00abfunzionari\u00bb del calibro di Ford e Negroponte e di come abbiamo un ruolo rilevante in Siria, sono necessarie alcune premesse.<\/p>\n<p>Va sottolineato che il Prof. Michel Chossudovsky ci \u00a0ha gi\u00e0 fornito un\u2019eccellente presentazione storica delle connessioni di Negroponte, Ford e Petraeus in relazione con gli squadroni della morte e la destabilizzazione, in Salvador prima, in Iraq poi e in Siria adesso.<\/p>\n<p>John Negroponte \u00e8 stato ambasciatore americano in Honduras dal 1981 al 1985. In tale ruolo, \u00e8 stato funzionale all\u2019appoggiare e supervisionare gli assassini dei Contra del Nicaragua che, bench\u00e9 di base in Honduras, furono protagonisti di efferati atti di terrorismo all\u2019interno del Nicaragua. Un\u2019operazione che, nel suo complesso, cost\u00f2 la vita a 50.000 civili innocenti. Questa \u00e8 l\u2019origine del termine \u00abOpzione Salvador\u00bb usato quando si parla della costituzione \u2013 a scopi politici \u2013 di \u00absquadroni della morte\u00bb. Un\u2019opzione che \u00e8 diventata un contrassegno di Negroponte e del sistema che egli rappresenta.<br \/>\nNegroponte \u00e8 anche stato responsabile della formazione degli squadroni della morte dell\u2019Honduras che furono usati in una missioni di terrore contro gli oppositori del regime honduregno \u2013 appoggiato dagli USA \u2013 cos\u00ec come dei Sandinisti e della popolazione civile del Nicaragua.<\/p>\n<p>\u00abIl quotidiano Sun ha descritto le attivit\u00e0 di una unit\u00e0 armata dell\u2019Honduras \u2013\u00a0<em>Battalion 316<\/em>\u00a0\u2013 addestrata segretamente dalla CIA, unit\u00e0 che usava negli interrogatori strumenti per scariche elettriche e soffocamento. I prigionieri venivano spesso tenuti nudi e, quando non servivano pi\u00f9, uccisi e sepolti in loculi senza nome.<\/p>\n<p>Il 27 agosto del 1997, il General Frederick P. Hitz, ispettore della CIA, diffuse una relazione riservata interna di 211 pagine, dal titolo: \u00abArgomenti Selezionati relativi alle attivit\u00e0 della CIA in Honduras alla fine degli anni \u201980\u00bb. Relazione parzialmente declassificata il 22 ottobre 1998, in risposta alle richieste del rappresentante dei diritti civili dell\u2019Honduras.<\/p>\n<p>Nel 2005, Negroponte fu nominato ambasciatore in Iraq. In tale veste, supervision\u00f2 ancora una volta la costituzione di squadroni della morte aventi per obbiettivo i rivoltosi iracheni e la popolazione civile. In questo caso lo scopo consisteva nel fomentare divisioni all\u2019interno dei rivoltosi per frammentarne il fronte. Un\u2019opposizione divisa \u00e8 ovviamente molto pi\u00f9 facile da sconfiggere che non una unita. Una teoria che di volta in volta viene riconfermata come esatta.<\/p>\n<p>Negroponte (ultimo a destra) ai tempi dell\u2019Iraq<\/p>\n<div align=\"center\">\n<hr align=\"center\" size=\"2\" width=\"100%\" \/>\n<\/div>\n<p>\u00c8 vero che nel 2005 filtr\u00f2 a Newsweek una vicenda nella quale si confermava che il Pentagono stesse \u00abconsiderando la formazione di squadroni della morte composte da combattenti curdi e sciiti per colpire i capi dei rivoltosi iracheni con un cambio strategico mutuato dallo sforzo americano nell\u2019America Centrale, 20 anni prima, contro la guerriglia di sinistra\u00bb.<\/p>\n<p>Ma il Pentagono fece ben di pi\u00f9 del semplice\u00a0<em>prendere in considerazione<\/em>\u00a0una simile opzione. Non molto tempo dopo la\u00a0<em>fuga<\/em>\u00a0di questa notizia, l\u2019Iraq incominci\u00f2 a vederne concretizzarsi gli effetti.<\/p>\n<p>Nell\u2019ambito della\u00a0<em>Opzione Salvador<\/em>, Negroponte ebbe l\u2019aiuto di un suo collega degli anni Ottanta ai tempi dell\u2019America Centrale: il Colonnello in pensione James Steele. Steele \u2013 la cui qualifica a Bagdad era quella di Consigliere per le Forze di Sicurezza Irachene \u2013 supervision\u00f2 la selezione e l\u2019addestramento dei componenti dell\u2019Organizzazione Badr e dell\u2019esercito Mehdi, le due pi\u00f9 grosse milizie sciite dell\u2019Iraq; ci\u00f2 al fine di colpire sia la leadership del Paese che i principali collegamenti dell\u2019importante resistenza sunnita.<\/p>\n<p>Che la cosa sia stata voluta o no, gli squadroni della morte sfuggirono subito di mano e divennero la prima causa di morte in Iraq. Voluti o meno, i numerosissimi episodi di corpi torturati e mutilati scaricati ogni giorno per le strade di Bagdad furono prodotti da quegli squadroni della morte la cui spinta iniziale venne da Negroponte. Ed \u00e8 questa violenza appoggiata e fomentata dagli USA che ha dato il suo contributo principale nel portare a quell\u2019inferno che \u00e8 oggi l\u2019Iraq.<\/p>\n<p>Ovviamente, il fatto che l\u2019opzione degli squadroni della morte sia stata concretizzata cos\u00ec rapidamente dopo la diffusione della relazione, suggerisce che i mercenari fossero ben organizzati e collocati gi\u00e0 da tempo prima che <em>Newsweek<\/em>\u00a0ne rivelasse l\u2019esistenza.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/04\/la-siria-sotto-attacco-degli-americani\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/06\/04\/la-siria-sotto-attacco-degli-americani\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>La Siria sotto attacco degli Americani di Brandon Turbeville ____________ da \u201cActivist Post ____________ Col procedere\u00a0di evidenti atti di destabilizzazione, stanno diventando sempre pi\u00f9 ovvie le connessioni fra le forze terroriste dell\u2019\u00abopposizione\u00bb ed i governi anglo-americani pro-NATO, anche se la stampa ufficiale allineata si rifiuta di trattare l\u2019argomento se non per gettarvi sopra del fumo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1547,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/1546"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=1546"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/1546\/revisions"}],"predecessor-version":[{"id":1549,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/1546\/revisions\/1549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/1547"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=1546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=1546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=1546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}