{"id":156156,"date":"2019-07-08T13:30:47","date_gmt":"2019-07-08T11:30:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=156156"},"modified":"2019-07-08T13:30:47","modified_gmt":"2019-07-08T11:30:47","slug":"la-polemica-e-qui-la-festa-si-purtroppo-enzo-suma-contro-wwf-e-jovanotti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/08\/la-polemica-e-qui-la-festa-si-purtroppo-enzo-suma-contro-wwf-e-jovanotti\/","title":{"rendered":"LA POLEMICA \/ E&#8217; QUI LA FESTA? SI&#8217;, PURTROPPO&#8230;ENZO SUMA CONTRO WWF E JOVANOTTI"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-156157\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/es.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/es.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/es-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/es-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/es-60x60.jpg 60w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>(Rdl)______Ostuni (BR),\u00a0 luglio 2019. 13.20. <em>&#8220;45.000 persone! Questi i partecipanti alla prima tappa del tour in spiaggia di Jovanotti. In un ecosistema cos\u00ec fragile come quello di una spiaggia e degli ambienti dunali, dove sono presenti piante sensibilissime al calpestio e dove trovano rifugio uccelli di varie specie. Tra questi il fratino, a rischio estinzione. In questo periodo ci sono ancora nidi e i piccoli pulcini indifesi, che non sono ancora in grado di volare, verranno calpestati brutalmente. Questa stessa brutalit\u00e0 vorrei applicarla ai tre responsabili con una denuncia penale a: Jovanotti, i sindaci dei comuni delle varie tappe e i dirigenti del WWF. Rompere un solo uovo di fratino \u00e8 per la legge un reato penale. Ma la legge \u00e8 davvero uguale per tutti?&#8221;<\/em>.<\/p>\n<p>Cos\u00ec questa mattina sul suo diario Facebook, a commento del concerto di ieri a Lignano Sabbiadoro, si \u00e8 espresso Enzo Suma (nella foto), 38 anni, di Ostuni, guida escursionistica e naturalista, che ha poi proseguito rincarando la dose: <em>&#8220;Per la Puglia il 20 luglio il tour far\u00e0 tappa a Barletta, anche qui, ancora una volta, in un area dove nidificano i fratini. Questa gente, in nome dei soldi e del grande business che c&#8217;\u00e8 dietro, ha preso il rispetto per l&#8217;ambiente (che sventola nei loro slogan pubblicitari) e lo ha letteralmente calpestato sotto i piedi di 45MILA persone. Se fosse un reato dovrebbero essere accusati anche di ipocrisia. Nei loro comunicati sbandierano il &#8216;rispetto dell&#8217;ambiente&#8217; che nella loro concezione vuol dire invogliare la gente a raccogliere la spazzatura e dire quattro parole al microfono sul problema della plastica nel mare. <\/em><\/p>\n<p><em>Nel frattempo abbiamo calpestato le uova e i pulcini di una specie a rischio estinzione, abbiamo calpestato le piante delle dune embrionali e abbiamo letteralmente cacciato via tutti quegli uccelli che, solo in queste poche aree naturali, trovano un posto dove sostare, rifugiarsi e riprodursi. <\/em><\/p>\n<p><em>Voi che mi leggete potete fare una cosa. Non andate al concerto! E se siete iscritti al wwf protestate perch\u00e9 vi hanno preso in giro! Mentre voi donate i vostri soldi per la tutela dell&#8217;ambiente loro lo mettono in enorme pericolo con questi mega concerti sulla spiaggia&#8221;.\u00a0<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/08\/la-polemica-e-qui-la-festa-si-purtroppo-enzo-suma-contro-wwf-e-jovanotti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/08\/la-polemica-e-qui-la-festa-si-purtroppo-enzo-suma-contro-wwf-e-jovanotti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Ostuni (BR),\u00a0 luglio 2019. 13.20. &#8220;45.000 persone! Questi i partecipanti alla prima tappa del tour in spiaggia di Jovanotti. In un ecosistema cos\u00ec fragile come quello di una spiaggia e degli ambienti dunali, dove sono presenti piante sensibilissime al calpestio e dove trovano rifugio uccelli di varie specie. Tra questi il fratino, a rischio estinzione. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":156157,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156156"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=156156"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156156\/revisions"}],"predecessor-version":[{"id":156158,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156156\/revisions\/156158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/156157"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=156156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=156156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=156156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}