{"id":156286,"date":"2019-07-13T00:02:03","date_gmt":"2019-07-12T22:02:03","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=156286"},"modified":"2019-07-11T17:12:37","modified_gmt":"2019-07-11T15:12:37","slug":"il-piacere-delle-poesie-di-cristhine-demyfabre","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/13\/il-piacere-delle-poesie-di-cristhine-demyfabre\/","title":{"rendered":"&#8216;IL PIACERE&#8217; DELLE POESIE DI CRISTHINE DEMYFABRE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-156288\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/CD.jpg\" alt=\"\" width=\"687\" height=\"960\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/CD.jpg 687w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/CD-215x300.jpg 215w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/>di <strong>Raffaele Polo<\/strong>______<\/p>\n<p>Ha senso, al giorno d&#8217;oggi, presentare una raccolta di componimenti poetici imperniati sull&#8217;amore,sulla solitudine e il rimpianto e quasi parafrasando Saffo, instillare quel sottile brivido che danno le parole lussuria,danza oscena, gemito di piacere?<\/p>\n<p>\u00c8 un percorso obbligato, ancorch\u00e9 piacevole, cui ci costringe <strong>Cristhine Demyfabre<\/strong>\u00a0(nella foto) che nasce a Cir\u00f2 Marina e vive nel mondo, come recita la scarna biografia che completa questo<em><strong> &#8216;Sui marciapiedi dell&#8217;anima&#8217;<\/strong><\/em>, edito da &#8216;I Sogni di Carta&#8217; (euro 10).<\/p>\n<p>Nella prefazione Paolo Rausa collega i versi della brava poetessa con la canzone di Battiato &#8216;Es un sentimento nuevo&#8230;&#8217;, fino ad esplorare le intime sensibilit\u00e0 di un affresco di versi che si fanno apprezzare soprattutto per la pacatezza dell&#8217;espressione e per la costante ricerca di un semplice mezzo poetico che sia incisivo e convincente, senza travalicare il senso di quella malinconia petrarchesca che sovente pare artefatta e atteggiata.<\/p>\n<p>Non in queste composizioni, per\u00f2: con toni a volte severi e taglienti, Cristhine ci abitua alle sue armonie, ai suoi misurati sospiri.<\/p>\n<p>E come la mettiamo con l&#8217;idea di Eros, che potrebbe apparire come una sorta di predisposizione alla ricerca di una effimera soddisfazione dei sensi, magari negata da contingenze terrene?<\/p>\n<p>Scavando e approfondendo il credo poetico della brava autrice, capiamo che l&#8217;amore \u00e8 qui partecipe di un mondo interiore che vuole ispirarsi, inconsciamente, a quell&#8217; &#8216;Ama, e fa ci\u00f2 che vuoi&#8217; che Agostino ha incardinato quasi senza apparire nelle nostre esistenze, svolgendo un percorso di grande spessore proprio in chi si dedica alla poesia e all&#8217;introspezione.<\/p>\n<p>Certo, una passionale e vigorosa spinta erotica \u00e8 ben presente nell&#8217;immaginario che ci comunicano, ad esempio, questi versi:<em> &#8216;Sei la mia stagione\/ migliore.\/ Le parole grani di rosario\/ in un dio vivente.\/Tra le rose spinate,\/ ti mancher\u00f2,\/ il tuo pensiero audace\/ cade sui miei seni\/ aspettano le gocce\/ del piacere.\/ Avida e insaziabile\/ la bocca trema.&#8217; <\/em><\/p>\n<p>Ora, anche se ci parrebbe pi\u00f9 logico che il termine giusto fosse &#8216;aspettando&#8217; anzich\u00e9 &#8216;aspettano&#8217;, \u00e8 proprio questo particolare che ci lascia perplessi e ci fa rileggere e assimilare al meglio l&#8217;intera composizione. Finiamo per chiederci se sia veramente una sintesi legata all&#8217;amplesso amoroso e ai suoi risvolti, oppure se ci sia dell&#8217;altro, celato a prima vista&#8230;.<\/p>\n<p>Come nella immagine di copertina, la cornice circonda uno specchio che non c&#8217;\u00e8, ma che passa attraverso chi lo regge, trascurandone il volto, verso altri obiettivi.<\/p>\n<p>Le poesie di Cristhine sono cos\u00ec, da leggere e meditare con curiosit\u00e0 e piacere.<\/p>\n<p>Piacere: una parola da comprendere al meglio, in tutte le sue sfaccettature&#8230;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-156289\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi.jpeg\" alt=\"\" width=\"1738\" height=\"2483\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi.jpeg 1738w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi-210x300.jpeg 210w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi-717x1024.jpeg 717w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi-768x1097.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi-1075x1536.jpeg 1075w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/07\/marciapiedi-1434x2048.jpeg 1434w\" sizes=\"(max-width: 1738px) 100vw, 1738px\" \/><\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/13\/il-piacere-delle-poesie-di-cristhine-demyfabre\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/07\/13\/il-piacere-delle-poesie-di-cristhine-demyfabre\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo______ Ha senso, al giorno d&#8217;oggi, presentare una raccolta di componimenti poetici imperniati sull&#8217;amore,sulla solitudine e il rimpianto e quasi parafrasando Saffo, instillare quel sottile brivido che danno le parole lussuria,danza oscena, gemito di piacere? \u00c8 un percorso obbligato, ancorch\u00e9 piacevole, cui ci costringe Cristhine Demyfabre\u00a0(nella foto) che nasce a Cir\u00f2 Marina e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":156288,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,57],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156286"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=156286"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156286\/revisions"}],"predecessor-version":[{"id":156290,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/156286\/revisions\/156290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/156288"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=156286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=156286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=156286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}