{"id":157376,"date":"2019-08-10T14:27:20","date_gmt":"2019-08-10T12:27:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=157376"},"modified":"2019-08-10T16:54:44","modified_gmt":"2019-08-10T14:54:44","slug":"un-arresto-per-omicidio-stradale-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/08\/10\/un-arresto-per-omicidio-stradale-2\/","title":{"rendered":"UN ARRESTO PER OMICIDIO STRADALE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-157377\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/08\/ospedale-SS-ANN-1.jpg\" alt=\"\" width=\"669\" height=\"333\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/08\/ospedale-SS-ANN-1.jpg 669w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/08\/ospedale-SS-ANN-1-300x149.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/08\/ospedale-SS-ANN-1-600x300.jpg 600w\" sizes=\"(max-width: 669px) 100vw, 669px\" \/>(e.l.)_______Viaggiava con tre amici\u00a0 da Talsano verso il centro di Taranto\u00a0a bordo di una Seat Ibiza che all&#8217;improvviso si \u00e8 scontrata con una\u00a0Ford Fusion e poi si \u00e8 schiantata contro un muro. L&#8217;impatto per lui \u00e8 stato fatale. E&#8217; morto cos\u00ec questa notte Lino Albano, 59 anni. Ci son stati altri tre feriti, curati al Pronto Soccorso dell&#8217;ospedale Santissima Annunziata (nella foto), fra cui il conducente della Ibiza, di 50 anni, che, dopo i controlli cui \u00e8 stato sottoposto, \u00e8 stato arrestato con l&#8217;accusa di omicidio stradale: aveva il tasso di alcol nel sangue superiore al consentito. Si trova ora ancora ricoverato in ospedale, ma in stato di arresto.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/08\/10\/un-arresto-per-omicidio-stradale-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/08\/10\/un-arresto-per-omicidio-stradale-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)_______Viaggiava con tre amici\u00a0 da Talsano verso il centro di Taranto\u00a0a bordo di una Seat Ibiza che all&#8217;improvviso si \u00e8 scontrata con una\u00a0Ford Fusion e poi si \u00e8 schiantata contro un muro. L&#8217;impatto per lui \u00e8 stato fatale. E&#8217; morto cos\u00ec questa notte Lino Albano, 59 anni. Ci son stati altri tre feriti, curati al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":157377,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/157376"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=157376"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/157376\/revisions"}],"predecessor-version":[{"id":157379,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/157376\/revisions\/157379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/157377"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=157376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=157376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=157376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}