{"id":159282,"date":"2019-10-05T09:27:47","date_gmt":"2019-10-05T07:27:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=159282"},"modified":"2019-10-05T09:27:47","modified_gmt":"2019-10-05T07:27:47","slug":"accoglienza-non-e-servire-un-piatto-di-cicorie","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/10\/05\/accoglienza-non-e-servire-un-piatto-di-cicorie\/","title":{"rendered":"&#8220;Accoglienza non \u00e8 servire un piatto di cicorie&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-159283\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/10\/COBU.jpg\" alt=\"\" width=\"720\" height=\"404\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/10\/COBU.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/10\/COBU-300x168.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>Riceviamo e volentieri pubblichiamo.\u00a0Il portavoce della Lega provinciale Massimo Martella scrive all\u2019imprenditore Donato Fersino e ce ne manda copia per conoscenza______<\/p>\n<p>Caro Donato,<\/p>\n<p>scrivi che le nostre comuni \u201cradici ci hanno permesso di sviluppare nei secoli il senso del confronto, del dialogo e dell\u2019ospitalit\u00e0\u201d . Hai perfettamente ragione.<\/p>\n<p>Rilevo per\u00f2 che queste per te siano solo parole che non metti in pratica visto che critichi fortemente una scelta che appartiene alla libera espressione di ogni cittadino e che \u00e8 garantita dalla nostra Costituzione. Una Carta costituzionale che \u00e8 l\u2019elaborato di quelle straordinarie personalit\u00e0 che parteciparono all\u2019assemblea costituente, tra questi non dobbiamo dimenticare il pugliese Aldo Moro e mi piace ricordare il suo intervento del 13 marzo 1947 quando, \u00a0si discuteva degli articoli 1,6 e 7 che diverranno poi 1, 2 e 3, \u00a0disse:\u00a0\u00a0\u201c Divisi &#8211; come siamo &#8211; da diverse intuizioni politiche, da diversi orientamenti ideologici, tuttavia noi siamo membri di una comunit\u00e0, la comunit\u00e0 del nostro Stato e vi restiamo uniti sulla base di un elementare, semplice idea dell\u2019uomo la quale ci accomuna e determina un rispetto reciproco degli uni verso gli altri\u201d.<\/p>\n<p>Dunque caro Donato mi chiedo e ti chiedo: siamo davvero comunit\u00e0 aperta al dialogo e all\u2019ospitalit\u00e0 se\u00a0oggi\u00a0reagisci trincerandoti nel concetto di democrazia storica e non allarghi i tuoi orizzonti al mutamento sociale che anche la nostra comunit\u00e0 sta vivendo? Perch\u00e9 alzi barriere ideologiche,\u00a0 muri di pregiudizi verso un partito, la Lega con Salvini, che rappresenta uomini e donne del tuo stesso Paese? Perch\u00e9 il tuo sguardo pone un confine netto tra Sud e Nord? Perch\u00e9, considerate le nostre comuni radici e la nostra storia, non ritieni sia \u00a0possibile che da questo Sud, dal tuo e nostro Sud, possa generarsi una voce comune \u00a0che rivendica e ottiene quell\u2019attenzione sbandierata per decenni da quanti hanno considerato il Mezzogiorno solo bacino elettorale da saccheggiare, da quanti hanno governato il nostro Paese per decenni, da quanti sono stati eletti quali rappresentati del Sud al Parlamento e che il Sud hanno svenduto?<\/p>\n<p>La Lega con Salvini pu\u00f2 proporre una nuova idea del Mezzogiorno, finalmente indipendente dove le ragioni dell\u2019accoglienza e del dialogo sono quelle del riscatto di una societ\u00e0 che finora si \u00e8 accontentata di contratti precari e di lavoro nero. Questo ha penalizzato il Sud non il Nord saccheggiatore. Non siamo stati capaci, e il tuo ne \u00e8 un esempio, di capire cos\u2019\u00e8 una democrazia. Gli insegnamenti della Grecia, lo dimostri, gli hai persi per strada limitando la volont\u00e0 personale di un sindaco di aderire ad un movimento politico come sancito dall\u2019articolo 49 della nostra Costituzione. Nel tuo invito, seppur nobili sono i tuoi richiami, ci sono solo belle parole, slogan per un territorio che non ne ha pi\u00f9 bisogno. L\u2019identit\u00e0 nasce anche dalla diversit\u00e0, e qui riprendo il concetto di comunit\u00e0, perch\u00e9 se il Salento fosse una Comunit\u00e0 vera, il tessuto imprenditoriale di cui tu fai parte farebbe squadra con il tessuto istituzionale e sociale per la valorizzazione del territorio. Si sarebbe potuta recuperare la Cripta di Coelimanna se ci fossero state le sinergie necessarie tra pubblico e privato illuminato, propenso al bene comune e non solo e soltanto al profitto personale.<\/p>\n<p>L\u2019idea di accoglienza non \u00e8 servire un piatto di cicorie pur raccontando la bellezza del posto. Accoglienza significa preoccuparsi di sapere cosa l\u2019intera comunit\u00e0 in sui si opera sia in grado di offrire collaborando con tutti a costruire reti turistiche in grado di attrarre nuovi investimenti e di creare posti di lavoro reali e non \u201ca giornata\u201d. Non c\u2019\u00e8 ospitalit\u00e0, e dunque quello che definisci \u201cvalore aggiunto\u201d, se chi opera nel settore ricettivo non si confronta con chi ha idee e valori differenti.\u00a0\u00a0Ecco perch\u00e9 ti invito per essere coerente con quanto hai scritto nella lettera al sindaco di Supersano,\u00a0 ad affiggere sotto l\u2019insegna de \u201cLe Stanzie\u201d il cartello: qui non si accettano elettori della Lega con Salvini.<\/p>\n<p>Un caro saluto.<br \/>\nMassimo Martella<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/10\/05\/accoglienza-non-e-servire-un-piatto-di-cicorie\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/10\/05\/accoglienza-non-e-servire-un-piatto-di-cicorie\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo.\u00a0Il portavoce della Lega provinciale Massimo Martella scrive all\u2019imprenditore Donato Fersino e ce ne manda copia per conoscenza______ Caro Donato, scrivi che le nostre comuni \u201cradici ci hanno permesso di sviluppare nei secoli il senso del confronto, del dialogo e dell\u2019ospitalit\u00e0\u201d . Hai perfettamente ragione. Rilevo per\u00f2 che queste per te siano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":159283,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/159282"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=159282"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/159282\/revisions"}],"predecessor-version":[{"id":159284,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/159282\/revisions\/159284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/159283"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=159282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=159282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=159282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}