{"id":15993,"date":"2013-05-11T18:00:41","date_gmt":"2013-05-11T18:00:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=15993"},"modified":"2013-05-11T18:01:29","modified_gmt":"2013-05-11T18:01:29","slug":"albinoleffe-lecce-si-decide-tutto-alla-fine","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/11\/albinoleffe-lecce-si-decide-tutto-alla-fine\/","title":{"rendered":"ALBINOLEFFE \u2013 LECCE : SI DECIDE TUTTO ALLA FINE."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/11\/albinoleffe-lecce-si-decide-tutto-alla-fine\/lecce-stadio-4\/\" rel=\"attachment wp-att-15994\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/lecce-stadio.png\" alt=\"\" width=\"455\" height=\"341\" class=\"alignleft size-full wp-image-15994\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/lecce-stadio.png 455w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/lecce-stadio-300x224.png 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/a>Le burrasche sono violente ma hanno una fine. E quando il cielo da grigio e plumbeo ritorna calmo gli equipaggi sono costretti o a fare la conta dei danni, dei morti e dei feriti o , grazie alla bravura del capitano e dei nocchieri, a continuare la navigazione verso il porto d\u2019arrivo.<\/p>\n<p>\u00c8 questa la romantica metafora dell\u2019annata che sta vivendo il Lecce, l\u2019annata caratterizzata dalla burrasca chiamata Lega Pro che, volente o nolente, sta per finire nella sua fase pi\u00f9 acuta. Il Lecce non \u00e8 padrone del suo destino, il pareggio in rimonta rimediato in casa con il Carpi costringe i giallorossi a fare bottino pieno a Bergamo in casa dell\u2019Albinoleffe sperando che la Cremonese faccia risultato positivo in casa con il Trapani.<\/p>\n<p>I grigiorossi lombardi, a differenza dell\u2019Albinoleffe, hanno ancora qualcosa da chiedere al campionato, infatti, una vittoria contro il Trapani combinata ad una sconfitta della Sudtirol (a sua volta impegnata allo stadio \u201cDruso\u201d contro una Tritium che rischia l\u2019ultima piazza) significherebbe l\u2019approdo ai playoff. L\u2019ingresso ai playoff cercherebbe di dare un significato ad una stagione nettamente sotto le aspettative disputata dalla squadra di Cremona.<\/p>\n<p>Si suol dire che la speranza sia l\u2019ultima a morire, ma nel caso di questa famigerata conclusione di campionato \u00e8 difficile negare che la partita con il Carpi, dove una vittoria ci avrebbe proiettato ad un +2 dal Trapani, abbia lasciato scorie. Innanzitutto sar\u00e0 da registrare l\u2019assenza per squalifica di Chevanton per somma di ammonizioni, in partite da dentro o fuori come quella di domani Javier avrebbe potuto dare una marcia in pi\u00f9 al Lecce.<\/p>\n<p>L\u2019ostacolo da affrontare sar\u00e0 l\u2019Albinoleffe, protagonista di un campionato atipico condizionato sin da subito da una pesante penalizzazione (inflitta a causa dell\u2019implicazione dei bergamaschi nel calcioscommesse) di 11 punti. Penalizzazione (poi ridotta a 6 punti) che ha inciso non solo sul piano matematico sul rendimento dell\u2019Albinoleffe: senza il gap inflitto dal calcioscommesse gli orobici si troverebbero in piena zona playoff.<\/p>\n<p>Il campionato dei bergamaschi \u00e8 naturalmente partito nelle acque cattive della classifica e, complice un inizio altres\u00ec non entusiasmante, gli stessi sono stati candidati dai pi\u00f9 come candidati seri alla lotta playout.<\/p>\n<p>Lo sconto di pena ed un inversione di rotta di risultati (partita dalla met\u00e0 di dicembre) hanno permesso all\u2019Albinoleffe di abbandonare la zona playout assestandosi prima a centro classifica e poi, a primavera grazie ad uno scatto di 6 vittorie su 8 partite tra marzo ed aprile, a ridosso della zona playoff. Il sogno della squadra bergamasca guidata da mister Pala si \u00e8 infranto domenica scorsa al \u201cSinigaglia\u201d di Como a causa della sconfitta per 2-1 contro i biancazzurri. Resta comunque la buona stagione disputata dai bergamaschi, dati spacciati da molti gi\u00e0 in estate.<\/p>\n<p>Pala dovrebbe opporsi agli schemi offensivi di Toma con un 4-3-1-2 che vede gli uomini pi\u00f9 impiegati in difesa nel quartetto formato dai terzini Regonesi e Salvi e dai centrali Mauro Belotti e Allievi. In porta il bravo estremo difensore scuola Milan Offredi.<\/p>\n<p>A centrocampo la forza dei bergamaschi: nello scacchiere infatti risalta la sostanza di Girasole e la quantit\u00e0 (anche in zona realizzativa) del francese Taugourdeau. A completamento del reparto il ventenne Marvin Maietti. Pronto a tappare eventuali falle il veterano Previtali. Sulla trequarti spazio all\u2019ex primavera del Milan Valoti in ballottaggio con Simone Pontiggia. In avanti la coppia d\u2019attacco titolare dovrebbe essere formata da Andrea Belotti e Pesenti con l\u2019ex Atalanta Ciss\u00e8 pronto ad entrare per cercare di incidere a partita in corso.<\/p>\n<p>Mister Toma dovr\u00e0 fare a meno dei calciatori \u201ccroce e delizia\u201d Chevanton e Chiric\u00f2 ma riavr\u00e0 a disposizione Bomber Foti ed Inaci\u00f2 Pi\u00e0. La prolungata assenza di Lillo ha pesato in questi lunghi mesi di rendimento altalenante e di difficolt\u00e0 a trovare il gol.<\/p>\n<p>Ci\u00f2 che non dovrebbe mancare di certo all\u2019\u201dAtleti Azzurri d\u2019Italia\u201d non sar\u00e0 di certo il sostegno dei tifosi, previsti in 1000 unit\u00e0 da ogni parte d\u2019Italia per spingere il Lecce ad una vittoria che, accompagnata ad un mezzo passo falso del Trapani potrebbe significare Serie B senza playoff.<\/p>\n<p>Sar\u00e0 vitale la coesione tra le varie componenti domani a Bergamo per sopravvivere a questi ultimi frangenti di burrasca ed impostare la rotta verso il porto del purgatorio chiamato serie B.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>I convocati di Mister Toma per la partita:<\/p>\n<p>PORTIERI:\u2028Benassi, Bleve<\/p>\n<p>DIFENSORI\u2028Diniz, D&#8217;Ambrosio, Esposito, Fatic, Ferrario, Martinez, Vanin, Vinicius<\/p>\n<p>CENTROCAMPISTI\u2028Bogliacino, De Rose, Giacomazzi, Memushaj, Zappacosta<\/p>\n<p>ATTACCANTI\u2028Bustamante, Falco, Foti, Jeda, Pi\u00e0<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nella foto: \u201cNovanta minuti di battaglia per amore di questa maglia\u201d, lo striscione esposto dalla Curva Nord in occasione di Lecce-Palermo del 07-06-2003.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/11\/albinoleffe-lecce-si-decide-tutto-alla-fine\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/11\/albinoleffe-lecce-si-decide-tutto-alla-fine\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Le burrasche sono violente ma hanno una fine. E quando il cielo da grigio e plumbeo ritorna calmo gli equipaggi sono costretti o a fare la conta dei danni, dei morti e dei feriti o , grazie alla bravura del capitano e dei nocchieri, a continuare la navigazione verso il porto d\u2019arrivo. \u00c8 questa la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15993"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=15993"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15993\/revisions"}],"predecessor-version":[{"id":16000,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/15993\/revisions\/16000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/15994"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=15993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=15993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=15993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}