{"id":16036,"date":"2013-05-13T08:17:20","date_gmt":"2013-05-13T08:17:20","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16036"},"modified":"2013-05-13T08:17:20","modified_gmt":"2013-05-13T08:17:20","slug":"tenta-di-rubare-lauto-denunciato-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/tenta-di-rubare-lauto-denunciato-2\/","title":{"rendered":"TENTA DI RUBARE L\u2019AUTO: DENUNCIATO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/tenta-di-rubare-lauto-denunciato-2\/ladro-di-auto\/\" rel=\"attachment wp-att-16037\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/ladro-di-auto.jpg\" alt=\"\" width=\"374\" height=\"280\" class=\"alignleft size-full wp-image-16037\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/ladro-di-auto.jpg 374w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/ladro-di-auto-300x224.jpg 300w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><\/a>Alle ore 02,00 di questa mattina, i militari dell\u2019Aliquota Radiomobile di Campi Salentina hanno proceduto al deferimento in stato di libert\u00e0 per il reato di tentato furto, un rumeno trentenne, pregiudicato senza fissa dimora. Cinque minuti prima il proprietario di una Panda parcheggiata nei pressi di casa sua, a Leverano, aveva visto armeggiare nella propria auto due individui, e aveva quindi chiamato il 112. I militari hanno rintracciato non molto distante dall\u2019autovettura, lasciata aperta ma non forzata, da cui non era stato rubato nulla, il suddetto rumeno, ubriaco, poi riconosciuto dalla vittima del tentato furto. I militari di Leverano chiederanno in giornata il foglio di via obbligatorio al Questore di Lecce.<\/p>\n<p><em>\u00a0<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/tenta-di-rubare-lauto-denunciato-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/tenta-di-rubare-lauto-denunciato-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alle ore 02,00 di questa mattina, i militari dell\u2019Aliquota Radiomobile di Campi Salentina hanno proceduto al deferimento in stato di libert\u00e0 per il reato di tentato furto, un rumeno trentenne, pregiudicato senza fissa dimora. Cinque minuti prima il proprietario di una Panda parcheggiata nei pressi di casa sua, a Leverano, aveva visto armeggiare nella propria [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16037,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16036"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16036"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16036\/revisions"}],"predecessor-version":[{"id":16039,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16036\/revisions\/16039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16037"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}