{"id":16079,"date":"2013-05-13T14:29:09","date_gmt":"2013-05-13T14:29:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=16079"},"modified":"2013-05-13T14:30:23","modified_gmt":"2013-05-13T14:30:23","slug":"matino-scoperta-pescheria-abusiva","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/matino-scoperta-pescheria-abusiva\/","title":{"rendered":"MATINO: SCOPERTA PESCHERIA ABUSIVA."},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/matino-scoperta-pescheria-abusiva\/pesce-sequestrato\/\" rel=\"attachment wp-att-16080\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/pesce-sequestrato.jpg\" alt=\"\" width=\"470\" height=\"352\" class=\"alignleft size-full wp-image-16080\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/pesce-sequestrato.jpg 470w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/05\/pesce-sequestrato-300x224.jpg 300w\" sizes=\"(max-width: 470px) 100vw, 470px\" \/><\/a>SEQUESTRATI 80 KG. DI PESCE E MITILI VENDUTI SENZA LE PRESCRITTE AUTORIZZAZIONI AMMINISTRATIVE.<br \/>\nLa Guardia di Finanza di Gallipoli ha proceduto al sequestro di circa kg. 80 di pesce e mitili, esposti per la vendita in una pescheria abusiva del mercato coperto di Matino (LE).<br \/>\nUna pattuglia impegnata in un servizio di controllo sulla regolare emissione di scontrini e ricevute fiscali, al fine di riscontrare la veridicit\u00e0 di una segnalazione telefonica, pervenuta al numero di pubblica utilit\u00e0 \u201c117\u201d, da parte di un cliente della pescheria che lamentava l\u2019omesso rilascio dello scontrino fiscale, a seguito di un acquisto di pesce da poco effettuato.<br \/>\nLa pattuglia, giunta sul posto, accertava l\u2019assenza, non solo del registratore di cassa e di ogni altro misuratore fiscale, ma addirittura dei titoli autorizzativi, primo tra tutti la licenza commerciale, necessari per svolgere l\u2019attivit\u00e0 economica, esercitata con una partita IVA cessata dal 2004.<br \/>\nI finanzieri hanno proceduto al sequestro dei prodotti ittici rinvenuti e alla segnalazione del responsabile, un 49enne di Gallipoli alla Regione Puglia ed al Comune di Matino (LE), competenti per l\u2019irrogazione delle sanzioni amministrative da un minimo di 2.582 euro ad un massimo di 15.493 euro.<br \/>\nIl pesce in sequestro, ritenuto commestibile ed in buono stato di conservazione dai funzionari dell\u2019A.S.L., \u00e8 stato devoluto in beneficienza alla CARITAS di Gallipoli (LE), mentre i mitili, privi del prescritto bollino di tracciabilit\u00e0, saranno distrutti.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/matino-scoperta-pescheria-abusiva\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/05\/13\/matino-scoperta-pescheria-abusiva\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>SEQUESTRATI 80 KG. DI PESCE E MITILI VENDUTI SENZA LE PRESCRITTE AUTORIZZAZIONI AMMINISTRATIVE. La Guardia di Finanza di Gallipoli ha proceduto al sequestro di circa kg. 80 di pesce e mitili, esposti per la vendita in una pescheria abusiva del mercato coperto di Matino (LE). Una pattuglia impegnata in un servizio di controllo sulla regolare [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16080,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16079"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=16079"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16079\/revisions"}],"predecessor-version":[{"id":16085,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/16079\/revisions\/16085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/16080"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=16079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=16079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=16079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}