{"id":161220,"date":"2019-12-17T00:02:40","date_gmt":"2019-12-16T23:02:40","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=161220"},"modified":"2019-12-17T14:44:21","modified_gmt":"2019-12-17T13:44:21","slug":"concerto-natalizio-dellunisalento-a-lecce-mercoledi-18","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2019\/12\/17\/concerto-natalizio-dellunisalento-a-lecce-mercoledi-18\/","title":{"rendered":"IL CORO DELL&#8217;UNISALENTO A LECCE MERCOLEDI&#8217; 18"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-161221\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2019\/12\/images.jpg\" alt=\"\" width=\"400\" height=\"224\" \/>(Rdl)______Mercoled\u00ec 18 dicembre, alle 19.00, nell\u2019ambito della festa di comunit\u00e0 organizzata dall\u2019Universit\u00e0 del Salento per celebrare le festivit\u00e0 natalizie si terr\u00e0 nel Duomo di Lecce il concerto del coro polifonico UniSalento in collaborazione con l&#8217;Istituzione Polifonica \u201cA. Vivaldi\u201d.<\/p>\n<p>L\u2019evento, patrocinato dal Comune di Lecce e organizzato con la collaborazione dell\u2019Arcidiocesi di Lecce, proporr\u00e0 un&#8217;antologia di celebri melodie natalizie e mariane, nell&#8217;elaborazione polifonica e strumentale del Maestro Luigi De Luca che ha voluto tracciare un percorso a tema sulla Nativit\u00e0, dall&#8217;attesa del Messia al dono di Maria e all&#8217;Avvento del Cristo.<\/p>\n<p>Il programma include musicisti meno noti, ma di profonda spiritualit\u00e0 e raffinatezza armonico-melodica, quali Nicola Vitone e Giuseppe Mul\u00e8, entrambi attivi nel Novecento.<\/p>\n<p>L&#8217;organico vocale, insieme agli interventi solistici, sar\u00e0 arricchito dal gruppo di Voci Bianche \u201cJuniores Musici\u201d, addestrato da Francesca Zacheo, Maestra collaboratrice per la vocalit\u00e0.<\/p>\n<p>&#8220;Invito la cittadinanza a partecipare numerosa a questo momento di aggregazione e spiritualit\u00e0. Il concerto del coro polifonico UniSalento vuole essere un omaggio alla citt\u00e0 di Lecce e a tutti coloro che in questi giorni ne vivono la bellezza e ne respirano il clima natalizio. Un modo per sentirci comunit\u00e0 nella comunit\u00e0 e ricercare quella coesione che \u00e8 presupposto ineludibile per promuovere lo sviluppo sostenibile del nostro territorio; una musica per accordare i nostri spiriti&#8221;.______<\/p>\n<p>Note al programma di sala.<\/p>\n<p>L&#8217;Ave Maria, che C. Gounod volle costruire sulla trama del I\u00b0 Preludio del \u201cClavicembalo ben temperato\u201d di J.S. Bach, verr\u00e0 proposta nell&#8217;elaborazione per soli, coro a 4 voci ed ensemble, curata dal M\u00b0 De Luca. \u00c8 una sorta di musica al cubo nella quale lo stesso Maestro si \u00e8 cimentato elaborando anche la non meno famosa Ave Maria di F. Schubert, che verr\u00e0 eseguita nella versione: solo, coro a 4 voci e ensemble.<\/p>\n<p>*******<\/p>\n<p>L&#8217;Oratorio de No\u00ebl di Camille Saint-Sa\u00ebns attinge al racconto evangelico e alla salmodia biblica, costruiti in un continuum perfettamente amalgamato. Momenti evocativi si alternano con tratti volutamente arcaizzanti, espressi con intimo lirismo. Ne risulta una temperie stilistica che molto deve al raffinatissimo gusto timbrico dell&#8217;organista Saint-Sa\u00ebns, in linea con la nobilt\u00e0 classicheggiante del migliore Ottocento francese.<\/p>\n<p>L&#8217;interpretazione del M\u00b0 De Luca sar\u00e0 soprattutto una ridistribuzione dei ruoli vocali, attraverso una pi\u00f9 larga organizzazione del Quintetto solistico, tesa ad evidenziare la ricchezza del gioco polifonico e timbrico suggerito dalla struttura dell&#8217;opera.<\/p>\n<p>Il Largo di G. Mul\u00e8, caratterizzato da un&#8217;intensa emotivit\u00e0 melodica, ha suggerito al M\u00b0 De Luca una rivisitazione per soli, coro ed ensemble sul tema del Natale: \u201cNotte serena di pace, Notte sublime d&#8217;amor!\u201d.<\/p>\n<p>*******<\/p>\n<p>Il momento pi\u00f9 tangibilmente legato alla tradizione melica-natalizia vedr\u00e0 protagonista il francese Fran\u00e7ois Couperin (In notte placida) e l&#8217;italiano Antonio De Fidio (Dormi, non piangere). In campo le Voci Bianche, che festosamente parteciperanno anche al celeberrimo Quanno nascette Ninno.<\/p>\n<p>*******<\/p>\n<p>Concluder\u00e0 il concerto una variazione polifonico-strumentale sul tema dell&#8217;Alleluja gregoriano, proposta dal M\u00b0 Luigi De Luca.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2019\/12\/17\/concerto-natalizio-dellunisalento-a-lecce-mercoledi-18\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2019\/12\/17\/concerto-natalizio-dellunisalento-a-lecce-mercoledi-18\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Mercoled\u00ec 18 dicembre, alle 19.00, nell\u2019ambito della festa di comunit\u00e0 organizzata dall\u2019Universit\u00e0 del Salento per celebrare le festivit\u00e0 natalizie si terr\u00e0 nel Duomo di Lecce il concerto del coro polifonico UniSalento in collaborazione con l&#8217;Istituzione Polifonica \u201cA. Vivaldi\u201d. L\u2019evento, patrocinato dal Comune di Lecce e organizzato con la collaborazione dell\u2019Arcidiocesi di Lecce, proporr\u00e0 un&#8217;antologia di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":161221,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/161220"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=161220"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/161220\/revisions"}],"predecessor-version":[{"id":161224,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/161220\/revisions\/161224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/161221"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=161220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=161220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=161220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}