{"id":162247,"date":"2020-01-21T00:27:53","date_gmt":"2020-01-20T23:27:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=162247"},"modified":"2020-01-21T08:38:09","modified_gmt":"2020-01-21T07:38:09","slug":"il-punto-il-ritorno","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/21\/il-punto-il-ritorno\/","title":{"rendered":"IL PUNTO \/ IL RITORNO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-162264\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/01\/foto-spo.jpg\" alt=\"\" width=\"960\" height=\"658\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/01\/foto-spo.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/01\/foto-spo-300x206.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2020\/01\/foto-spo-768x526.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(.)______Varcata la boa di met\u00e0, il campionato comincia il suo girone di ritorno, con la ventesima giornata, aperta di sabato pomeriggio a Roma, da una sempre pi\u00f9\u00a0 sorprendente Lazio, giunta alla undicesima vittoria consecutiva, 5\u00a0 a 1 alla malcapitata Sampdoria, tripletta di Immobile, dal canto suo arrivato a 23 gol, una cifra pazzesca.<\/p>\n<p>Ora la Lazio fa paura anche alle due capolista.<\/p>\n<p>Sabato sera, il Sassuolo batte il Torino 2 a 1, ospiti in vantaggio su autorete, nella ripresa la rimonta firmata da Boga e Berardi.<\/p>\n<p>Sabato notte, pure la Fiorentina, del resto rinforzata e rimotivata, passa al San Paolo, uno 0 &#8211; 2 senza discussioni, in gol il redivivo Chiesa, e Vlahovic. Ringhia contro la luna Rino Gattuso, quarta sconfitta su cinque partite da quando \u00e8 subentrato ad Ancelotti sulla panchina del Napoli: &#8220;<em>Imbarazzanti. E&#8217; una squadra malata. Chiediamo scusa e andiamo in ritir<\/em>o&#8221;. Ritiro poi sospeso il giorno dopo.<\/p>\n<p>&nbsp;<\/p>\n<p>Il pranzo della domenica \u00e8 apparecchiato a San Siro per Milan e Udinese. Finisce 3 a 2, all&#8217;ultimo secondo, in una partita scoppiettante,Rebic regala ai suoi un&#8217; altra vittoria per la risalita in classifica.<\/p>\n<p>&nbsp;<\/p>\n<p>Domenica pomeriggio per Bologna-Verona, Brescia-Cagliari, e Lecce-Inter, con l&#8217;atteso ritorno, da allenatore nerazzurro, nella &#8216;sua&#8217; citt\u00e0 di Antonio Conte, di cui abbiamo riferito a parte a caldo.<\/p>\n<p>Tutte in pareggio.<\/p>\n<p>1 a 1 a Bologna, gol di Bani verso l&#8217;inizio per i padroni di casa, pareggio di Borini per gli ospiti verso la fine.<\/p>\n<p>2 a 2 a Brescia, con le doppiette di Torregrossa e di Joao Pedro, ennesima balotellata di Balotelli, che entra in\u00a0 campo al 74&#8242; e ne esce dopo sette minuti, lasciando i suoi in dieci nella fase decisiva: fa fallo entrando a gamba tesa su di un avversario, l&#8217;arbitro lo ammonisce, lui lo manda a quel paese due volte di seguito, e cos\u00ec il cartellino giallo diventa subito rosso.<\/p>\n<p>Domenica sera Genoa-Roma, i Romanisti passano alla grande, 1 a 3.<\/p>\n<p>Domenica notte Juventus-Parma, con la capolista che prova ad allungare, dopo il 2 a 1 in cui, non solo per la doppietta, Cristiano Ronaldo ha fatto la differenza.<\/p>\n<p>&nbsp;<\/p>\n<p>A chiudere il turno, il monday night per Atalanta e Spal. Con sorpresa. A Bergamo passano 1 a 2 i Ferraresi, che\u00a0 lasciano cos\u00ec il fanalino di coda nelle mani del Genoa, pur non abbandonando la linea rossa.<\/p>\n<p>In coda ora la situazione \u00e8 la seguente, dal basso in alto: Genoa 14 punti, Spal e Brescia 15, Lecce 16, Sampdoria 19, Sassuolo 22.<\/p>\n<p>In testa, da sola la Juventus, in fuga, con 51 punti, seguita dall&#8217;Inter con 47 e dalla lazio con 45: i romani hanno per\u00f2 una partita in meno, che recupereranno il prossimo mese.<\/p>\n<p>&nbsp;<\/p>\n<p>La seconda giornata del girone di ritorno, la numero 21 del campionato, si aprir\u00e0 venerd\u00ec 24, proseguir\u00e0 sabato, e si concluder\u00e0 tutta quanta di domenica, con e sera e nella notte le partite pi\u00f9 attese, il derby romano, e la capolista che va in casa del derelitto Napoli.<\/p>\n<p>Il Lecce gioca domenica 26 a Verona.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/21\/il-punto-il-ritorno\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2020\/01\/21\/il-punto-il-ritorno\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(.)______Varcata la boa di met\u00e0, il campionato comincia il suo girone di ritorno, con la ventesima giornata, aperta di sabato pomeriggio a Roma, da una sempre pi\u00f9\u00a0 sorprendente Lazio, giunta alla undicesima vittoria consecutiva, 5\u00a0 a 1 alla malcapitata Sampdoria, tripletta di Immobile, dal canto suo arrivato a 23 gol, una cifra pazzesca. Ora la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":162264,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/162247"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=162247"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/162247\/revisions"}],"predecessor-version":[{"id":162310,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/162247\/revisions\/162310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/162264"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=162247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=162247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=162247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}